{"id":8388,"date":"2017-11-17T12:20:00","date_gmt":"2017-11-17T11:20:00","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?p=8388"},"modified":"2017-11-17T12:20:00","modified_gmt":"2017-11-17T11:20:00","slug":"arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/","title":{"rendered":"Arezzo &#8211; Truffe: arrestata banda di &#8220;falsi Carabinieri&#8221; nell&#8217;aretino"},"content":{"rendered":"<p>Dalle prime ore di questa mattina, i Carabinieri della Compagnia di Arezzo, con il supporto dei colleghi del Comando Provinciale di Napoli, hanno dato esecuzione ad un\u2019 ordinanza di applicazione di misura cautelare nei confronti di dodici persone, emessa dal giudice per le indagini preliminari di Arezzo &#8211; Dott. Ponticelli &#8211; , su conforme richiesta della locale Procura \u2013 Sost. Proc. Dott.ssa Iannelli &#8211; , tutte ritenute responsabili di \u201cAssociazione per delinquere finalizzata alla commissione di truffe a danno di anziani\u201d. Il provvedimento restrittivo costituisce l\u2019epilogo di un\u2019articolata e complessa attivit\u00e0 investigativa, avviata nel novembre 2016, a seguito di una serie di truffe consumate nel territorio della provincia di Arezzo, e che ha permesso di individuare e ricostruire un\u2019organizzazione malavitosa di soggetti originari e residenti in Provincia di Napoli che commettevano raggiri a persone anziane su tutto il territorio nazionale. I truffatori agivano sempre con il medesimo \u201cmodus operandi\u201d.<br \/>\nLe vittime venivano individuate consultando i siti internet specializzati (www.elenchitelefonici.it www.paginebianche.it www.trovanumeri.com etc.).<br \/>\nI \u201ctelefonisti\u201d si presentavano a persone anziane vittime come \u201cCarabinieri\u201d, \u201cAvvocati\u201d o \u201cAgenti di societ\u00e0 assicurative\u201d, rappresentando generalmente un grave sinistro stradale dove era rimasto coinvolto un prossimo congiunto della vittima (solitamente un figlio o un nipote) e che per conferma della cosa potevano chiamare il \u201c112\u201d. Facevano s\u00ec che ci\u00f2 avvenisse senza che la parte offesa riattaccasse il telefono.<br \/>\nUna volta sentito digitare i tre tasti, un altro soggetto telefonava qualificandosi come Carabiniere confermando alla vittima quanto gi\u00e0 anticipato dall\u2019altro complice.<br \/>\nIn questa fase, i truffatori cercavano di carpire alla vittima pi\u00f9 dati personali possibili e soprattutto se la stessa si trovava in casa da sola. Il passaggio successivo era quindi da parte del telefonista di chiedere alla vittima il pagamento di una \u201ccauzione\u201d di alcune migliaia di euro affinch\u00e9 il congiunto potesse riacquistare la libert\u00e0 evitando di andare incontro a sanzioni penali o amministrative, facendosi dire per telefono sia il contante posseduto che gli oggetti in oro (alcune volte, facendoglieli addirittura pesare per capirne il valore). In alcune circostanze la vittima veniva \u201crimbalzata\u201d tra pi\u00f9 telefonisti al chiaro scopo di aumentarne l\u2019angoscia e la confusione e indurla cos\u00ec al pagamento. Quando la truffa andava a segno, il sedicente carabiniere concludeva il colloquio indicando alla vittima un avvocato o incaricato dell\u2019assicurazione che si sarebbe recato presso la sua abitazione per ritirare quanto preteso, che spesso, oltre ai soldi, si trattava di monili in oro, e ogni oggetto di valore, poi rivenduti presso compro oro compiacenti. Le somme richieste arrivavano anche a superare i settemila euro. Gli anziani contattati, tenuti al telefono anche per pi\u00f9 di un ora, venivano letteralmente sconvolti dalla notizia che un loro parente poteva essere coinvolto in un sinistro stradale, ed inoltre avere guai con la giustizia. Dopo la consumazione della truffa, le vittime rimanevano scioccate dal fatto di essere stati raggirati e di avere perduto, molte volte, i ricordi di una vita, come fedi, ricordi dei coniugi o di parenti defunti. Gli indagati, tutti residenti nel napoletano, avevano ognuno un proprio ruolo nel sodalizio: vi era l\u2019organizzatore, il quale dirigeva il gruppo individuando le vittime e distribuendo i compiti ad ognuno; gli incaricati del supporto logistico che si occupavano del reperimento delle \u201csim card\u201d , spesso intestate a ignari soggetti stranieri, e del noleggio di autovetture usate per gli spostamenti; i telefonisti, che contattavano le vittime da Napoli; gli emissari, che, pronti nelle vicinanze delle abitazioni degli anziani, al segnale ricevuto dai telefonisti, si presentavano per riscuotere quanto preteso. Per eludere eventuali indagini, i truffatori adottavano alcune cautele come cambiare frequentemente la zona di azione, sostituendo con regolarit\u00e0 i cellulari e le \u201cschede sim\u201d utilizzate, cos\u00ec come rivolgersi a diversificate societ\u00e0 di noleggio auto per i mezzi utilizzati. Le indagini hanno riguardato 70 truffe, tra tentate e consumate, compiute, tra il novembre 2016 e il marzo 2017, in Toscana, Liguria, Umbria, Lazio, Abruzzo e Puglia, quantificando in circa 200.000 euro il valore complessivo sottratto alle vittime. Inoltre, sono emersi legami, anche parentali, tra due destinatari delle misure cautelari e un soggetto ritenuto affiliato a un sodalizio criminale camorristico riconducibile all\u2019 \u201dAlleanza di Secondigliano\u201d. Gli arrestati dovranno rispondere dei reati di associazione per delinquere finalizzata ai delitti di truffa aggravata in danno di persone anziane o comunque in condizioni di minorata difesa. Al termine delle operazioni di cattura e fotosegnalamento, i destinatari delle misure cautelari, sono stati condotti presso la casa circondariale di Napoli Poggioreale e presso i rispettivi domicili.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalle prime ore di questa mattina, i Carabinieri della Compagnia di Arezzo, con il supporto dei colleghi del Comando Provinciale di Napoli, hanno dato esecuzione ad un\u2019 ordinanza di applicazione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-8388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arezzo - Truffe: arrestata banda di &quot;falsi Carabinieri&quot; nell&#039;aretino - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arezzo - Truffe: arrestata banda di &quot;falsi Carabinieri&quot; nell&#039;aretino - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"Dalle prime ore di questa mattina, i Carabinieri della Compagnia di Arezzo, con il supporto dei colleghi del Comando Provinciale di Napoli, hanno dato esecuzione ad un\u2019 ordinanza di applicazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-17T11:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Arezzo &#8211; Truffe: arrestata banda di &#8220;falsi Carabinieri&#8221; nell&#8217;aretino\",\"datePublished\":\"2017-11-17T11:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/\"},\"wordCount\":749,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/\",\"name\":\"Arezzo - Truffe: arrestata banda di \\\"falsi Carabinieri\\\" nell'aretino - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"datePublished\":\"2017-11-17T11:20:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/17\\\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arezzo &#8211; Truffe: arrestata banda di &#8220;falsi Carabinieri&#8221; nell&#8217;aretino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arezzo - Truffe: arrestata banda di \"falsi Carabinieri\" nell'aretino - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/","og_locale":"it_IT","og_type":"article","og_title":"Arezzo - Truffe: arrestata banda di \"falsi Carabinieri\" nell'aretino - Portale dei Carabinieri","og_description":"Dalle prime ore di questa mattina, i Carabinieri della Compagnia di Arezzo, con il supporto dei colleghi del Comando Provinciale di Napoli, hanno dato esecuzione ad un\u2019 ordinanza di applicazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-17T11:20:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Arezzo &#8211; Truffe: arrestata banda di &#8220;falsi Carabinieri&#8221; nell&#8217;aretino","datePublished":"2017-11-17T11:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/"},"wordCount":749,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/","name":"Arezzo - Truffe: arrestata banda di \"falsi Carabinieri\" nell'aretino - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","datePublished":"2017-11-17T11:20:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/17\/arezzo-truffe-arrestata-banda-di-falsi-carabinieri-nellaretino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Arezzo &#8211; Truffe: arrestata banda di &#8220;falsi Carabinieri&#8221; nell&#8217;aretino"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=8388"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8388\/revisions"}],"predecessor-version":[{"id":8389,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8388\/revisions\/8389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=8388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=8388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=8388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}