{"id":8396,"date":"2017-11-18T10:30:00","date_gmt":"2017-11-18T09:30:00","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?p=8396"},"modified":"2017-11-18T10:30:00","modified_gmt":"2017-11-18T09:30:00","slug":"casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/","title":{"rendered":"Casamassima (BA) &#8211; Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne"},"content":{"rendered":"<p>I Carabinieri della Stazione di Casamassima, nel corso di un mirato servizio volto a prevenire e contrastare lo spaccio di sostanze stupefacenti, hanno arrestato in flagranza un 24enne del luogo, gi\u00e0 noto alle forze dell\u2019ordine.<br \/>\nI Carabinieri della locale Stazione, venuti a conoscenza che nella zona periferica della citt\u00e0 avvenivano movimenti sospetti legati allo spaccio della droga, decidevano di svolgere un servizio di osservazione nei pressi di un terreno non coltivato. Ad un certo punto notavano un giovane entrare velocemente in una villetta di C.da la Pigna, e dirigersi in un deposito, ubicato nella parte retrostante dell\u2019immobile. Considerate le circostanze sospette, i militari bloccavano il giovane a cui spiegavano il motivo della loro presenza ed iniziavano la perquisizione personale; il ragazzo vistosi ormai scoperto non poteva fare altro che consegnare alcune dosi di hashish, circa 8 grammi, suddivisi in stecchette, nascoste nel borsello personale.<br \/>\nMa la successiva perquisizione, proprio all\u2019interno deposito, permetteva ai Carabinieri di rinvenire fra i sacchi di mangime, panetti di hashish per un peso complessivo di oltre un chilogrammo, dosi di cocaina per complessivi 50 grammi e varie dosi di eroina, per 10 grammi totali, nonch\u00e9 bilancini e materiale vario per il confezionamento della droga.<br \/>\nMa oltre alla droga, i militari rinvenivano e sequestravano anche una pistola marca Whalter, calibro 6,35, con colpo in canna e relativo munizionamento, illegalmente detenuta.<br \/>\nPer il 24enne sono cos\u00ec scattate le manette, dovendo rispondere della detenzione ai fini di spaccio di sostanze stupefacenti e detenzione illegale di arma da sparo con relativo munizionamento.<br \/>\nPer lui si sono aperte le porte della Casa Circondariale di Bari, ove rimarr\u00e0 a disposizione del Pubblico Ministero informato dell\u2019accaduto.<br \/>\nLa droga nei prossimi giorni verr\u00e0 analizzata dal Laboratorio Analisi del Comando Provinciale Carabinieri di Bari al fine di definirne con precisione la qualit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Carabinieri della Stazione di Casamassima, nel corso di un mirato servizio volto a prevenire e contrastare lo spaccio di sostanze stupefacenti, hanno arrestato in flagranza un 24enne del luogo, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-8396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casamassima (BA) - Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casamassima (BA) - Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"I Carabinieri della Stazione di Casamassima, nel corso di un mirato servizio volto a prevenire e contrastare lo spaccio di sostanze stupefacenti, hanno arrestato in flagranza un 24enne del luogo, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-18T09:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Casamassima (BA) &#8211; Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne\",\"datePublished\":\"2017-11-18T09:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/\"},\"wordCount\":313,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/\",\"name\":\"Casamassima (BA) - Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"datePublished\":\"2017-11-18T09:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/18\\\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casamassima (BA) &#8211; Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casamassima (BA) - Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/","og_locale":"it_IT","og_type":"article","og_title":"Casamassima (BA) - Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne - Portale dei Carabinieri","og_description":"I Carabinieri della Stazione di Casamassima, nel corso di un mirato servizio volto a prevenire e contrastare lo spaccio di sostanze stupefacenti, hanno arrestato in flagranza un 24enne del luogo, [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-18T09:30:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Casamassima (BA) &#8211; Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne","datePublished":"2017-11-18T09:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/"},"wordCount":313,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/","name":"Casamassima (BA) - Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","datePublished":"2017-11-18T09:30:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/18\/casamassima-ba-sorpreso-mentre-preparava-le-dosi-per-lo-spaccio-in-carcere-un-24enne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Casamassima (BA) &#8211; Sorpreso mentre preparava le dosi per lo spaccio. In carcere un 24enne"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=8396"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8396\/revisions"}],"predecessor-version":[{"id":8397,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8396\/revisions\/8397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=8396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=8396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=8396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}