{"id":8470,"date":"2017-11-25T11:40:00","date_gmt":"2017-11-25T10:40:00","guid":{"rendered":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?p=8470"},"modified":"2017-11-25T11:40:00","modified_gmt":"2017-11-25T10:40:00","slug":"pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/","title":{"rendered":"Pescara &#8211; Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b"},"content":{"rendered":"<p>Nella notte del 24 novembre, i Carabinieri del Nucleo Investigativo del Reparto Operativo di Pescara hanno tratto in arresto A.G., 59enne di Cappelle sul Tavo (Pe) e F.T, 32enne ex ciclista professionista di Montesilvano, entrambi pregiudicati. L\u2019operazione \u00e8 avvenuta a seguito dell\u2019esecuzione di un\u2019ordinanza di custodia cautelare agli arresti domiciliari, emessa per \u201cfurto aggravato in abitazione in concorso\u201d dal GIP del Tribunale di Pescara sulla base delle indagini svolte negli ultimi mesi dal Nucleo Investigativo.<br \/>\nL\u2019indagine ha avuto inizio allorquando gli arrestati vennero sorpresi dai carabinieri il 27 giugno u.s. mentre si apprestavano a recuperare due autovetture, una Volkswagen Golf ed una Kia Sportage, rubate pochi giorni prima rispettivamente in Giulianova (Te) e Francavilla al Mare (Ch), lasciate in sosta nei pressi della Stazione ferroviaria di Montesilvano. L\u2019immediata perquisizione personale e veicolare consentiva al Nucleo Investigativo di rinvenire e sequestrare una centralina marca Bosch per autovetture Kia , chiavi di accensioni di Bmw, 4 pneumatici completi di cerchi in lega per autovetture Hyundai, numerosi strumenti da scasso, due martinetti per il sollevamento di autovetture, due carte postamat ed un attrezzo in acciaio con un perno sporgente filettato con congegno a leva utilizzato per forzare casseforti a muro. Proprio gli accertamenti sviluppati sulla provenienza delle due carte postamat e del particolarissimo attrezzo rinvenuto, consentiva ai Carabinieri di raccogliere elementi di prova sulla responsabilit\u00e0 dei due arrestati anche in ordine ad un furto in abitazione consumato il 23 giugno precedente ai danni di una famiglia di Farindola (Pe), assenta da casa per una vacanza. Nella circostanza, i ladri avevano forzato una finestra e la cassaforte a muro con la particolare tecnica della leva sostenuta da un attrezzo in acciaio con perno (vds foto) che, inserito nello sportello della cassaforte, dopo aver praticato un foro con un trapano, agisce da sollevatore dei sostegni laterali. Questi ultimi, sottoposti a crescente pressione, cedono e provocano un distacco del sistema di apertura, sul quale restano ben impressi i segni distintivi del perno filettato.<br \/>\nQuesta particolare ed efficace metodica di scasso rappresenta un salto di qualit\u00e0 nella pratica dei furti in abitazione in relazione alla capacit\u00e0 di forzare casseforti, in particolar modo quelle a muro, con una tecnica rapida che si realizza attraverso l\u2019uso di uno strumento di fattura artigianale, sia pur contraddistinta da segni distintivi di assoluta rilevanza investigativa, e che potrebbe aver coinvolto numerose altre abitazioni della provincia.<br \/>\nSaranno in tale senso sviluppati ulteriori analisi ed accertamenti al fine di definire la pi\u00f9 ampia portata di questa specifica tecnica criminosa.<br \/>\nIn tal senso, anche attraverso la pubblicazione delle foto, trattandosi di modus operandi molto tipico ed inusuale, si vuole rendere pubblica questa metodica al fine di divulgare a cittadini la descritta tecnica laddove siano stati vittime di furti che hanno interessato casseforti a muro. In tal caso si invitano a segnalare il caso presso il Nucleo Investigativo del Comando Provinciale carabinieri di Pescara.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella notte del 24 novembre, i Carabinieri del Nucleo Investigativo del Reparto Operativo di Pescara hanno tratto in arresto A.G., 59enne di Cappelle sul Tavo (Pe) e F.T, 32enne ex [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-8470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forze-dell-ordine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pescara - Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b - Portale dei Carabinieri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-\u200b\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pescara - Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b - Portale dei Carabinieri\" \/>\n<meta property=\"og:description\" content=\"Nella notte del 24 novembre, i Carabinieri del Nucleo Investigativo del Reparto Operativo di Pescara hanno tratto in arresto A.G., 59enne di Cappelle sul Tavo (Pe) e F.T, 32enne ex [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-\u200b\/\" \/>\n<meta property=\"og:site_name\" content=\"Portale dei Carabinieri\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-25T10:40:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Pescara &#8211; Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b\",\"datePublished\":\"2017-11-25T10:40:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/\"},\"wordCount\":497,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"articleSection\":[\"Forze dell'Ordine\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/\",\"name\":\"Pescara - Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b - Portale dei Carabinieri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"datePublished\":\"2017-11-25T10:40:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2015\\\/09\\\/carabinieri.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/2017\\\/11\\\/25\\\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pescara &#8211; Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/\",\"name\":\"Portale dei Carabinieri\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/portale-dei-carabinieri\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pescara - Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b - Portale dei Carabinieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-\u200b\/","og_locale":"it_IT","og_type":"article","og_title":"Pescara - Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b - Portale dei Carabinieri","og_description":"Nella notte del 24 novembre, i Carabinieri del Nucleo Investigativo del Reparto Operativo di Pescara hanno tratto in arresto A.G., 59enne di Cappelle sul Tavo (Pe) e F.T, 32enne ex [&hellip;]","og_url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-\u200b\/","og_site_name":"Portale dei Carabinieri","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-25T10:40:00+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Pescara &#8211; Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b","datePublished":"2017-11-25T10:40:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/"},"wordCount":497,"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","articleSection":["Forze dell'Ordine"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/","name":"Pescara - Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b - Portale dei Carabinieri","isPartOf":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","datePublished":"2017-11-25T10:40:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#primaryimage","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","contentUrl":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-content\/uploads\/sites\/30\/2015\/09\/carabinieri.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/2017\/11\/25\/pescara-operazione-pit-stop-arrestati-due-pescaresi-dediti-a-furti-in-appartamento-con-tecniche-particolari-%e2%80%8b\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/"},{"@type":"ListItem","position":2,"name":"Pescara &#8211; Operazione Pit Stop: Arrestati due pescaresi dediti a furti in appartamento con tecniche particolari \u200b"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#website","url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/","name":"Portale dei Carabinieri","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/comments?post=8470"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8470\/revisions"}],"predecessor-version":[{"id":8471,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/posts\/8470\/revisions\/8471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media\/3"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/media?parent=8470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/categories?post=8470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/portale-dei-carabinieri\/wp-json\/wp\/v2\/tags?post=8470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}