{"id":104,"date":"2015-01-28T21:09:17","date_gmt":"2015-01-28T20:09:17","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=104"},"modified":"2015-01-28T21:09:17","modified_gmt":"2015-01-28T20:09:17","slug":"le-arance-della-salute","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/","title":{"rendered":"Le Arance della Salute"},"content":{"rendered":"<p><span style=\"color: #ff6600\">Anche quest&#8217;anno l&#8217; AIRC (Associazione Italiana per la Ricera sul Cancro) organizza una giornata per la raccolta di fondi per lo studio sul cancro. Vi aspettiamo uniti nella ricerca e nella speranza per il progresso ,in\u00a0<strong>Piazza degli Eroi\u00a0<span style=\"text-decoration: underline\">sabato 31 gennaio.<\/span><\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche quest&#8217;anno l&#8217; AIRC (Associazione Italiana per la Ricera sul Cancro) organizza una giornata per la raccolta di fondi per lo studio sul cancro. Vi aspettiamo uniti nella ricerca e [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le Arance della Salute - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Arance della Salute - Posta\" \/>\n<meta property=\"og:description\" content=\"Anche quest&#8217;anno l&#8217; AIRC (Associazione Italiana per la Ricera sul Cancro) organizza una giornata per la raccolta di fondi per lo studio sul cancro. Vi aspettiamo uniti nella ricerca e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-28T20:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/01\/airc_arance_14-640x480.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Le Arance della Salute\",\"datePublished\":\"2015-01-28T20:09:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/\"},\"wordCount\":45,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/01\\\/airc_arance_14-640x480.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/\",\"name\":\"Le Arance della Salute - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/01\\\/airc_arance_14-640x480.jpg\",\"datePublished\":\"2015-01-28T20:09:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/01\\\/airc_arance_14-640x480.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/01\\\/airc_arance_14-640x480.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/01\\\/28\\\/le-arance-della-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Arance della Salute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Arance della Salute - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/","og_locale":"it_IT","og_type":"article","og_title":"Le Arance della Salute - Posta","og_description":"Anche quest&#8217;anno l&#8217; AIRC (Associazione Italiana per la Ricera sul Cancro) organizza una giornata per la raccolta di fondi per lo studio sul cancro. Vi aspettiamo uniti nella ricerca e [&hellip;]","og_url":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/","og_site_name":"Posta","article_published_time":"2015-01-28T20:09:17+00:00","og_image":[{"width":533,"height":400,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/01\/airc_arance_14-640x480.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Le Arance della Salute","datePublished":"2015-01-28T20:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/"},"wordCount":45,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/01\/airc_arance_14-640x480.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/","url":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/","name":"Le Arance della Salute - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/01\/airc_arance_14-640x480.jpg","datePublished":"2015-01-28T20:09:17+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/01\/airc_arance_14-640x480.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/01\/airc_arance_14-640x480.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2015\/01\/28\/le-arance-della-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Le Arance della Salute"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/104\/revisions"}],"predecessor-version":[{"id":105,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/104\/revisions\/105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/103"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}