{"id":210,"date":"2015-08-07T20:03:07","date_gmt":"2015-08-07T18:03:07","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=210"},"modified":"2015-08-07T20:06:13","modified_gmt":"2015-08-07T18:06:13","slug":"servizio-idrico-villa-camponeschi-laculo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/","title":{"rendered":"Servizio Idrico. Villa Camponeschi &#8211; Laculo"},"content":{"rendered":"<p>Si informa la popolazione che nei giorni correnti, la Regione Lazio (settore risorse idriche), ha rilevato una diminuzione dell&#8217;approvvigionamento idrico dovuto alle persistenti condizioni climatiche. Si invita la popolazione, con particolare riferimento a Laculo e Villa Camponeschi, ad un utilizzo corretto dell&#8217;acqua ed a limitarne l&#8217;uso per necessit\u00e0 primarie. Si sta provvedendo (per Villa Camponeschi) ad interrompere il servizio idrico nelle ore notturne dei prossimi giorni (dal 08.08 al 24.08), cos\u00ec da garantire l&#8217;efficienza del servizio fino alla fine della stagione calda.<\/p>\n<p style=\"text-align: right\">L&#8217;amministrazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa la popolazione che nei giorni correnti, la Regione Lazio (settore risorse idriche), ha rilevato una diminuzione dell&#8217;approvvigionamento idrico dovuto alle persistenti condizioni climatiche. Si invita la popolazione, con [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":6,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizio Idrico. Villa Camponeschi - Laculo - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizio Idrico. Villa Camponeschi - Laculo - Posta\" \/>\n<meta property=\"og:description\" content=\"Si informa la popolazione che nei giorni correnti, la Regione Lazio (settore risorse idriche), ha rilevato una diminuzione dell&#8217;approvvigionamento idrico dovuto alle persistenti condizioni climatiche. Si invita la popolazione, con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-07T18:03:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-07T18:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2014\/10\/untitled-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Servizio Idrico. Villa Camponeschi &#8211; Laculo\",\"datePublished\":\"2015-08-07T18:03:07+00:00\",\"dateModified\":\"2015-08-07T18:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/\"},\"wordCount\":87,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2014\\\/10\\\/untitled-4.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/\",\"name\":\"Servizio Idrico. Villa Camponeschi - Laculo - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2014\\\/10\\\/untitled-4.png\",\"datePublished\":\"2015-08-07T18:03:07+00:00\",\"dateModified\":\"2015-08-07T18:06:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2014\\\/10\\\/untitled-4.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2014\\\/10\\\/untitled-4.png\",\"width\":181,\"height\":240},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/08\\\/07\\\/servizio-idrico-villa-camponeschi-laculo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizio Idrico. Villa Camponeschi &#8211; Laculo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizio Idrico. Villa Camponeschi - Laculo - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/","og_locale":"it_IT","og_type":"article","og_title":"Servizio Idrico. Villa Camponeschi - Laculo - Posta","og_description":"Si informa la popolazione che nei giorni correnti, la Regione Lazio (settore risorse idriche), ha rilevato una diminuzione dell&#8217;approvvigionamento idrico dovuto alle persistenti condizioni climatiche. Si invita la popolazione, con [&hellip;]","og_url":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/","og_site_name":"Posta","article_published_time":"2015-08-07T18:03:07+00:00","article_modified_time":"2015-08-07T18:06:13+00:00","og_image":[{"width":181,"height":240,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2014\/10\/untitled-4.png","type":"image\/png"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Servizio Idrico. Villa Camponeschi &#8211; Laculo","datePublished":"2015-08-07T18:03:07+00:00","dateModified":"2015-08-07T18:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/"},"wordCount":87,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2014\/10\/untitled-4.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/","url":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/","name":"Servizio Idrico. Villa Camponeschi - Laculo - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2014\/10\/untitled-4.png","datePublished":"2015-08-07T18:03:07+00:00","dateModified":"2015-08-07T18:06:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2014\/10\/untitled-4.png","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2014\/10\/untitled-4.png","width":181,"height":240},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2015\/08\/07\/servizio-idrico-villa-camponeschi-laculo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Servizio Idrico. Villa Camponeschi &#8211; Laculo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=210"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/210\/revisions"}],"predecessor-version":[{"id":213,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/210\/revisions\/213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/6"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}