{"id":236,"date":"2015-10-02T11:52:13","date_gmt":"2015-10-02T09:52:13","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=236"},"modified":"2015-10-02T11:52:13","modified_gmt":"2015-10-02T09:52:13","slug":"distribuzione-secchi-raccolta-differenziata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/","title":{"rendered":"Distribuzione secchi Raccolta Differenziata"},"content":{"rendered":"<p style=\"text-align: left\">Si comunica che nella mattinata di <strong>Sabato 3 Ottobre<\/strong>,<\/p>\n<p style=\"text-align: left\">dalle ore <strong>9:00 alle 10:00<\/strong>,<\/p>\n<p style=\"text-align: left\">sar\u00e0 possibile ritirare i contenitori per la raccolta differenziata presso la Palestra Comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che nella mattinata di Sabato 3 Ottobre, dalle ore 9:00 alle 10:00, sar\u00e0 possibile ritirare i contenitori per la raccolta differenziata presso la Palestra Comunale.<\/p>\n","protected":false},"author":14,"featured_media":237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Distribuzione secchi Raccolta Differenziata - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Distribuzione secchi Raccolta Differenziata - Posta\" \/>\n<meta property=\"og:description\" content=\"Si comunica che nella mattinata di Sabato 3 Ottobre, dalle ore 9:00 alle 10:00, sar\u00e0 possibile ritirare i contenitori per la raccolta differenziata presso la Palestra Comunale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-02T09:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/raccolta-differenziata-famiglie-italiane.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Distribuzione secchi Raccolta Differenziata\",\"datePublished\":\"2015-10-02T09:52:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/\"},\"wordCount\":28,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/10\\\/raccolta-differenziata-famiglie-italiane.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/\",\"name\":\"Distribuzione secchi Raccolta Differenziata - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/10\\\/raccolta-differenziata-famiglie-italiane.jpg\",\"datePublished\":\"2015-10-02T09:52:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/10\\\/raccolta-differenziata-famiglie-italiane.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/10\\\/raccolta-differenziata-famiglie-italiane.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/02\\\/distribuzione-secchi-raccolta-differenziata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Distribuzione secchi Raccolta Differenziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Distribuzione secchi Raccolta Differenziata - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/","og_locale":"it_IT","og_type":"article","og_title":"Distribuzione secchi Raccolta Differenziata - Posta","og_description":"Si comunica che nella mattinata di Sabato 3 Ottobre, dalle ore 9:00 alle 10:00, sar\u00e0 possibile ritirare i contenitori per la raccolta differenziata presso la Palestra Comunale.","og_url":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/","og_site_name":"Posta","article_published_time":"2015-10-02T09:52:13+00:00","og_image":[{"width":533,"height":400,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/raccolta-differenziata-famiglie-italiane.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Distribuzione secchi Raccolta Differenziata","datePublished":"2015-10-02T09:52:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/"},"wordCount":28,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/raccolta-differenziata-famiglie-italiane.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/","url":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/","name":"Distribuzione secchi Raccolta Differenziata - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/raccolta-differenziata-famiglie-italiane.jpg","datePublished":"2015-10-02T09:52:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/raccolta-differenziata-famiglie-italiane.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/raccolta-differenziata-famiglie-italiane.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/02\/distribuzione-secchi-raccolta-differenziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Distribuzione secchi Raccolta Differenziata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=236"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/236\/revisions"}],"predecessor-version":[{"id":238,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/236\/revisions\/238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/237"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}