{"id":245,"date":"2015-10-30T18:05:41","date_gmt":"2015-10-30T17:05:41","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=245"},"modified":"2015-10-30T18:15:25","modified_gmt":"2015-10-30T17:15:25","slug":"calendario-raccolta-differenziata","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/","title":{"rendered":"Calendario Raccolta Differenziata"},"content":{"rendered":"<p>Nell&#8217;articolo lasciamo il nuovo calendario della raccolta differenziata, pubblicato la settimana scorsa sul sito del comune, per agio e disponibilit\u00e0 di tutti i cittadini. Buon seguito<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-246\" src=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/Calendario-Nuovo2-300x206.jpg\" alt=\"Calendario Nuovo2\" width=\"300\" height=\"206\" srcset=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/Calendario-Nuovo2-300x206.jpg 300w, https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/Calendario-Nuovo2.jpg 582w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_248\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/calendario_differenziata.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/10\/calendario_differenziata.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>calendario_differenziata<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;articolo lasciamo il nuovo calendario della raccolta differenziata, pubblicato la settimana scorsa sul sito del comune, per agio e disponibilit\u00e0 di tutti i cittadini. Buon seguito \ud83d\udcce Allegaticalendario_differenziata<\/p>\n","protected":false},"author":14,"featured_media":198,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calendario Raccolta Differenziata - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendario Raccolta Differenziata - Posta\" \/>\n<meta property=\"og:description\" content=\"Nell&#8217;articolo lasciamo il nuovo calendario della raccolta differenziata, pubblicato la settimana scorsa sul sito del comune, per agio e disponibilit\u00e0 di tutti i cittadini. Buon seguito \ud83d\udcce Allegaticalendario_differenziata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-30T17:05:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-30T17:15:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/07\/raccolta-differenziata-a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Calendario Raccolta Differenziata\",\"datePublished\":\"2015-10-30T17:05:41+00:00\",\"dateModified\":\"2015-10-30T17:15:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/\"},\"wordCount\":29,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/07\\\/raccolta-differenziata-a.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/\",\"name\":\"Calendario Raccolta Differenziata - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/07\\\/raccolta-differenziata-a.jpg\",\"datePublished\":\"2015-10-30T17:05:41+00:00\",\"dateModified\":\"2015-10-30T17:15:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/07\\\/raccolta-differenziata-a.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2015\\\/07\\\/raccolta-differenziata-a.jpg\",\"width\":600,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2015\\\/10\\\/30\\\/calendario-raccolta-differenziata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendario Raccolta Differenziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendario Raccolta Differenziata - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/","og_locale":"it_IT","og_type":"article","og_title":"Calendario Raccolta Differenziata - Posta","og_description":"Nell&#8217;articolo lasciamo il nuovo calendario della raccolta differenziata, pubblicato la settimana scorsa sul sito del comune, per agio e disponibilit\u00e0 di tutti i cittadini. Buon seguito \ud83d\udcce Allegaticalendario_differenziata","og_url":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/","og_site_name":"Posta","article_published_time":"2015-10-30T17:05:41+00:00","article_modified_time":"2015-10-30T17:15:25+00:00","og_image":[{"width":600,"height":388,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/07\/raccolta-differenziata-a.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Calendario Raccolta Differenziata","datePublished":"2015-10-30T17:05:41+00:00","dateModified":"2015-10-30T17:15:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/"},"wordCount":29,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/07\/raccolta-differenziata-a.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/","url":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/","name":"Calendario Raccolta Differenziata - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/07\/raccolta-differenziata-a.jpg","datePublished":"2015-10-30T17:05:41+00:00","dateModified":"2015-10-30T17:15:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/07\/raccolta-differenziata-a.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2015\/07\/raccolta-differenziata-a.jpg","width":600,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2015\/10\/30\/calendario-raccolta-differenziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Calendario Raccolta Differenziata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=245"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/245\/revisions"}],"predecessor-version":[{"id":247,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/245\/revisions\/247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/198"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}