{"id":388,"date":"2016-11-25T21:59:06","date_gmt":"2016-11-25T20:59:06","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=388"},"modified":"2016-11-25T21:59:06","modified_gmt":"2016-11-25T20:59:06","slug":"incontro-con-la-regione-lazio-cava-carpelone","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/","title":{"rendered":"Incontro con la Regione Lazio (Cava Carpelone)"},"content":{"rendered":"<p>Come precedentemente accordato dall&#8217;amministrazione con la cittadinanza, si terr\u00e0 un incontro con la rappresentanza della Regione sull&#8217; argomento &#8220;Cava carpelone&#8221; (deposito macerie provenienti da Amatrice). Lo stesso si terr\u00e0 questo Luned\u00ec, 28 novembre, presso l&#8217;edificio Ex Scolette a partire dalle ore 15:00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come precedentemente accordato dall&#8217;amministrazione con la cittadinanza, si terr\u00e0 un incontro con la rappresentanza della Regione sull&#8217; argomento &#8220;Cava carpelone&#8221; (deposito macerie provenienti da Amatrice). Lo stesso si terr\u00e0 questo [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incontro con la Regione Lazio (Cava Carpelone) - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incontro con la Regione Lazio (Cava Carpelone) - Posta\" \/>\n<meta property=\"og:description\" content=\"Come precedentemente accordato dall&#8217;amministrazione con la cittadinanza, si terr\u00e0 un incontro con la rappresentanza della Regione sull&#8217; argomento &#8220;Cava carpelone&#8221; (deposito macerie provenienti da Amatrice). Lo stesso si terr\u00e0 questo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-25T20:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/11\/assemblea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Incontro con la Regione Lazio (Cava Carpelone)\",\"datePublished\":\"2016-11-25T20:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/\"},\"wordCount\":47,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/11\\\/assemblea.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/\",\"name\":\"Incontro con la Regione Lazio (Cava Carpelone) - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/11\\\/assemblea.jpg\",\"datePublished\":\"2016-11-25T20:59:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/11\\\/assemblea.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/11\\\/assemblea.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2016\\\/11\\\/25\\\/incontro-con-la-regione-lazio-cava-carpelone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro con la Regione Lazio (Cava Carpelone)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incontro con la Regione Lazio (Cava Carpelone) - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/","og_locale":"it_IT","og_type":"article","og_title":"Incontro con la Regione Lazio (Cava Carpelone) - Posta","og_description":"Come precedentemente accordato dall&#8217;amministrazione con la cittadinanza, si terr\u00e0 un incontro con la rappresentanza della Regione sull&#8217; argomento &#8220;Cava carpelone&#8221; (deposito macerie provenienti da Amatrice). Lo stesso si terr\u00e0 questo [&hellip;]","og_url":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/","og_site_name":"Posta","article_published_time":"2016-11-25T20:59:06+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/11\/assemblea.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Incontro con la Regione Lazio (Cava Carpelone)","datePublished":"2016-11-25T20:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/"},"wordCount":47,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/11\/assemblea.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/","url":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/","name":"Incontro con la Regione Lazio (Cava Carpelone) - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/11\/assemblea.jpg","datePublished":"2016-11-25T20:59:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/11\/assemblea.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/11\/assemblea.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2016\/11\/25\/incontro-con-la-regione-lazio-cava-carpelone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Incontro con la Regione Lazio (Cava Carpelone)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/388\/revisions"}],"predecessor-version":[{"id":390,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/388\/revisions\/390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/389"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}