{"id":476,"date":"2017-05-04T11:23:54","date_gmt":"2017-05-04T09:23:54","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=476"},"modified":"2017-05-04T11:23:54","modified_gmt":"2017-05-04T09:23:54","slug":"assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/","title":{"rendered":"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma)"},"content":{"rendered":"<p>L&#8217;Ordinanza 21 del 28 Aprile stabilisce l&#8217;erogazione di contributi per chi ha dovuto sostenere spese di trasloco e di deposito temporaneo, in seguito al danneggiamento della propria abitazione a causa degli evento sismici. In allegato all&#8217;articolo c&#8217;\u00e8 l&#8217;ordinanza con le specifiche e gli allegati per la richiesta del contributo.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_477\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/05\/Ordinanza-n21-del-28-4-17.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/05\/Ordinanza-n21-del-28-4-17.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza n21 del 28-4-17<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Ordinanza 21 del 28 Aprile stabilisce l&#8217;erogazione di contributi per chi ha dovuto sostenere spese di trasloco e di deposito temporaneo, in seguito al danneggiamento della propria abitazione a causa [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma) - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma) - Posta\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Ordinanza 21 del 28 Aprile stabilisce l&#8217;erogazione di contributi per chi ha dovuto sostenere spese di trasloco e di deposito temporaneo, in seguito al danneggiamento della propria abitazione a causa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-04T09:23:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/10\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma)\",\"datePublished\":\"2017-05-04T09:23:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/\"},\"wordCount\":60,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/10\\\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/\",\"name\":\"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma) - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/10\\\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg\",\"datePublished\":\"2017-05-04T09:23:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/10\\\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2016\\\/10\\\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/05\\\/04\\\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma) - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/","og_locale":"it_IT","og_type":"article","og_title":"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma) - Posta","og_description":"L&#8217;Ordinanza 21 del 28 Aprile stabilisce l&#8217;erogazione di contributi per chi ha dovuto sostenere spese di trasloco e di deposito temporaneo, in seguito al danneggiamento della propria abitazione a causa [&hellip;]","og_url":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/","og_site_name":"Posta","article_published_time":"2017-05-04T09:23:54+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/10\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma)","datePublished":"2017-05-04T09:23:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/"},"wordCount":60,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/10\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/","url":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/","name":"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma) - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/10\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg","datePublished":"2017-05-04T09:23:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/10\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2016\/10\/1ea804dbf6a45ba977293c237ecc1b08_XL.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2017\/05\/04\/assegnazione-di-contributi-per-i-costi-di-trasloco-e-di-deposito-temporaneo-sisma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Assegnazione di contributi per i costi di trasloco e di deposito temporaneo (sisma)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/476\/revisions\/478"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/378"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}