{"id":493,"date":"2017-06-16T11:09:42","date_gmt":"2017-06-16T09:09:42","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=493"},"modified":"2017-06-16T11:09:42","modified_gmt":"2017-06-16T09:09:42","slug":"bando-volontari-per-il-servizio-civile-nazionale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/","title":{"rendered":"Bando volontari per il servizio civile nazionale"},"content":{"rendered":"<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\"><strong><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Fai domanda per il Servizio Civile <\/span><\/strong><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: center;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal;background: white\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">E\u2019 stato pubblicato il\u00a0<span>bando<\/span>\u00a0per i volontari del servizio civile emesso dalla Presidenza del Consiglio dei Ministri. Il termine per fare domanda scade il<span>\u00a026\/6\/2017 alle ore 14.00.<\/span><\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Nell\u2019ambito di questo bando \u00e8 possibile fare domanda per svolgere il servizio civile presso i progetti:<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Velino in\/veste sociale e<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Ambiente Velino <\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">che saranno gestiti in partnership da Comunit\u00e0 Montana del Velino e Comune di Posta.<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Sono disponibili 12 posti, e in particolare:<\/span><\/p>\n<ul>\n<li style=\"text-indent: -21.3pt;line-height: normal;margin: 0cm 0cm .0001pt 21.3pt\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">6 posti presso la sede della Comunit\u00e0 Montana (Posta)<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"text-indent: -21.3pt;line-height: normal;margin: 0cm 0cm .0001pt 21.3pt\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">6 posti presso la sede del Comune di Posta\n<p> <\/span><\/li>\n<\/ul>\n<p style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Possono candidarsi i giovani che abbiano compiuto i 18 anni e non superato i 28 (28 anni e 364 giorni alla data di presentazione della domanda). \u00c8 possibile candidarsi ad un solo progetto di servizio civile, pena l\u2019esclusione della domanda.<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"><br \/>\nLa domanda deve essere presentata esclusivamente secondo una delle seguenti modalit\u00e0:<br \/>\n\u2022 inviata a mezzo raccomandata A\/R all&#8217;indirizzo della Comunit\u00e0 Montana del Velino, Via Roma 103 \u2013 02019 Posta (RI)<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">(la raccomandata deve PERVENIRE entro il 26\/6\/17 &#8211; NON fa fede il timbro postale);\u00a0<\/p>\n<p> <\/span><\/p>\n<ul>\n<li style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"> con Posta Elettronica Certificata (PEC) avendo cura di allegare tutta la documentazione in formato PDF); l\u2019indirizzo PEC del mittente deve essere intestato al giovane che si candida; la domanda deve pervenire all\u2019indirizzo PEC: \u00a0info@pec.velino.it;<\/span><\/li>\n<\/ul>\n<p style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">\u00a0<\/span><\/p>\n<ul>\n<li style=\"margin-bottom: .0001pt;text-align: justify;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"> Consegnata a mano presso la sede della Comunit\u00e0 Montana del Velino, Via Roma 103 \u2013 02019 Posta (RI). <\/span><\/li>\n<\/ul>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">La domanda deve comprendere:<br \/>\n\u2022 il modulo dell&#8217;allegato 2 \u2013 domanda di partecipazione\u201a compilato e firmato\u201a con la firma necessariamente apposta in forma autografa;<br \/>\n\u2022 la fotocopia di un documento di identit\u00e0 valido; <\/span><\/p>\n<ul>\n<li style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"> il modulo dell&#8217;allegato 3 \u2013 dichiarazione sui titoli posseduti;<br \/>\n\u2022 eventuale curriculum vitae\u201a copia di eventuali titoli in possesso del candidato (diplomi, attestati, ecc) e ogni altra documentazione significativa.<\/span><\/li>\n<\/ul>\n<p style=\"margin-bottom: .0001pt;line-height: normal;background: white\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"><br \/>\nPer informazioni e chiarimenti potete contattare _________________,<span>\u00a0 <\/span><\/span><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">Tel. 06-97180028,<span>\u00a0 <\/span>e-mail\u00a0<\/span><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif';color: windowtext\">_____________________<\/span><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">\u00a0<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"><br \/>\nSi allega la seguente documentazione:<\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">&#8211; <a href=\"images\/Bando_Protezione_Civile_06.17\/Bando-Regione-Lazio.pdf\">il bando<\/a><\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">&#8211; <\/span><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"><a href=\"images\/Bando_Protezione_Civile_06.17\/Allegato_6_Sintesi_di_Velino_In-veste_sociale.pdf\">una sintesi del progetto Velino in\/veste Sociale<\/a><\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">&#8211; <\/span><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\"><a href=\"images\/Bando_Protezione_Civile_06.17\/Allegato_6_Sintesi_di_Ambiente_Velino.pdf\">una sintesi del progetto Ambiente Velino<\/a><\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 12.0pt;font-family: 'Times New Roman','serif'\">&#8211; i moduli allegati: <a href=\"images\/Bando_Protezione_Civile_06.17\/Allegato2_-_Domanda_di_ammissione.docx\">Allegato 2<\/a><\/span><\/p>\n<p style=\"margin-bottom: .0001pt;line-height: normal\"><span style=\"font-size: 10pt\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<a href=\"images\/Bando_Protezione_Civile_06.17\/Allegato_3_Dichiarazione_Titoli.doc\">Allegato 3<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fai domanda per il Servizio Civile \u00a0 E\u2019 stato pubblicato il\u00a0bando\u00a0per i volontari del servizio civile emesso dalla Presidenza del Consiglio dei Ministri. Il termine per fare domanda scade il\u00a026\/6\/2017 [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando volontari per il servizio civile nazionale - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando volontari per il servizio civile nazionale - Posta\" \/>\n<meta property=\"og:description\" content=\"Fai domanda per il Servizio Civile \u00a0 E\u2019 stato pubblicato il\u00a0bando\u00a0per i volontari del servizio civile emesso dalla Presidenza del Consiglio dei Ministri. Il termine per fare domanda scade il\u00a026\/6\/2017 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-16T09:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/04\/Servizio-Civile-Nazionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Bando volontari per il servizio civile nazionale\",\"datePublished\":\"2017-06-16T09:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/\"},\"wordCount\":323,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/04\\\/Servizio-Civile-Nazionale.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/\",\"name\":\"Bando volontari per il servizio civile nazionale - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/04\\\/Servizio-Civile-Nazionale.jpg\",\"datePublished\":\"2017-06-16T09:09:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/04\\\/Servizio-Civile-Nazionale.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/04\\\/Servizio-Civile-Nazionale.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/06\\\/16\\\/bando-volontari-per-il-servizio-civile-nazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando volontari per il servizio civile nazionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando volontari per il servizio civile nazionale - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Bando volontari per il servizio civile nazionale - Posta","og_description":"Fai domanda per il Servizio Civile \u00a0 E\u2019 stato pubblicato il\u00a0bando\u00a0per i volontari del servizio civile emesso dalla Presidenza del Consiglio dei Ministri. Il termine per fare domanda scade il\u00a026\/6\/2017 [&hellip;]","og_url":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/","og_site_name":"Posta","article_published_time":"2017-06-16T09:09:42+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/04\/Servizio-Civile-Nazionale.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Bando volontari per il servizio civile nazionale","datePublished":"2017-06-16T09:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/"},"wordCount":323,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/04\/Servizio-Civile-Nazionale.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/","url":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/","name":"Bando volontari per il servizio civile nazionale - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/04\/Servizio-Civile-Nazionale.jpg","datePublished":"2017-06-16T09:09:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/04\/Servizio-Civile-Nazionale.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/04\/Servizio-Civile-Nazionale.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2017\/06\/16\/bando-volontari-per-il-servizio-civile-nazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Bando volontari per il servizio civile nazionale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=493"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/493\/revisions"}],"predecessor-version":[{"id":494,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/493\/revisions\/494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/466"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}