{"id":543,"date":"2017-08-10T12:42:30","date_gmt":"2017-08-10T10:42:30","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=543"},"modified":"2017-08-10T12:42:30","modified_gmt":"2017-08-10T10:42:30","slug":"sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/","title":{"rendered":"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17"},"content":{"rendered":"<p><span style=\"font-family: georgia,palatino;font-size: 14pt\">Si comunica alla cittadinanza che il giorno Marted\u00ec 15 Agosto, la TAC Ecologica non effettuer\u00e0 il servizio di raccolta della differenziata, quindi il ritiro di carta e cartone.<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica alla cittadinanza che il giorno Marted\u00ec 15 Agosto, la TAC Ecologica non effettuer\u00e0 il servizio di raccolta della differenziata, quindi il ritiro di carta e cartone.<\/p>\n","protected":false},"author":14,"featured_media":544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17 - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17 - Posta\" \/>\n<meta property=\"og:description\" content=\"Si comunica alla cittadinanza che il giorno Marted\u00ec 15 Agosto, la TAC Ecologica non effettuer\u00e0 il servizio di raccolta della differenziata, quindi il ritiro di carta e cartone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-10T10:42:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/08\/carta-e-cartone1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"239\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\\\/08\\\/17\",\"datePublished\":\"2017-08-10T10:42:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/\"},\"wordCount\":38,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/08\\\/carta-e-cartone1.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/\",\"name\":\"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\\\/08\\\/17 - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/08\\\/carta-e-cartone1.jpg\",\"datePublished\":\"2017-08-10T10:42:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/08\\\/carta-e-cartone1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/08\\\/carta-e-cartone1.jpg\",\"width\":550,\"height\":239},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2017\\\/08\\\/10\\\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\\\/08\\\/17\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17 - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/","og_locale":"it_IT","og_type":"article","og_title":"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17 - Posta","og_description":"Si comunica alla cittadinanza che il giorno Marted\u00ec 15 Agosto, la TAC Ecologica non effettuer\u00e0 il servizio di raccolta della differenziata, quindi il ritiro di carta e cartone.","og_url":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/","og_site_name":"Posta","article_published_time":"2017-08-10T10:42:30+00:00","og_image":[{"width":550,"height":239,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/08\/carta-e-cartone1.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17","datePublished":"2017-08-10T10:42:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/"},"wordCount":38,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/08\/carta-e-cartone1.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/","url":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/","name":"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17 - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/08\/carta-e-cartone1.jpg","datePublished":"2017-08-10T10:42:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/08\/carta-e-cartone1.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2017\/08\/carta-e-cartone1.jpg","width":550,"height":239},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2017\/08\/10\/sospensione-del-ritiro-del-rifiuto-differenziato-per-il-solo-giorno-del-150817\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Sospensione del ritiro del rifiuto differenziato per il solo giorno del 15\/08\/17"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=543"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/543\/revisions"}],"predecessor-version":[{"id":545,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/543\/revisions\/545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/544"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}