{"id":607,"date":"2018-06-07T10:52:09","date_gmt":"2018-06-07T08:52:09","guid":{"rendered":"https:\/\/comunicacity.net\/posta\/?p=607"},"modified":"2018-06-07T10:52:09","modified_gmt":"2018-06-07T08:52:09","slug":"sabato-23-giugno-giornata-della-prevenzione-a-posta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/","title":{"rendered":"Sabato 23 Giugno, Giornata della prevenzione a Posta"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":14,"featured_media":608,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sabato 23 Giugno, Giornata della prevenzione a Posta - Posta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sabato 23 Giugno, Giornata della prevenzione a Posta - Posta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/\" \/>\n<meta property=\"og:site_name\" content=\"Posta\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-07T08:52:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2018\/06\/giornata-prevenzione-posta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"565\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Paoni\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Paoni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/\"},\"author\":{\"name\":\"Gianluca Paoni\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"headline\":\"Sabato 23 Giugno, Giornata della prevenzione a Posta\",\"datePublished\":\"2018-06-07T08:52:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/\"},\"wordCount\":7,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/06\\\/giornata-prevenzione-posta.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/\",\"name\":\"Sabato 23 Giugno, Giornata della prevenzione a Posta - Posta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/06\\\/giornata-prevenzione-posta.jpg\",\"datePublished\":\"2018-06-07T08:52:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/06\\\/giornata-prevenzione-posta.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2018\\\/06\\\/giornata-prevenzione-posta.jpg\",\"width\":565,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/2018\\\/06\\\/07\\\/sabato-23-giugno-giornata-della-prevenzione-a-posta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sabato 23 Giugno, Giornata della prevenzione a Posta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/\",\"name\":\"Posta\",\"description\":\"Ecco un altro sito ComunicaCity Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/#\\\/schema\\\/person\\\/df05c599adf9079c14eff92386669266\",\"name\":\"Gianluca Paoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g\",\"caption\":\"Gianluca Paoni\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/posta\\\/author\\\/giordanofoffo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sabato 23 Giugno, Giornata della prevenzione a Posta - Posta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/","og_locale":"it_IT","og_type":"article","og_title":"Sabato 23 Giugno, Giornata della prevenzione a Posta - Posta","og_url":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/","og_site_name":"Posta","article_published_time":"2018-06-07T08:52:09+00:00","og_image":[{"width":565,"height":800,"url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2018\/06\/giornata-prevenzione-posta.jpg","type":"image\/jpeg"}],"author":"Gianluca Paoni","twitter_misc":{"Scritto da":"Gianluca Paoni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/"},"author":{"name":"Gianluca Paoni","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"headline":"Sabato 23 Giugno, Giornata della prevenzione a Posta","datePublished":"2018-06-07T08:52:09+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/"},"wordCount":7,"image":{"@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2018\/06\/giornata-prevenzione-posta.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/","url":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/","name":"Sabato 23 Giugno, Giornata della prevenzione a Posta - Posta","isPartOf":{"@id":"https:\/\/comunicacity.net\/posta\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2018\/06\/giornata-prevenzione-posta.jpg","datePublished":"2018-06-07T08:52:09+00:00","author":{"@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#primaryimage","url":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2018\/06\/giornata-prevenzione-posta.jpg","contentUrl":"https:\/\/comunicacity.net\/posta\/wp-content\/uploads\/sites\/9\/2018\/06\/giornata-prevenzione-posta.jpg","width":565,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/posta\/2018\/06\/07\/sabato-23-giugno-giornata-della-prevenzione-a-posta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/posta\/"},{"@type":"ListItem","position":2,"name":"Sabato 23 Giugno, Giornata della prevenzione a Posta"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/posta\/#website","url":"https:\/\/comunicacity.net\/posta\/","name":"Posta","description":"Ecco un altro sito ComunicaCity Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/posta\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/posta\/#\/schema\/person\/df05c599adf9079c14eff92386669266","name":"Gianluca Paoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/165369c3659e8137aeb937a1549edf8dbbc48e675e89f9efeff10c126921535c?s=96&d=mm&r=g","caption":"Gianluca Paoni"},"url":"https:\/\/comunicacity.net\/posta\/author\/giordanofoffo\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/comments?post=607"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/607\/revisions"}],"predecessor-version":[{"id":609,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/posts\/607\/revisions\/609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media\/608"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/media?parent=607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/categories?post=607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/posta\/wp-json\/wp\/v2\/tags?post=607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}