{"id":132,"date":"2024-11-27T18:31:19","date_gmt":"2024-11-27T17:31:19","guid":{"rendered":"https:\/\/comunicacity.net\/prossedi\/?p=132"},"modified":"2024-11-27T18:31:22","modified_gmt":"2024-11-27T17:31:22","slug":"avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/","title":{"rendered":"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE"},"content":{"rendered":"<p><em>Obiettivo del presente Avviso \u00e8 la riqualificazione di aree verdi pubbliche presenti sul territorio comunale.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Lo scopo del presente Avviso \u00e8 la ricerca di soggetti esterni all\u2019Amministrazione Comunale, pubblici o privati (persone fisiche o giuridiche), anche in forma associata, che intendano proporsi come sponsor dell\u2019Amministrazione per realizzare interventi di riqualificazione di aree verdi pubbliche, consistenti :<\/p>\n<ul>\n<li>nella sostituzione di attrezzature ludiche obsolete, nel<\/li>\n<li>nell\u2019installazione di attrezzature sportive, arredi urbani e nuovi giochi,<\/li>\n<\/ul>\n<p>Ai soggetti attuatori dei progetti sar\u00e0 riconosciuto un ritorno di immagine attraverso l\u2019apposizione, sul luogo assegnato, di uno o pi\u00f9 pannelli di comunicazione, in esenzione dal versamento del canone non trattandosi di pubblicit\u00e0.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_162\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/2_ALLEGATO-A-ELENCO-AREE-SPONSORIZZABILI.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/2_ALLEGATO-A-ELENCO-AREE-SPONSORIZZABILI.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>2_ALLEGATO A ELENCO AREE SPONSORIZZABILI<\/a><\/li>\n<li><a id=\"wpba_attachment_list_161\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/1_AVVISO-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/1_AVVISO-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>1_AVVISO (1)<\/a><\/li>\n<li><a id=\"wpba_attachment_list_160\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/Atto-copia-conforme-1-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/Atto-copia-conforme-1-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Atto copia conforme (1) (1)<\/a><\/li>\n<li><a id=\"wpba_attachment_list_163\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/2_ALLEGATO-B-SCHEMA-DI-CONTRATTO.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/2_ALLEGATO-B-SCHEMA-DI-CONTRATTO.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>2_ALLEGATO B SCHEMA DI CONTRATTO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_164\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/2_ALLEGATO-C-ISTANZA-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/2_ALLEGATO-C-ISTANZA-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>2_ALLEGATO C ISTANZA (1)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Obiettivo del presente Avviso \u00e8 la riqualificazione di aree verdi pubbliche presenti sul territorio comunale.&nbsp; Descrizione&nbsp; Lo scopo del presente Avviso \u00e8 la ricerca di soggetti esterni all\u2019Amministrazione Comunale, pubblici [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":159,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE - Prossedi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE - Prossedi\" \/>\n<meta property=\"og:description\" content=\"Obiettivo del presente Avviso \u00e8 la riqualificazione di aree verdi pubbliche presenti sul territorio comunale.&nbsp; Descrizione&nbsp; Lo scopo del presente Avviso \u00e8 la ricerca di soggetti esterni all\u2019Amministrazione Comunale, pubblici [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/\" \/>\n<meta property=\"og:site_name\" content=\"Prossedi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-27T17:31:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-27T17:31:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/manutenzione-verde-pubblico-maiori-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE\",\"datePublished\":\"2024-11-27T17:31:19+00:00\",\"dateModified\":\"2024-11-27T17:31:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/\"},\"wordCount\":122,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2024\\\/11\\\/manutenzione-verde-pubblico-maiori-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/\",\"name\":\"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE - Prossedi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2024\\\/11\\\/manutenzione-verde-pubblico-maiori-1.jpg\",\"datePublished\":\"2024-11-27T17:31:19+00:00\",\"dateModified\":\"2024-11-27T17:31:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2024\\\/11\\\/manutenzione-verde-pubblico-maiori-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2024\\\/11\\\/manutenzione-verde-pubblico-maiori-1.jpg\",\"width\":1170,\"height\":650},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2024\\\/11\\\/27\\\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE - Prossedi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE - Prossedi","og_description":"Obiettivo del presente Avviso \u00e8 la riqualificazione di aree verdi pubbliche presenti sul territorio comunale.&nbsp; Descrizione&nbsp; Lo scopo del presente Avviso \u00e8 la ricerca di soggetti esterni all\u2019Amministrazione Comunale, pubblici [&hellip;]","og_url":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/","og_site_name":"Prossedi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-11-27T17:31:19+00:00","article_modified_time":"2024-11-27T17:31:22+00:00","og_image":[{"width":1170,"height":650,"url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/manutenzione-verde-pubblico-maiori-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE","datePublished":"2024-11-27T17:31:19+00:00","dateModified":"2024-11-27T17:31:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/"},"wordCount":122,"publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/manutenzione-verde-pubblico-maiori-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/","url":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/","name":"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE - Prossedi","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/manutenzione-verde-pubblico-maiori-1.jpg","datePublished":"2024-11-27T17:31:19+00:00","dateModified":"2024-11-27T17:31:22+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#primaryimage","url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/manutenzione-verde-pubblico-maiori-1.jpg","contentUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2024\/11\/manutenzione-verde-pubblico-maiori-1.jpg","width":1170,"height":650},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/prossedi\/2024\/11\/27\/avviso-per-ricerca-di-sponsorizzazioni-per-interventi-di-riqualificazione-di-aree-verdi-pubbliche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/prossedi\/"},{"@type":"ListItem","position":2,"name":"AVVISO PER RICERCA DI SPONSORIZZAZIONI PER INTERVENTI DI RIQUALIFICAZIONE DI AREE VERDI PUBBLICHE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/prossedi\/#website","url":"https:\/\/comunicacity.net\/prossedi\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/prossedi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/prossedi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/prossedi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001458"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/comments?post=132"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/132\/revisions"}],"predecessor-version":[{"id":152,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/132\/revisions\/152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media\/159"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media?parent=132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/categories?post=132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/tags?post=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}