{"id":366,"date":"2025-03-03T09:48:17","date_gmt":"2025-03-03T08:48:17","guid":{"rendered":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/"},"modified":"2025-03-03T09:48:17","modified_gmt":"2025-03-03T08:48:17","slug":"giorno-della-memoria-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/prossedi\/2025\/03\/03\/giorno-della-memoria-2\/","title":{"rendered":"Giorno della Memoria"},"content":{"rendered":"<p style='margin-bottom: 11px;padding-bottom: 0px'><b style='font-size: 16px;color: #333'>Dal 28 Gennaio 2025<\/b> <b style='font-size: 16px;color: #333'>al 28 Gennaio 2025<\/b><\/p>\n<p><em>Bandiere a mezz&#8217;asta per il Giorno della Memoria<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In omaggio alle vittime dello sterminio e delle persecuzioni del popolo ebraico e dei deportati militari e politici italiani nei campi nazisti.<\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>A chi \u00e8 rivolto:<\/b><\/p>\n<p><span style='font-size: 16px;color: #555'>Commemorazione<\/span><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Costi:<\/b> <span style='font-size: 16px;color: #555'>Nessun costo.<\/span><\/p>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Contatti:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 5px'><span>Comune di Prossedi<\/span><\/li>\n<p><span style='font-size: 15px'><b>Indirizzo<\/b>: via P.ssa A. Gabrielli 74<\/span><br \/><span style='font-size: 15px'><b>Telefono<\/b>: 0773 957016<\/span><br \/><span style='font-size: 15px'><b>Telefono<\/b>: 0773 957212<\/span><br \/><span style='font-size: 15px'><b>Fax<\/b>: 0773 956026<\/span><br \/><span style='font-size: 15px'><b>PEC<\/b>: comune.prossedi@postecert.it<\/span><\/ul>\n<p>&nbsp;<\/p>\n<p><b>Immagini<\/b><\/p>\n<p><img src='https:\/\/comune.prossedi.lt.it\/wp-content\/uploads\/2025\/01\/1737967181517-scaled.jpg'><\/img><\/p>\n<p>\n\t\t\t<h4>Inizio<\/h4>\n<p>28\/01\/2025 00:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>28\/01\/2025 00:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Dal 28 Gennaio 2025 al 28 Gennaio 2025 Bandiere a mezz&#8217;asta per il Giorno della Memoria&nbsp; Descrizione&nbsp; In omaggio alle vittime dello sterminio e delle persecuzioni del popolo ebraico e [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":434,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giorno della Memoria - Prossedi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giorno della Memoria - Prossedi\" \/>\n<meta property=\"og:description\" content=\"Dal 28 Gennaio 2025 al 28 Gennaio 2025 Bandiere a mezz&#8217;asta per il Giorno della Memoria&nbsp; Descrizione&nbsp; In omaggio alle vittime dello sterminio e delle persecuzioni del popolo ebraico e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Prossedi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-03T08:48:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/01\/1737967181517-scaled-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Giorno della Memoria\",\"datePublished\":\"2025-03-03T08:48:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/\"},\"wordCount\":67,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/03\\\/1737967181517-scaled-2.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/\",\"name\":\"Giorno della Memoria - Prossedi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/03\\\/1737967181517-scaled-2.jpg\",\"datePublished\":\"2025-03-03T08:48:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/03\\\/1737967181517-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/03\\\/1737967181517-scaled-2.jpg\",\"width\":2560,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/01\\\/27\\\/giorno-della-memoria-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giorno della Memoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giorno della Memoria - Prossedi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/","og_locale":"it_IT","og_type":"article","og_title":"Giorno della Memoria - Prossedi","og_description":"Dal 28 Gennaio 2025 al 28 Gennaio 2025 Bandiere a mezz&#8217;asta per il Giorno della Memoria&nbsp; Descrizione&nbsp; In omaggio alle vittime dello sterminio e delle persecuzioni del popolo ebraico e [&hellip;]","og_url":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/","og_site_name":"Prossedi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-03T08:48:17+00:00","og_image":[{"width":2560,"height":2448,"url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/01\/1737967181517-scaled-2.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Giorno della Memoria","datePublished":"2025-03-03T08:48:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/"},"wordCount":67,"publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/03\/1737967181517-scaled-2.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/","url":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/","name":"Giorno della Memoria - Prossedi","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/03\/1737967181517-scaled-2.jpg","datePublished":"2025-03-03T08:48:17+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#primaryimage","url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/03\/1737967181517-scaled-2.jpg","contentUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/03\/1737967181517-scaled-2.jpg","width":2560,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/01\/27\/giorno-della-memoria-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/prossedi\/"},{"@type":"ListItem","position":2,"name":"Giorno della Memoria"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/prossedi\/#website","url":"https:\/\/comunicacity.net\/prossedi\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/prossedi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/prossedi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/prossedi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"28\/01\/2025 00:00","cc4_eve_data_fine":"28\/01\/2025 00:00","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001617"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/comments?post=366"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/366\/revisions"}],"predecessor-version":[{"id":432,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/366\/revisions\/432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media\/434"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media?parent=366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/categories?post=366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/tags?post=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}