{"id":384,"date":"2025-02-15T09:53:49","date_gmt":"2025-02-15T08:53:49","guid":{"rendered":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/"},"modified":"2025-02-15T09:53:49","modified_gmt":"2025-02-15T08:53:49","slug":"compagnia-itinerante-della-salute","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/","title":{"rendered":"Compagnia itinerante della salute"},"content":{"rendered":"<p><em>La Compagnia Itinerante della Salute fa tappa nelle citt\u00e0 della provincia: prevenzione e screening gratuiti dal 17 al 21 febbraio.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<h3 data-start=\"0\" data-end=\"139\">La\u00a0<strong data-start=\"144\" data-end=\"161\">ASL di Latina<\/strong>\u00a0ha avviato un&#8217;importante campagna di prevenzione con la\u00a0<strong data-start=\"218\" data-end=\"255\">Compagnia Itinerante della Salute<\/strong>, un\u2019iniziativa dedicata alla tutela del benessere dei cittadini attraverso screening e consulenze gratuite.<\/h3>\n<p data-start=\"367\" data-end=\"570\">Dal\u00a0<strong data-start=\"371\" data-end=\"392\">17 al 21 febbraio<\/strong>, un\u2019<strong data-start=\"397\" data-end=\"413\">unit\u00e0 mobile<\/strong>\u00a0sar\u00e0 presente in diverse localit\u00e0 della provincia per offrire servizi sanitari essenziali, facilitando l\u2019accesso alla prevenzione e alla diagnosi precoce.<\/p>\n<h3 data-start=\"572\" data-end=\"605\"><strong data-start=\"576\" data-end=\"603\">Calendario delle tappe:<\/strong><\/h3>\n<p data-start=\"606\" data-end=\"947\"><strong data-start=\"609\" data-end=\"624\">-17 febbraio<\/strong>\u00a0&#8211; Terracina (Piazza Garibaldi)<br data-start=\"655\" data-end=\"658\" \/><strong data-start=\"661\" data-end=\"676\">-18 febbraio<\/strong>\u00a0&#8211; Sabaudia (Piazza del Comune)<br data-start=\"707\" data-end=\"710\" \/><strong data-start=\"713\" data-end=\"728\">-19 febbraio<\/strong>\u00a0&#8211; Pontinia (Piazza Roma)<br data-start=\"753\" data-end=\"756\" \/><strong data-start=\"759\" data-end=\"774\">-20 febbraio<\/strong>\u00a0&#8211; Sonnino-Roccasecca (Piazzale antistante Chiesa di San Francesco)<br data-start=\"841\" data-end=\"844\" \/><strong data-start=\"847\" data-end=\"862\">-21 febbraio<\/strong>\u00a0&#8211; Priverno-Prossedi (Via Madonna delle Grazie &#8211; Area parcheggio Casa della Salute)<\/p>\n<p data-start=\"949\" data-end=\"998\">\u23f0\u00a0<strong data-start=\"951\" data-end=\"974\">Orario di attivit\u00e0:<\/strong>\u00a0dalle 9:00 alle 16:30<\/p>\n<h3 data-start=\"1000\" data-end=\"1030\"><strong data-start=\"1004\" data-end=\"1028\">Servizi disponibili:<\/strong><\/h3>\n<ul data-start=\"1031\" data-end=\"1425\">\n<li data-start=\"1031\" data-end=\"1115\"><strong data-start=\"1033\" data-end=\"1055\">Screening gratuiti<\/strong>: mammografia, HPV\/PAP test, consegna provetta colon-retto<\/li>\n<li data-start=\"1116\" data-end=\"1157\"><strong data-start=\"1118\" data-end=\"1155\">Counseling senologico e ostetrico<\/strong><\/li>\n<li data-start=\"1158\" data-end=\"1262\"><strong data-start=\"1160\" data-end=\"1201\">Consulenza sui corretti stili di vita<\/strong>\u00a0(alimentazione, attivit\u00e0 fisica, prevenzione fumo e alcol)<\/li>\n<li data-start=\"1263\" data-end=\"1377\"><strong data-start=\"1265\" data-end=\"1303\">Valutazione dei fattori di rischio<\/strong>\u00a0per malattie croniche (pressione arteriosa, glicemia, colesterolo, BMI)<\/li>\n<li data-start=\"1378\" data-end=\"1425\"><strong data-start=\"1380\" data-end=\"1423\">Prenotazione vaccinale per l\u2019et\u00e0 adulta<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.prossedi.lt.it\/wp-content\/uploads\/2025\/02\/Compagnia-itinerante-della-salute.jpg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Compagnia Itinerante della Salute fa tappa nelle citt\u00e0 della provincia: prevenzione e screening gratuiti dal 17 al 21 febbraio.&nbsp; Descrizione&nbsp; La\u00a0ASL di Latina\u00a0ha avviato un&#8217;importante campagna di prevenzione con [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":385,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Compagnia itinerante della salute - Prossedi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Compagnia itinerante della salute - Prossedi\" \/>\n<meta property=\"og:description\" content=\"La Compagnia Itinerante della Salute fa tappa nelle citt\u00e0 della provincia: prevenzione e screening gratuiti dal 17 al 21 febbraio.&nbsp; Descrizione&nbsp; La\u00a0ASL di Latina\u00a0ha avviato un&#8217;importante campagna di prevenzione con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"Prossedi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-15T08:53:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Compagnia-itinerante-della-salute.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"1662\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Compagnia itinerante della salute\",\"datePublished\":\"2025-02-15T08:53:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/\"},\"wordCount\":185,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Compagnia-itinerante-della-salute.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/\",\"name\":\"Compagnia itinerante della salute - Prossedi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Compagnia-itinerante-della-salute.jpg\",\"datePublished\":\"2025-02-15T08:53:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Compagnia-itinerante-della-salute.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Compagnia-itinerante-della-salute.jpg\",\"width\":1170,\"height\":1662},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/15\\\/compagnia-itinerante-della-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compagnia itinerante della salute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Compagnia itinerante della salute - Prossedi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/","og_locale":"it_IT","og_type":"article","og_title":"Compagnia itinerante della salute - Prossedi","og_description":"La Compagnia Itinerante della Salute fa tappa nelle citt\u00e0 della provincia: prevenzione e screening gratuiti dal 17 al 21 febbraio.&nbsp; Descrizione&nbsp; La\u00a0ASL di Latina\u00a0ha avviato un&#8217;importante campagna di prevenzione con [&hellip;]","og_url":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/","og_site_name":"Prossedi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-02-15T08:53:49+00:00","og_image":[{"width":1170,"height":1662,"url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Compagnia-itinerante-della-salute.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Compagnia itinerante della salute","datePublished":"2025-02-15T08:53:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/"},"wordCount":185,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Compagnia-itinerante-della-salute.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/","url":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/","name":"Compagnia itinerante della salute - Prossedi","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Compagnia-itinerante-della-salute.jpg","datePublished":"2025-02-15T08:53:49+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#primaryimage","url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Compagnia-itinerante-della-salute.jpg","contentUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Compagnia-itinerante-della-salute.jpg","width":1170,"height":1662},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/15\/compagnia-itinerante-della-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/prossedi\/"},{"@type":"ListItem","position":2,"name":"Compagnia itinerante della salute"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/prossedi\/#website","url":"https:\/\/comunicacity.net\/prossedi\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/prossedi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/prossedi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/prossedi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001627"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/comments?post=384"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media\/385"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media?parent=384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/categories?post=384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/tags?post=384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}