{"id":416,"date":"2025-02-26T15:28:58","date_gmt":"2025-02-26T14:28:58","guid":{"rendered":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/"},"modified":"2025-02-26T15:28:58","modified_gmt":"2025-02-26T14:28:58","slug":"avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/","title":{"rendered":"AVVISO PUBBLICO PER L&#8217;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3."},"content":{"rendered":"<p><em>Avviso pubblico riservato ai Comuni del Distretto LT\/3<br \/>\n<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Obiettivo del presente Avviso \u00e8 di garantire un sistema di offerta di strutture altamente qualificate in grado di erogare servizi di qualit\u00e0 rispondenti ai reali bisogni degli ospiti, con prestazioni realizzate ed erogate nel pieno rispetto della loro dignit\u00e0, ed offrendo altres\u00ec una maggiore possibilit\u00e0 di scelta tra le strutture stesse.<\/p>\n<p>La domanda per l&#8217;accreditamento e l&#8217;iscrizione al Registro delle Strutture socio-assistenziali, redatta secondo il modello allegato e corredata dei documenti richiesti come sopra elencati deve essere inviata al Comune di Priverno, Capofila del Distretto Monti Lepini LT\/3, all&#8217;indirizzo pec servizisociali.priverno@pec.it <strong>entro e non oltre il giorno 24\/03\/2025.<\/strong>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.prossedi.lt.it\/wp-content\/uploads\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled.jpg' alt='image'><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_418\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/AVVISO-2025.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/AVVISO-2025.docx', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO 2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_419\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/ALLEGATO-A-ISTANZA-ACCREDITAMENTO-2025.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/ALLEGATO-A-ISTANZA-ACCREDITAMENTO-2025.docx', '_system'); return false;\"><i class='icon attachment'><\/i>ALLEGATO A &#8211; ISTANZA ACCREDITAMENTO 2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_420\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/CONSENSO-TRATTAMENTO-DATI.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/CONSENSO-TRATTAMENTO-DATI.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>CONSENSO TRATTAMENTO DATI<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso pubblico riservato ai Comuni del Distretto LT\/3 &nbsp; Descrizione&nbsp; Obiettivo del presente Avviso \u00e8 di garantire un sistema di offerta di strutture altamente qualificate in grado di erogare servizi [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PUBBLICO PER L&#039;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3. - Prossedi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PUBBLICO PER L&#039;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3. - Prossedi\" \/>\n<meta property=\"og:description\" content=\"Avviso pubblico riservato ai Comuni del Distretto LT\/3 &nbsp; Descrizione&nbsp; Obiettivo del presente Avviso \u00e8 di garantire un sistema di offerta di strutture altamente qualificate in grado di erogare servizi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Prossedi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-26T14:28:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"AVVISO PUBBLICO PER L&#8217;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\\\/3.\",\"datePublished\":\"2025-02-26T14:28:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/\"},\"wordCount\":133,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/\",\"name\":\"AVVISO PUBBLICO PER L'ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\\\/3. - Prossedi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg\",\"datePublished\":\"2025-02-26T14:28:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/02\\\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg\",\"width\":2560,\"height\":1585},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/02\\\/26\\\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PUBBLICO PER L&#8217;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\\\/3.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PUBBLICO PER L'ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3. - Prossedi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PUBBLICO PER L'ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3. - Prossedi","og_description":"Avviso pubblico riservato ai Comuni del Distretto LT\/3 &nbsp; Descrizione&nbsp; Obiettivo del presente Avviso \u00e8 di garantire un sistema di offerta di strutture altamente qualificate in grado di erogare servizi [&hellip;]","og_url":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/","og_site_name":"Prossedi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-02-26T14:28:58+00:00","og_image":[{"width":2560,"height":1585,"url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"AVVISO PUBBLICO PER L&#8217;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3.","datePublished":"2025-02-26T14:28:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/"},"wordCount":133,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/","url":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/","name":"AVVISO PUBBLICO PER L'ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3. - Prossedi","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg","datePublished":"2025-02-26T14:28:58+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#primaryimage","url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg","contentUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/02\/Strutture-residenenziali-e-semiresidenziali-scaled-1.jpg","width":2560,"height":1585},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/02\/26\/avviso-pubblico-per-laccreditamento-delle-strutture-residenziali-e-semiresidenziali-che-erogano-servizi-socioassistenziali-nei-comuni-del-distretto-lt-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/prossedi\/"},{"@type":"ListItem","position":2,"name":"AVVISO PUBBLICO PER L&#8217;ACCREDITAMENTO DELLE STRUTTURE RESIDENZIALI E SEMIRESIDENZIALI CHE EROGANO SERVIZI SOCIOASSISTENZIALI NEI COMUNI DEL DISTRETTO LT\/3."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/prossedi\/#website","url":"https:\/\/comunicacity.net\/prossedi\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/prossedi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/prossedi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/prossedi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001659"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/comments?post=416"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media\/417"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media?parent=416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/categories?post=416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/tags?post=416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}