{"id":511,"date":"2025-04-17T10:57:56","date_gmt":"2025-04-17T08:57:56","guid":{"rendered":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/"},"modified":"2025-04-17T10:57:56","modified_gmt":"2025-04-17T08:57:56","slug":"bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/","title":{"rendered":"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI  IN \u201cFIDA PASCOLO\u201d &#8211; ANNO 2025"},"content":{"rendered":"<p><em>Avviso per i cittadini residenti e gli imprenditori agricoli con sede legale nel Comune di Prossedi nonch\u00e9 i cittadini non residenti e gli imprenditori agricoli la cui stalla \u00e8 ubicata nel territorio comunale<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>La domanda dovr\u00e0 contenere le seguenti informazioni e relativa documentazione:<\/p>\n<ol>\n<li>generalit\u00e0, residenza e requisiti di ordine imprenditoriale agricolo del richiedente;<\/li>\n<li>dichiarazione del numero dei capi \u2013 espressi in UBA \u2013 che si intendono introdurre al pascolo, distinti per specie ed et\u00e0;<\/li>\n<li>dichiarazione di avvenuta applicazione del microchip (bovini ed equini) quale sistema di identificazione, ovvero, in assenza, di equivalente sistema di riconoscimento;<\/li>\n<li>stralcio catastale identificativo del fondo oggetto di richiesta;<\/li>\n<li>copia Registro di stalla (completo di matricole auricolari);<\/li>\n<li>certificato sanitario-veterinario attestante provenienza e requisiti del bestiame;<\/li>\n<li>dichiarazione di impegno al versamento, in soluzione unica, della tariffa di fida pascolo comunicata dal Comune preliminarmente al rilascio dell\u2019atto di concessione;<\/li>\n<li>dichiarazione di impegno al rispetto dei contenuti del presente Regolamento e delle norme regionali, nazionali e comunitarie che sovrintendono alla materia oggetto del presente Regolamento.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Ai sensi dell\u2019art. 3 del regolamento Comunale la concessione in fida pascolo pu\u00f2 essere richiesta anche per pi\u00f9 anni (fino ad un massimo di anni 3).&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.prossedi.lt.it\/wp-content\/uploads\/2025\/04\/News-Avviso_800x440@200.jpg' alt='image'><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_513\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/Avviso-2.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/Avviso-2.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso (2)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso per i cittadini residenti e gli imprenditori agricoli con sede legale nel Comune di Prossedi nonch\u00e9 i cittadini non residenti e gli imprenditori agricoli la cui stalla \u00e8 ubicata [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d - ANNO 2025 - Prossedi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d - ANNO 2025 - Prossedi\" \/>\n<meta property=\"og:description\" content=\"Avviso per i cittadini residenti e gli imprenditori agricoli con sede legale nel Comune di Prossedi nonch\u00e9 i cittadini non residenti e gli imprenditori agricoli la cui stalla \u00e8 ubicata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Prossedi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-17T08:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/News-Avviso_800x440@200-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"787\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d &#8211; ANNO 2025\",\"datePublished\":\"2025-04-17T08:57:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/\"},\"wordCount\":210,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/04\\\/News-Avviso_800x440@200-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/\",\"name\":\"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d - ANNO 2025 - Prossedi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/04\\\/News-Avviso_800x440@200-1.jpg\",\"datePublished\":\"2025-04-17T08:57:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/04\\\/News-Avviso_800x440@200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/04\\\/News-Avviso_800x440@200-1.jpg\",\"width\":787,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/04\\\/17\\\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d &#8211; ANNO 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d - ANNO 2025 - Prossedi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/","og_locale":"it_IT","og_type":"article","og_title":"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d - ANNO 2025 - Prossedi","og_description":"Avviso per i cittadini residenti e gli imprenditori agricoli con sede legale nel Comune di Prossedi nonch\u00e9 i cittadini non residenti e gli imprenditori agricoli la cui stalla \u00e8 ubicata [&hellip;]","og_url":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/","og_site_name":"Prossedi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-17T08:57:56+00:00","og_image":[{"width":787,"height":528,"url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/News-Avviso_800x440@200-1.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d &#8211; ANNO 2025","datePublished":"2025-04-17T08:57:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/"},"wordCount":210,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/News-Avviso_800x440@200-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/","url":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/","name":"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d - ANNO 2025 - Prossedi","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/News-Avviso_800x440@200-1.jpg","datePublished":"2025-04-17T08:57:56+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/News-Avviso_800x440@200-1.jpg","contentUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/04\/News-Avviso_800x440@200-1.jpg","width":787,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/04\/17\/bando-per-la-concessione-di-terreni-comunali-in-fida-pascolo-anno-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/prossedi\/"},{"@type":"ListItem","position":2,"name":"BANDO PER LA CONCESSIONE DI TERRENI COMUNALI IN \u201cFIDA PASCOLO\u201d &#8211; ANNO 2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/prossedi\/#website","url":"https:\/\/comunicacity.net\/prossedi\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/prossedi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/prossedi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/prossedi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001707"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/comments?post=511"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media\/512"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media?parent=511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/categories?post=511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/tags?post=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}