{"id":731,"date":"2025-10-22T16:14:10","date_gmt":"2025-10-22T14:14:10","guid":{"rendered":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/"},"modified":"2025-10-22T16:14:10","modified_gmt":"2025-10-22T14:14:10","slug":"parliamo-di-prevenzione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/","title":{"rendered":"Parliamo di Prevenzione"},"content":{"rendered":"<p><em>Appuntamento di riflessione e di condivisione dedicato alle Donne<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Sabato alle ore 16.00 &#8220;Parliamo di Prevenzione&#8221; presso il Centro Studi;<\/p>\n<p>Domenica invece appuntamento alle ore 9.30 in Piazza Umberto I per la Passeggiata in Rosa nel nostro centro storico&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.prossedi.lt.it\/wp-content\/uploads\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appuntamento di riflessione e di condivisione dedicato alle Donne&nbsp; Descrizione&nbsp; Sabato alle ore 16.00 &#8220;Parliamo di Prevenzione&#8221; presso il Centro Studi; Domenica invece appuntamento alle ore 9.30 in Piazza Umberto [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":732,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parliamo di Prevenzione - Prossedi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parliamo di Prevenzione - Prossedi\" \/>\n<meta property=\"og:description\" content=\"Appuntamento di riflessione e di condivisione dedicato alle Donne&nbsp; Descrizione&nbsp; Sabato alle ore 16.00 &#8220;Parliamo di Prevenzione&#8221; presso il Centro Studi; Domenica invece appuntamento alle ore 9.30 in Piazza Umberto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/\" \/>\n<meta property=\"og:site_name\" content=\"Prossedi\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-22T14:14:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Parliamo di Prevenzione\",\"datePublished\":\"2025-10-22T14:14:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/10\\\/569167133_1140942911563123_4450166309935740907_n.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/\",\"name\":\"Parliamo di Prevenzione - Prossedi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/10\\\/569167133_1140942911563123_4450166309935740907_n.jpg\",\"datePublished\":\"2025-10-22T14:14:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/10\\\/569167133_1140942911563123_4450166309935740907_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/wp-content\\\/uploads\\\/sites\\\/225\\\/2025\\\/10\\\/569167133_1140942911563123_4450166309935740907_n.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/2025\\\/10\\\/22\\\/parliamo-di-prevenzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parliamo di Prevenzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/prossedi\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parliamo di Prevenzione - Prossedi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/","og_locale":"it_IT","og_type":"article","og_title":"Parliamo di Prevenzione - Prossedi","og_description":"Appuntamento di riflessione e di condivisione dedicato alle Donne&nbsp; Descrizione&nbsp; Sabato alle ore 16.00 &#8220;Parliamo di Prevenzione&#8221; presso il Centro Studi; Domenica invece appuntamento alle ore 9.30 in Piazza Umberto [&hellip;]","og_url":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/","og_site_name":"Prossedi","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-22T14:14:10+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Parliamo di Prevenzione","datePublished":"2025-10-22T14:14:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/"},"wordCount":48,"publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/","url":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/","name":"Parliamo di Prevenzione - Prossedi","isPartOf":{"@id":"https:\/\/comunicacity.net\/prossedi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg","datePublished":"2025-10-22T14:14:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#primaryimage","url":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg","contentUrl":"https:\/\/comunicacity.net\/prossedi\/wp-content\/uploads\/sites\/225\/2025\/10\/569167133_1140942911563123_4450166309935740907_n.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/prossedi\/2025\/10\/22\/parliamo-di-prevenzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/prossedi\/"},{"@type":"ListItem","position":2,"name":"Parliamo di Prevenzione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/prossedi\/#website","url":"https:\/\/comunicacity.net\/prossedi\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/prossedi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/prossedi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/prossedi\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/prossedi\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/prossedi\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002004"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/comments?post=731"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/posts\/731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media\/732"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/media?parent=731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/categories?post=731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/prossedi\/wp-json\/wp\/v2\/tags?post=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}