{"id":216,"date":"2017-07-10T13:13:47","date_gmt":"2017-07-10T11:13:47","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=216"},"modified":"2017-07-10T13:13:47","modified_gmt":"2017-07-10T11:13:47","slug":"la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/","title":{"rendered":"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE"},"content":{"rendered":"<p>\u201cDa Frosinone vogliamo far partire un segnale forte, che rimetta al centro il ruolo delle Province rispetto a compiti assolti in passato con ottimi risultati e che necessitano anche in futuro di essere gestiti a livello locale, avendo tra l\u2019altro le professionalit\u00e0 idonee per farlo. Gioved\u00ec prossimo, pertanto, il Consiglio provinciale discuter\u00e0 una proposta di delibera per richiedere alla Regione Lazio, previo emendamento alla legge di stabilit\u00e0 2016, la possibilit\u00e0, sia normativa che finanziaria, di gestire tutti i compiti e le funzioni della Polizia provinciale per la vigilanza e il controllo ittico venatorio. Ringrazio il consigliere Antonio Di Nota per il lavoro preparatorio alla redazione dell\u2019atto\u201d.<\/p>\n<p>E\u2019 quanto afferma il Presidente della Provincia di Frosinone Antonio Pompeo.<\/p>\n<p>\u201cQuando parlo di necessit\u00e0 di ripristinare in pieno i compiti della Polizia provinciale, le funzioni di polizia venatoria ed ittica, di polizia faunistica, di polizia zoofila e di polizia ambientale e amministrativa su materie non fondamentali\u201d.<\/p>\n<p>\u201cIn quest\u2019ultimo periodo \u2013 argomenta il Presidente Pompeo &#8211; l\u2019incertezza normativa e finanziaria \u00a0rispetto a questa materia ha creato solamente difficolt\u00e0 e disagi, sguarnendo il territorio di un presidio importante. Le Province, attraverso il corpo della Polizia provinciale, hanno sempre svolto un compito egregio, fondamentale, apprezzato. Frosinone per esempio soffre il problema della presenza dei cinghiali, che tanti danni sta provocando sia alle culture che alla viabilit\u00e0. E\u2019 essenziale pertanto che la Polizia provinciale, come chiedono le amministrazioni comunali, possa essere pienamente legittimata ad intervenire. Anche perch\u00e9 in questo lasso di tempo i compiti del corpo non sono stati assolti da altri. C\u2019\u00e8 stato soltanto un vuoto\u201d.<\/p>\n<p>\u201cIl vero efficientamento del sistema non significa solamente tagliare, ma razionalizzare e valorizzare ci\u00f2 che funziona. Le Province negli anni hanno dimostrato di saper svolgere benissimo certi compiti: non solo la polizia provinciale, ma l\u2019edilizia scolastica e soprattutto la viabilit\u00e0. E non abbiamo paura di continuare a svolgerli. Chiediamo solo di poterlo fare. Senza le Province che possono sistemare le strade, ammodernare le scuole, tutelare e controllore l\u2019ambiente, ci perde il territorio, la possibilit\u00e0 di un suo sviluppo, la credibilit\u00e0 della politica\u201d.<\/p>\n<p>\u201cPartiamo dalla richiesta di ripristinare le funzioni della Polizia provinciale \u2013 conclude Pompeo &#8211; per poi discutere anche sulle altre materie con la Regione Lazio. In questo percorso, la Provincia di Frosinone auspica anche la condivisione da parte di tutte le Province del Lazio. Allo stesso tempo, continuiamo, attraverso l\u2019Upi e il Presidente Variati, a far sentire la nostra voce sui tavoli nazionali, per le funzioni fondamentali. L\u2019Italia e la buona amministrazione, quella dell\u2019efficienza e degli sprechi eliminati, deve ripartire dai territori. Le Province, messe in condizioni di agire, possono essere il segnale di questa ripartenza\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cDa Frosinone vogliamo far partire un segnale forte, che rimetta al centro il ruolo delle Province rispetto a compiti assolti in passato con ottimi risultati e che necessitano anche in [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":28,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"\u201cDa Frosinone vogliamo far partire un segnale forte, che rimetta al centro il ruolo delle Province rispetto a compiti assolti in passato con ottimi risultati e che necessitano anche in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-10T11:13:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2017\/03\/palazzo-provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"518\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE\",\"datePublished\":\"2017-07-10T11:13:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/\"},\"wordCount\":463,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2017\\\/03\\\/palazzo-provincia.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/\",\"name\":\"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2017\\\/03\\\/palazzo-provincia.jpg\",\"datePublished\":\"2017-07-10T11:13:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2017\\\/03\\\/palazzo-provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2017\\\/03\\\/palazzo-provincia.jpg\",\"width\":777,\"height\":518},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2017\\\/07\\\/10\\\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/","og_locale":"it_IT","og_type":"article","og_title":"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE - Provincia di Frosinone","og_description":"\u201cDa Frosinone vogliamo far partire un segnale forte, che rimetta al centro il ruolo delle Province rispetto a compiti assolti in passato con ottimi risultati e che necessitano anche in [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-07-10T11:13:47+00:00","og_image":[{"width":777,"height":518,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2017\/03\/palazzo-provincia.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE","datePublished":"2017-07-10T11:13:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/"},"wordCount":463,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2017\/03\/palazzo-provincia.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/","name":"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2017\/03\/palazzo-provincia.jpg","datePublished":"2017-07-10T11:13:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2017\/03\/palazzo-provincia.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2017\/03\/palazzo-provincia.jpg","width":777,"height":518},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2017\/07\/10\/la-provincia-di-frosinone-chiede-alla-regione-lazio-la-delega-piena-sul-controllo-ittico-venatorio-della-polizia-provinciale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"LA PROVINCIA DI FROSINONE CHIEDE ALLA REGIONE LAZIO LA DELEGA PIENA SUL CONTROLLO ITTICO VENATORIO DELLA POLIZIA PROVINCIALE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=216"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/216\/revisions"}],"predecessor-version":[{"id":217,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/216\/revisions\/217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/28"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}