{"id":386,"date":"2018-04-05T12:32:22","date_gmt":"2018-04-05T10:32:22","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=386"},"modified":"2018-04-05T12:32:22","modified_gmt":"2018-04-05T10:32:22","slug":"interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/","title":{"rendered":"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi"},"content":{"rendered":"<p>Si comunica che a far data dal giorno 7 aprile 2018 e fino al completamento dei lavori di messa in sicurezza, il settore Viabilit\u00e0 della Provincia di Frosinone ha disposto l\u2019istituzione del senso unico alternato, regolato da semaforo mobile, sulla SSV Sora A\/1, all\u2019altezza dei tratti ricompresi tra il km 53+570 e il km 54+200 (galleria \u201cColle Flonio\u201d) e tra il km 54+600 e il km 55+200 (galleria \u201cSan Francesco\u201d), entrambi nel territorio di Vicalvi.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_387\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/04\/ordinanza.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/04\/ordinanza.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che a far data dal giorno 7 aprile 2018 e fino al completamento dei lavori di messa in sicurezza, il settore Viabilit\u00e0 della Provincia di Frosinone ha disposto [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Si comunica che a far data dal giorno 7 aprile 2018 e fino al completamento dei lavori di messa in sicurezza, il settore Viabilit\u00e0 della Provincia di Frosinone ha disposto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-05T10:32:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/02\/superstrada_galleria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"449\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Interventi sulla SSV Sora A\\\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi\",\"datePublished\":\"2018-04-05T10:32:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/\"},\"wordCount\":91,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/02\\\/superstrada_galleria.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/\",\"name\":\"Interventi sulla SSV Sora A\\\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/02\\\/superstrada_galleria.jpg\",\"datePublished\":\"2018-04-05T10:32:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/02\\\/superstrada_galleria.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/02\\\/superstrada_galleria.jpg\",\"width\":449,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/04\\\/05\\\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interventi sulla SSV Sora A\\\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/","og_locale":"it_IT","og_type":"article","og_title":"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi - Provincia di Frosinone","og_description":"Si comunica che a far data dal giorno 7 aprile 2018 e fino al completamento dei lavori di messa in sicurezza, il settore Viabilit\u00e0 della Provincia di Frosinone ha disposto [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-04-05T10:32:22+00:00","og_image":[{"width":449,"height":800,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/02\/superstrada_galleria.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi","datePublished":"2018-04-05T10:32:22+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/"},"wordCount":91,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/02\/superstrada_galleria.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/","name":"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/02\/superstrada_galleria.jpg","datePublished":"2018-04-05T10:32:22+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/02\/superstrada_galleria.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/02\/superstrada_galleria.jpg","width":449,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/04\/05\/interventi-sulla-ssv-sora-a1-senso-unico-alternato-nelle-gallerie-colle-flonio-e-galleria-san-francesco-nel-territorio-di-vicalvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Interventi sulla SSV Sora A\/1, senso unico alternato nelle gallerie Colle Flonio e galleria San Francesco nel territorio di Vicalvi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=386"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/386\/revisions"}],"predecessor-version":[{"id":388,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/386\/revisions\/388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/366"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}