{"id":437,"date":"2018-11-06T15:00:06","date_gmt":"2018-11-06T14:00:06","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=437"},"modified":"2018-11-06T15:00:06","modified_gmt":"2018-11-06T14:00:06","slug":"pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/","title":{"rendered":"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI"},"content":{"rendered":"<p class=\"yiv2568467187MsoNormal\">Il Presidente della Provincia di Frosinone Antonio Pompeo, accogliendo le richieste del dirigente scolastico dell\u2019Itis Don Morosini, \u00a0ha scritto alla\u00a0Cotral\u00a0Spa, la societ\u00e0 che gestisce il servizio di trasporto pubblico locale, per chiedere una modifica di alcuni orari dei pullman.<\/p>\n<p class=\"yiv2568467187MsoNormal\">In particolare, gli alunni provenienti da Arce e Sora che frequentano l\u2019istituto lamentano l\u2019impossibilit\u00e0 di arrivare in tempo utile per le lezioni, a causa del cambiamento degli orari delle corse e la soppressione del collegamento diretto con Ferentino.<\/p>\n<p class=\"yiv2568467187MsoNormal\">\u201cCon la societ\u00e0 del trasporto pubblico locale\u2013 ha spiegato il Presidente Pompeo \u2013 esiste un dialogo continuo e sono diverse le segnalazioni che abbiamo inoltrato al\u00a0Cotral. Sicuramente anche questa volta, come accaduto in precedenza, la presidente Amalia Colaceci terr\u00e0 in considerazione le richieste che provengono da un ambito di primaria importanza come quello della scuola\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Presidente della Provincia di Frosinone Antonio Pompeo, accogliendo le richieste del dirigente scolastico dell\u2019Itis Don Morosini, \u00a0ha scritto alla\u00a0Cotral\u00a0Spa, la societ\u00e0 che gestisce il servizio di trasporto pubblico locale, [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Il Presidente della Provincia di Frosinone Antonio Pompeo, accogliendo le richieste del dirigente scolastico dell\u2019Itis Don Morosini, \u00a0ha scritto alla\u00a0Cotral\u00a0Spa, la societ\u00e0 che gestisce il servizio di trasporto pubblico locale, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-06T14:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/01\/foto-pompeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI\",\"datePublished\":\"2018-11-06T14:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/\"},\"wordCount\":160,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/01\\\/foto-pompeo.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/\",\"name\":\"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/01\\\/foto-pompeo.jpg\",\"datePublished\":\"2018-11-06T14:00:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/01\\\/foto-pompeo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2018\\\/01\\\/foto-pompeo.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2018\\\/11\\\/06\\\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/","og_locale":"it_IT","og_type":"article","og_title":"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI - Provincia di Frosinone","og_description":"Il Presidente della Provincia di Frosinone Antonio Pompeo, accogliendo le richieste del dirigente scolastico dell\u2019Itis Don Morosini, \u00a0ha scritto alla\u00a0Cotral\u00a0Spa, la societ\u00e0 che gestisce il servizio di trasporto pubblico locale, [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-06T14:00:06+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/01\/foto-pompeo.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI","datePublished":"2018-11-06T14:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/"},"wordCount":160,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/01\/foto-pompeo.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/","name":"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/01\/foto-pompeo.jpg","datePublished":"2018-11-06T14:00:06+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/01\/foto-pompeo.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2018\/01\/foto-pompeo.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2018\/11\/06\/pullman-studenti-di-sora-e-arce-il-presidente-pompeo-scrive-a-cotral-per-adeguare-le-corse-agli-orari-delle-lezioni-dellitis-morosini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"PULLMAN STUDENTI DI SORA E ARCE, Il PRESIDENTE POMPEO SCRIVE A COTRAL PER ADEGUARE LE CORSE AGLI ORARI DELLE LEZIONI DELL\u2019ITIS MOROSINI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=437"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/437\/revisions"}],"predecessor-version":[{"id":438,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/437\/revisions\/438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/357"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}