{"id":587,"date":"2019-07-25T15:35:11","date_gmt":"2019-07-25T13:35:11","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=587"},"modified":"2019-07-25T15:35:12","modified_gmt":"2019-07-25T13:35:12","slug":"provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/","title":{"rendered":"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie"},"content":{"rendered":"<p>Sono iniziati oggi i lavori di rifacimento della\u00a0segnaletica orizzontale\u00a0in corrispondenza dei tratti stradali di competenza provinciale che recentemente sono stati oggetto di interventi di bitumatura. A comunicarlo \u00e8 il Settore Viabilit\u00e0 della Provincia di Frosinone.<\/p>\n<p>Nel dettaglio, verranno realizzate le nuove linee di margine per delimitare la carreggiata stradale e saranno regolamentati e canalizzati tutti gli innesti con le intersecanti strade comunali nei seguenti tratti: S.P. 70 accesso a Casalvieri, in localit\u00e0 Fallena, in territorio di Casalvieri; S.P. 186 Carnello \u2013 Broccostella, tratto finale, in territorio di Broccostella; S.P. 210 Madonna della Stella \u2013 Brocco Alta, fino al nucleo abitato di Brocco Alta, in territorio di Broccostella; S.P. 112 Accesso a Picinisco, localit\u00e0 Borgo Castellone, in territorio di Picinisco.<\/p>\n<p>Inoltre sulla strada provinciale 70 Casalvieri-Atina (loc. Settignano e Ponte Nassetta), nei territori di Atina e Casalvieri e sugli accessi provinciali nord e sud dei tratti nel centro abitato di Gallinaro, oltre agli interventi suddetti, sar\u00e0 realizzata adeguata segnaletica per la limitazione della velocit\u00e0 e per la difesa delle utenze deboli.<\/p>\n<p>Infine, sar\u00e0 realizzata la nuova segnaletica orizzontale (linee di margine, stop, canalizzazioni, ecc.) su tutto il tracciato della strada provinciale103 Settefrati \u2013 Canneto (km. 14+100), particolarmente transitata in questo periodo dai pellegrini e dai turisti diretti al Santuario della Madonna di Canneto. Qui sono in corso anche i lavori di decespugliamento e del taglio dell&#8217;erba, eseguiti con mezzi di propriet\u00e0 provinciale dal personale dipendente.<\/p>\n<p>&#8220;<i>Continua la nostra opera di messa in sicurezza delle arterie di competenza dell&#8217;Ente<\/i>\u00a0\u2013 \u00e8 il commento del presidente della Provincia, Antonio Pompeo, e del consigliere provinciale delegato alla Viabilit\u00e0, Germano Caperna \u2013\u00a0<i>nell&#8217;ottica del miglioramento della viabilit\u00e0 provinciale, con particolare attenzione ai tratti che, nel periodo estivo, registrano un traffico pi\u00f9 elevato per la presenza di turisti e visitatori<\/i>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sono iniziati oggi i lavori di rifacimento della\u00a0segnaletica orizzontale\u00a0in corrispondenza dei tratti stradali di competenza provinciale che recentemente sono stati oggetto di interventi di bitumatura. A comunicarlo \u00e8 il Settore [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Sono iniziati oggi i lavori di rifacimento della\u00a0segnaletica orizzontale\u00a0in corrispondenza dei tratti stradali di competenza provinciale che recentemente sono stati oggetto di interventi di bitumatura. A comunicarlo \u00e8 il Settore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-25T13:35:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-25T13:35:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/05\/lavori-via-leuciana-768x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie\",\"datePublished\":\"2019-07-25T13:35:11+00:00\",\"dateModified\":\"2019-07-25T13:35:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/\"},\"wordCount\":299,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2019\\\/05\\\/lavori-via-leuciana.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/\",\"name\":\"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2019\\\/05\\\/lavori-via-leuciana.jpg\",\"datePublished\":\"2019-07-25T13:35:11+00:00\",\"dateModified\":\"2019-07-25T13:35:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2019\\\/05\\\/lavori-via-leuciana.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2019\\\/05\\\/lavori-via-leuciana.jpg\",\"width\":2976,\"height\":3968,\"caption\":\"sdr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2019\\\/07\\\/25\\\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/","og_locale":"it_IT","og_type":"article","og_title":"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie - Provincia di Frosinone","og_description":"Sono iniziati oggi i lavori di rifacimento della\u00a0segnaletica orizzontale\u00a0in corrispondenza dei tratti stradali di competenza provinciale che recentemente sono stati oggetto di interventi di bitumatura. A comunicarlo \u00e8 il Settore [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-25T13:35:11+00:00","article_modified_time":"2019-07-25T13:35:12+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/05\/lavori-via-leuciana-768x1024.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie","datePublished":"2019-07-25T13:35:11+00:00","dateModified":"2019-07-25T13:35:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/"},"wordCount":299,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/05\/lavori-via-leuciana.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/","name":"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/05\/lavori-via-leuciana.jpg","datePublished":"2019-07-25T13:35:11+00:00","dateModified":"2019-07-25T13:35:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/05\/lavori-via-leuciana.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/05\/lavori-via-leuciana.jpg","width":2976,"height":3968,"caption":"sdr"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2019\/07\/25\/provincia-al-via-i-lavori-di-rifacimento-della-segnaletica-stradale-su-7-arterie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Provincia: al via i lavori di rifacimento della segnaletica stradale su 7 arterie"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=587"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/587\/revisions"}],"predecessor-version":[{"id":588,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/587\/revisions\/588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}