{"id":667,"date":"2020-04-09T12:50:52","date_gmt":"2020-04-09T10:50:52","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=667"},"modified":"2020-04-09T12:50:52","modified_gmt":"2020-04-09T10:50:52","slug":"finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/","title":{"rendered":"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole"},"content":{"rendered":"<p>La Provincia di Frosinone incassa il via libera per altri due finanziamenti richiesti al Miur, relativi all&#8217;annualit\u00e0 2019, destinati a interventi di adeguamento sismico degli edifici scolastici superiori, di competenza dell&#8217;Amministrazione provinciale.<\/p>\n<p>Dopo i contributi ottenuti per l&#8217;anno 2018 per un ammontare di oltre 24 milioni di euro da utilizzare per la riqualificazione e la messa in sicurezza di 8 scuole della provincia, la Direzione regionale Infrastrutture e Mobilit\u00e0 ha comunicato, in questi giorni, la concessione dei due finanziamenti richiesti per l&#8217;anno 2019: quello per l&#8217;I.I.S. &#8216;Vincenzo Gioberti&#8217; di Sora, per 4.417.512,34 euro e quello relativo alla messa in sicurezza della sezione tecnica e professionale per l&#8217;Agricoltura e l&#8217;Ambiente dell&#8217;I.I.S. &#8216;Luigi Angeloni&#8217; di Frosinone.<\/p>\n<p>In questo secondo caso, inoltre, l&#8217;intervento, che consiste nella somma di 2.495.000 euro, consentir\u00e0 lo spostamento, nella nuova sede di via Armando Fabi, dove \u00e8 stato gi\u00e0 trasferito l&#8217;indirizzo Tecnico, delle classi del Professionale, attualmente rimaste nella sede di viale Roma.<\/p>\n<p>A questo punto, all&#8217;appello, mancano soltanto gli ultimi due finanziamenti, relativi all&#8217;annualit\u00e0 2020: quello per il &#8216;Bragaglia&#8217; di Frosinone e quello relativo all&#8217;I.I.S. di Pontecorvo, per un totale di oltre 2.160.000 euro.<\/p>\n<p>&#8220;In un momento di incertezza e paralisi dell&#8217;economia a causa dell&#8217;emergenza Covid-19 \u2013 dicono il presidente della Provincia Pompeo e i due consiglieri delegati a Edilizia scolastica e Pubblica Istruzione, Massimiliano Quadrini e Alessandra Sardellitti \u2013 la notizia di avere fondi a disposizione per rendere pi\u00f9 sicure le nostre scuole \u00e8 anche un segnale di speranza, il desiderio comune che tutti possiamo tornare, quanto prima, alla nostra quotidianit\u00e0 e a frequentare serenamente i luoghi da cui ora siamo lontani. La nostra azione nell&#8217;ambito dell&#8217;edilizia e della sicurezza scolastica \u2013 concludono &#8211; non conosce battute d&#8217;arresto ma rimane, sempre e comunque, tra le priorit\u00e0 della nostra azione amministrativa&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Provincia di Frosinone incassa il via libera per altri due finanziamenti richiesti al Miur, relativi all&#8217;annualit\u00e0 2019, destinati a interventi di adeguamento sismico degli edifici scolastici superiori, di competenza [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"La Provincia di Frosinone incassa il via libera per altri due finanziamenti richiesti al Miur, relativi all&#8217;annualit\u00e0 2019, destinati a interventi di adeguamento sismico degli edifici scolastici superiori, di competenza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-09T10:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/liceo-gioberti-foto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole\",\"datePublished\":\"2020-04-09T10:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/\"},\"wordCount\":301,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/liceo-gioberti-foto.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/\",\"name\":\"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/liceo-gioberti-foto.jpg\",\"datePublished\":\"2020-04-09T10:50:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/liceo-gioberti-foto.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/liceo-gioberti-foto.jpg\",\"width\":680,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/09\\\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/","og_locale":"it_IT","og_type":"article","og_title":"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole - Provincia di Frosinone","og_description":"La Provincia di Frosinone incassa il via libera per altri due finanziamenti richiesti al Miur, relativi all&#8217;annualit\u00e0 2019, destinati a interventi di adeguamento sismico degli edifici scolastici superiori, di competenza [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-09T10:50:52+00:00","og_image":[{"width":680,"height":365,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/liceo-gioberti-foto.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole","datePublished":"2020-04-09T10:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/"},"wordCount":301,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/liceo-gioberti-foto.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/","name":"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/liceo-gioberti-foto.jpg","datePublished":"2020-04-09T10:50:52+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/liceo-gioberti-foto.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/liceo-gioberti-foto.jpg","width":680,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/09\/finanziamenti-per-adeguamento-sismico-degli-edifici-scolastici-provinciali-quasi-7-milioni-di-euro-per-due-scuole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Finanziamenti per adeguamento sismico degli edifici scolastici provinciali: quasi 7 milioni di euro per due scuole"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=667"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/667\/revisions"}],"predecessor-version":[{"id":669,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/667\/revisions\/669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/668"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}