{"id":676,"date":"2020-04-19T17:37:39","date_gmt":"2020-04-19T15:37:39","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=676"},"modified":"2020-04-19T17:37:39","modified_gmt":"2020-04-19T15:37:39","slug":"coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/","title":{"rendered":"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio"},"content":{"rendered":"<p>Una lettera al presidente della Regione Lazio, Nicola Zingaretti, al suo vice Daniele Leodori e all&#8217;assessore regionale alla Sanit\u00e0 D&#8217;Amato. \u00c8 quella inviata oggi dal presidente di Upi Lazio e presidente della Provincia di Frosinone, Antonio Pompeo, per chiedere di effettuare i test seriologici sul coronavirus anche alle forze di polizia provinciali.<\/p>\n<p>Il presidente Pompeo aveva gi\u00e0 inoltrato, nei giorni scorsi, una comunicazione alle organizzazioni sindacali e al presidente di Anci Lazio, Riccardo Varone, dichiarando la sua piena disponibilit\u00e0 al confronto sulla proposta di sottoscrivere un accordo con la Regione per estendere le verifiche epidemiologiche anche sul personale della polizia provinciale. Al quale, dunque, chiede di aggiungere anche quello della polizia provinciale, attraverso un protocollo d&#8217;intesa specifico da sottoscrivere con Upi Lazio.<\/p>\n<p>&#8220;In qualit\u00e0 di presidente della Provincia di Frosinone ma anche come presidente di Upi Lazio \u2013 sottolinea Pompeo \u2013 ho ritenuto assolutamente opportuno chiedere alla Regione di comprendere, nel novero delle forze dell&#8217;ordine da sottoporre ai tamponi per riscontrare la presenza del Covid-19, anche le polizie provinciali, attraverso la sottoscrizione di un protocollo con Upi. In questa emergenza hanno affiancato sin da subito le altre forze dell&#8217;ordine e, sotto il coordinamento di Questura e Prefettura, avviato controlli capillari sul territorio. Con innegabile spirito di servizio e attaccamento alla divisa, le polizie provinciali non si sono risparmiate anche in situazioni molto difficili: cito il caso di Latina, con il Comune di Fondi decretato dal Governo zona rossa. Ma anche nelle verifiche quotidiane, sulle strade e negli esercizi commerciali, il loro supporto \u00e8 stato fondamentale per garantire la sicurezza e il controllo sugli spostamenti&#8221;.<\/p>\n<p>&#8220;Un impegno \u2013 ha continuato Pompeo nella lettera inviata a Zingaretti, Leodori e D&#8217;Amato &#8211; che merita di essere valorizzato e legittimato, dunque, anche tramite l\u2019inserimento della polizia provinciale nel programma di sorveglianza epidemiologica. Senza dimenticare \u2013 ha concluso il presidente di Upi Lazio \u2013 che il Governo ha gi\u00e0 stanziato fondi specifici per le polizie provinciali, riconoscendo loro sacrificio e impegno nella difficile battaglia di contrasto alla diffusione del coronavirus&#8221;.<\/p>\n<p align=\"CENTER\">\n","protected":false},"excerpt":{"rendered":"<p>Una lettera al presidente della Regione Lazio, Nicola Zingaretti, al suo vice Daniele Leodori e all&#8217;assessore regionale alla Sanit\u00e0 D&#8217;Amato. \u00c8 quella inviata oggi dal presidente di Upi Lazio e [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":671,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Una lettera al presidente della Regione Lazio, Nicola Zingaretti, al suo vice Daniele Leodori e all&#8217;assessore regionale alla Sanit\u00e0 D&#8217;Amato. \u00c8 quella inviata oggi dal presidente di Upi Lazio e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-19T15:37:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/polizia-provinciale-e-presidente-Pompeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"777\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio\",\"datePublished\":\"2020-04-19T15:37:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/\"},\"wordCount\":342,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/polizia-provinciale-e-presidente-Pompeo.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/\",\"name\":\"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/polizia-provinciale-e-presidente-Pompeo.jpg\",\"datePublished\":\"2020-04-19T15:37:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/polizia-provinciale-e-presidente-Pompeo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/04\\\/polizia-provinciale-e-presidente-Pompeo.jpg\",\"width\":777,\"height\":532,\"caption\":\"Il presidente della Provincia Antonio Pompeo con la polizia provinciale durante un servizio di controllo per l'emergenza Covid-19\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/19\\\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio - Provincia di Frosinone","og_description":"Una lettera al presidente della Regione Lazio, Nicola Zingaretti, al suo vice Daniele Leodori e all&#8217;assessore regionale alla Sanit\u00e0 D&#8217;Amato. \u00c8 quella inviata oggi dal presidente di Upi Lazio e [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-19T15:37:39+00:00","og_image":[{"width":777,"height":532,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/polizia-provinciale-e-presidente-Pompeo.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio","datePublished":"2020-04-19T15:37:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/"},"wordCount":342,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/polizia-provinciale-e-presidente-Pompeo.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/","name":"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/polizia-provinciale-e-presidente-Pompeo.jpg","datePublished":"2020-04-19T15:37:39+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/polizia-provinciale-e-presidente-Pompeo.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/04\/polizia-provinciale-e-presidente-Pompeo.jpg","width":777,"height":532,"caption":"Il presidente della Provincia Antonio Pompeo con la polizia provinciale durante un servizio di controllo per l'emergenza Covid-19"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/19\/coronavirus-pompeo-chiede-i-test-sierologici-anche-per-le-polizie-provinciali-del-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, Pompeo chiede i test sierologici anche per le polizie provinciali del Lazio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=676"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/676\/revisions"}],"predecessor-version":[{"id":677,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/676\/revisions\/677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/671"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}