{"id":688,"date":"2020-04-30T16:31:00","date_gmt":"2020-04-30T14:31:00","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=688"},"modified":"2020-04-30T16:32:07","modified_gmt":"2020-04-30T14:32:07","slug":"bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/","title":{"rendered":"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#8217;Ente: Provincia centrale anche nella ripartenza"},"content":{"rendered":"<p>Misure, risorse ed effetti di notevole peso quelli contenuti nello schema di bilancio di previsione 2020, adottato ieri dal presidente della Provincia di Frosinone, Antonio Pompeo, con la firma di un decreto che ora sar\u00e0 sottoposto all&#8217;attenzione del Consiglio provinciale.<\/p>\n<p align=\"JUSTIFY\">Un documento contabile in cui, accanto numeri importanti in settori chiave per lo sviluppo dell&#8217;intero territorio, sono contenuti interventi fondamentali che confermano il ruolo centrale di interlocuzione con il Governo e collegamento con i territori, svolto dalle Province in questa fase emergenziale tuttora in corso.<\/p>\n<p align=\"JUSTIFY\">A cominciare dai settori di primaria competenza dell&#8217;ente di Palazzo Jacobucci: viabilit\u00e0 ed edilizia scolastica.<\/p>\n<p>VIABILITA&#8217; E MANUTENZIONE STRADALE<\/p>\n<p>Per quanto concerne la viabilit\u00e0, ammontano a 1.750.000 euro le risorse relative alla manutenzione, alle quali si aggiungono 10.000.000 di euro di trasferimenti dal Ministero delle Infrastrutture e dal Fondo Pluriennale Vincolato. Una cifra complessiva che, dunque, si aggira intorno ai dodici milioni di euro.<\/p>\n<p>Sistemazione del piano viabile, bonifica di tratti dissestati, contrasto al dissesto idrogeologico, nuova segnaletica e barriere di sicurezza: sono queste le priorit\u00e0 che saranno affrontate con la messa in campo degli interventi mirati ad aumentare la qualit\u00e0 della circolazione stradale ma, soprattutto, le condizioni di sicurezza nelle arterie di competenza provinciale.<\/p>\n<p>EDILIZIA SCOLASTICA E ADEGUAMENTO PLESSI ALLE NORME ANTI-COVID<\/p>\n<p>Ancora pi\u00f9 incisiva, anche in considerazione della necessit\u00e0 di adeguare le strutture alle nuove misure che saranno varate dal Governo per il post Coronavirus, l&#8217;azione che la Provincia intende mettere in atto per quanto concerne l&#8217;edilizia scolastica.<\/p>\n<p>Ammontano a oltre 28 milioni di euro le risorse per il settore, suddiviso in manutenzione, ordinaria, straordinaria e contributi erogati dal Miur e dalla Regione Lazio. Questi serviranno per la realizzazione dei lavori di adeguamento strutturale, manutenzione straordinaria, efficientamento energetico, ampliamento e adeguamento alla normativa antincendio.<\/p>\n<p>Tra gli interventi per la ripresa dell&#8217;anno scolastico nella tradizionale modalit\u00e0 della didattica in presenza, l&#8217;Ente dovr\u00e0 prevedere la sistemazione di aule, laboratori e spazi, all&#8217;interno degli edifici, garantendo a docenti e studenti tutti gli standard di sicurezza previsti dalla normativa anti-Covid.<\/p>\n<p>AMBIENTE<\/p>\n<p>Con la ripartenza delle tante attivit\u00e0 produttive, imprese e aziende costrette a fermare lavoro e produzione a causa dell&#8217;emergenza sanitaria, la Provincia intende dare un nuovo impulso alla gestione del rilascio delle autorizzazioni ambientali.<\/p>\n<p>Proprio per questo, nello schema di bilancio, il presidente Pompeo ha inserito un consistente potenziamento delle risorse sul settore ambiente, pari a 700.000 euro, al fine di rispondere in maniera rapida ed efficace ai problemi di A.I.A. e A.U.A. L&#8217;obiettivo non \u00e8 solo quello di garantire un servizio fondamentale per lo sviluppo, ma anche quello di meglio tutelare l&#8217;ecosistema in cui viviamo, per un&#8217;azione di politica green, alla quale si aggiungono ulteriori misure per il potenziamento della raccolta differenziata. Un piano avviato nel 2015 e che si completer\u00e0 nell&#8217;annualit\u00e0 in corso, con risorse stanziate per 6 milioni di euro.<\/p>\n<p>POLIZIA LOCALE DELLA PROVINCIA<\/p>\n<p>Non solo ma anche in considerazione dell&#8217;importante, continuo ed efficace controllo del territorio, messo in campo dagli agenti della Polizia Locale della Provincia di Frosinone nella fase di emergenza sanitaria, in collaborazione con Questura e Prefettura, e considerata la necessit\u00e0 del costante impiego delle unit\u00e0 in servizio in diverse attivit\u00e0 di monitoraggio, verifica e tutela della provincia, lo schema di bilancio prevede lo stanziamento di un milione di euro al fine di rafforzare il corpo della Polizia Locale della Provincia e garantire, cos\u00ec, un&#8217;adeguata disponibilit\u00e0 di agenti e pattuglie.<\/p>\n<p>Sommando, dunque, i settori chiave degli interventi, lo schema di bilancio prevede uno stanziamento di circa 50 milioni di euro: un contributo notevole alla ripartenza del territorio.<\/p>\n<p>&#8220;Questo bilancio \u2013 ha detto il presidente Pompeo \u2013 arriva in un momento tra i pi\u00f9 difficili, anzi certamente il pi\u00f9 difficile dal secondo dopoguerra, non soltanto in termini sanitari, con un&#8217;emergenza senza precedenti che ha gettato l&#8217;intero Paese, e il nostro territorio di conseguenza, in una spirale di paura e paralisi per il rischio contagi, ma ora anche e soprattutto dal punto di vista sociale, economico, occupazionale. Dopo quasi due mesi di sacrifici, attivit\u00e0 ferme, serrande abbassate, cambiamenti delle abitudini di vita del singolo e misure stringenti che hanno costretto tutti noi a fermarci affinch\u00e9 il nostro nemico si fermasse, dobbiamo ripartire, con tutte le incognite, le incertezze e le difficolt\u00e0 che tutto questo ha generato&#8221;.<\/p>\n<p>&#8220;Gli interventi e le risorse stanziati in questo documento contabile, dunque, &#8211; evidenzia Pompeo &#8211; certificano ancora di pi\u00f9 il ruolo centrale e di traino che le Province hanno mostrato e dimostrato in questa fase di emergenza, presenti ai tavoli di confronto con il Governo, le Regioni, l&#8217;Anci, i sindacati e le associazioni di categoria nel dare voce alle istanze e alle richieste dei territori e studiare, insieme, le manovre giuste per ripartire&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-623 size-large\" src=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/11\/presidente-pompeo1-1024x683.png\" alt=\"\" width=\"680\" height=\"454\" srcset=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/11\/presidente-pompeo1-1024x683.png 1024w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/11\/presidente-pompeo1-300x200.png 300w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/11\/presidente-pompeo1-768x512.png 768w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/11\/presidente-pompeo1-680x453.png 680w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2019\/11\/presidente-pompeo1.png 1440w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;Grazie anche al supporto dell\u2019Upi, le Province sono tornate a consolidare, seppure in circostanze drammatiche, il loro ruolo di istituzioni degli investimenti a livello locale e fondamentale anello di congiunzione tra lo Stato e Amministrazioni locali. Una spinta ancora pi\u00f9 forte \u2013 conclude il presidente &#8211; a caricarci di ulteriore e inderogabile responsabilit\u00e0 per fornire un contributo determinante alla sicurezza dei cittadini, alla ripresa degli investimenti, all&#8217;apertura di cantieri per opere e infrastrutture e, pi\u00f9 in generale, alla speranza di nuova crescita e sviluppo integrato dei territori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Misure, risorse ed effetti di notevole peso quelli contenuti nello schema di bilancio di previsione 2020, adottato ieri dal presidente della Provincia di Frosinone, Antonio Pompeo, con la firma di [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tributi-e-finanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#039;Ente: Provincia centrale anche nella ripartenza - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#039;Ente: Provincia centrale anche nella ripartenza - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Misure, risorse ed effetti di notevole peso quelli contenuti nello schema di bilancio di previsione 2020, adottato ieri dal presidente della Provincia di Frosinone, Antonio Pompeo, con la firma di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-30T14:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-30T14:32:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/03\/provincia-frosinone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"593\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#8217;Ente: Provincia centrale anche nella ripartenza\",\"datePublished\":\"2020-04-30T14:31:00+00:00\",\"dateModified\":\"2020-04-30T14:32:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/\"},\"wordCount\":884,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/03\\\/provincia-frosinone.jpg\",\"articleSection\":[\"Tributi e Finanza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/\",\"name\":\"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell'Ente: Provincia centrale anche nella ripartenza - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/03\\\/provincia-frosinone.jpg\",\"datePublished\":\"2020-04-30T14:31:00+00:00\",\"dateModified\":\"2020-04-30T14:32:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/03\\\/provincia-frosinone.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/03\\\/provincia-frosinone.jpg\",\"width\":593,\"height\":443,\"caption\":\"L'Amministrazione provinciale di Frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/04\\\/30\\\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#8217;Ente: Provincia centrale anche nella ripartenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell'Ente: Provincia centrale anche nella ripartenza - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/","og_locale":"it_IT","og_type":"article","og_title":"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell'Ente: Provincia centrale anche nella ripartenza - Provincia di Frosinone","og_description":"Misure, risorse ed effetti di notevole peso quelli contenuti nello schema di bilancio di previsione 2020, adottato ieri dal presidente della Provincia di Frosinone, Antonio Pompeo, con la firma di [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-30T14:31:00+00:00","article_modified_time":"2020-04-30T14:32:07+00:00","og_image":[{"width":593,"height":443,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/03\/provincia-frosinone.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#8217;Ente: Provincia centrale anche nella ripartenza","datePublished":"2020-04-30T14:31:00+00:00","dateModified":"2020-04-30T14:32:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/"},"wordCount":884,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/03\/provincia-frosinone.jpg","articleSection":["Tributi e Finanza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/","name":"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell'Ente: Provincia centrale anche nella ripartenza - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/03\/provincia-frosinone.jpg","datePublished":"2020-04-30T14:31:00+00:00","dateModified":"2020-04-30T14:32:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/03\/provincia-frosinone.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/03\/provincia-frosinone.jpg","width":593,"height":443,"caption":"L'Amministrazione provinciale di Frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/04\/30\/bilancio-strade-scuole-ambiente-e-controllo-del-territorio-nel-piano-per-il-post-covid-19-il-presidente-pompeo-traccia-la-rotta-dellente-provincia-centrale-anche-nella-ripartenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Bilancio: strade, scuole, ambiente e controllo del territorio nel piano per il post-Covid 19. Il presidente Pompeo traccia la rotta dell&#8217;Ente: Provincia centrale anche nella ripartenza"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/688\/revisions"}],"predecessor-version":[{"id":690,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/688\/revisions\/690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/650"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}