{"id":725,"date":"2020-06-23T15:20:06","date_gmt":"2020-06-23T13:20:06","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=725"},"modified":"2020-06-23T15:21:27","modified_gmt":"2020-06-23T13:21:27","slug":"dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/","title":{"rendered":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi"},"content":{"rendered":"<p>Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi e annuncia importanti interventi della Provincia<\/p>\n<p>Il presidente della Provincia di Frosinone, Antonio Pompeo, ha incontrato questa mattina i sindaci dei Comuni ricadenti nella Valle dei Santi, alla luce delle gravi criticit\u00e0 affrontate nelle scorse settimane a causa della violenta ondata di maltempo, che ha provocato ingenti danni e riproposto, in modo drammatico, il problema del dissesto idrogeologico.<\/p>\n<p>Ad accompagnarlo i tecnici della Provincia e il consigliere delegato Germano Caperna.<\/p>\n<p>Il presidente Pompeo si \u00e8 confrontato con i primi cittadini e ascoltato dagli amministratori le istanze e le richieste legate agli interventi pi\u00f9 urgenti di messa in sicurezza di strade e aree che, specie negli ultimi episodi, hanno registrato situazioni particolarmente preoccupanti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-729 aligncenter\" src=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-4-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-4-300x178.jpg 300w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-4-768x456.jpg 768w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-4-680x403.jpg 680w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-4.jpg 799w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Esperia, Castelnuovo Parano, Ausonia, San Giorgio a Liri, Vallemaio, Sant&#8217;Ambrogio sul Garigliano, Sant&#8217;Andrea del Garigliano, Pignataro Interamna, Coreno Ausonio e Sant&#8217;Apollinare: per ciascuno di questi Comuni, dunque, l&#8217;Amministrazione provinciale ha gi\u00e0 predisposto interventi da eseguire, che vanno ad aggiungersi a lavori gi\u00e0 effettuati. Ma il presidente Pompeo ha inteso rassicurare gli amministratori sul sostegno fattivo che l&#8217;Ente di Palazzo Jacobucci metter\u00e0 in campo, oltre a quanto gi\u00e0 fatto. Accanto agli interventi di somma urgenza gi\u00e0 realizzati, infatti, la Provincia stanzier\u00e0 ulteriori 500.000 euro dal bilancio, che serviranno non soltanto per sanare le emergenze causate dal maltempo ma anche per risolvere le criticit\u00e0 presenti nelle aree interessate. Per un totale di 800.000 euro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-727 aligncenter\" src=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-2-300x203.jpg\" alt=\"\" width=\"300\" height=\"203\" srcset=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-2-300x203.jpg 300w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-2-680x460.jpg 680w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-2.jpg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&#8220;Sistemazione dei piani viabili, interventi di messa in sicurezza e manutenzione straordinaria nelle zone che hanno subito movimenti franosi \u2013 afferma Pompeo \u2013 sono solo alcuni degli interventi pianificati dall&#8217;Amministrazione provinciale nella Valle dei Santi che, nei giorni scorsi, \u00e8 stata colpita duramente da un violento nubifragio: pesanti i danni causati che, solo per un caso fortuito, non hanno provocato una tragedia. Oggi ho ascoltato dai colleghi amministratori numerose problematiche riguardanti i loro territori, sui quali c&#8217;\u00e8 impellente necessit\u00e0 di risorse per la messa in sicurezza. Per questo, oltre ai fondi stanziati dalla Regione Lazio e a quelli che la Provincia ha predisposto per interventi di somma urgenza, abbiamo deciso di impegnare altri 500.000 euro che serviranno non solo per affrontare le situazioni di emergenza ma anche per sanare le criticit\u00e0 presenti che finora non \u00e8 stato possibile eliminare&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-728 aligncenter\" src=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-3-300x179.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-3-300x179.jpg 300w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-3-768x459.jpg 768w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-3-680x406.jpg 680w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-3.jpg 777w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&#8220;La Provincia \u2013 ha concluso Pompeo \u2013 svolge da sempre un ruolo importante di controllo e sostegno dei territori, con particolare riguardo al settore della viabilit\u00e0 su cui l&#8217;attenzione dell&#8217;Ente \u00e8 costantemente puntata: dare risposte concrete agli amministratori del territorio significa svolgere appieno la funzione di cui l&#8217;ente provinciale \u00e8 stato investito dalla nostra Costituzione&#8221;.<\/p>\n<p>&#8220;Tempestivit\u00e0 ed efficacia da parte della Provincia \u2013 ha aggiunto il consigliere Caperna \u2013 non solo sulle emergenze ma anche rispetto alle altre problematiche di un&#8217;importante zona del nostro territorio come la valle dei Santi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi e annuncia importanti interventi della Provincia Il presidente della Provincia di Frosinone, Antonio Pompeo, ha incontrato [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":726,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi e annuncia importanti interventi della Provincia Il presidente della Provincia di Frosinone, Antonio Pompeo, ha incontrato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-23T13:20:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T13:21:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"776\" \/>\n\t<meta property=\"og:image:height\" content=\"515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi\",\"datePublished\":\"2020-06-23T13:20:06+00:00\",\"dateModified\":\"2020-06-23T13:21:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/\"},\"wordCount\":467,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/06\\\/Incontro-sindaci-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/\",\"name\":\"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/06\\\/Incontro-sindaci-1.jpg\",\"datePublished\":\"2020-06-23T13:20:06+00:00\",\"dateModified\":\"2020-06-23T13:21:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/06\\\/Incontro-sindaci-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/06\\\/Incontro-sindaci-1.jpg\",\"width\":776,\"height\":515},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/06\\\/23\\\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/","og_locale":"it_IT","og_type":"article","og_title":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi - Provincia di Frosinone","og_description":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi e annuncia importanti interventi della Provincia Il presidente della Provincia di Frosinone, Antonio Pompeo, ha incontrato [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-23T13:20:06+00:00","article_modified_time":"2020-06-23T13:21:27+00:00","og_image":[{"width":776,"height":515,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-1.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi","datePublished":"2020-06-23T13:20:06+00:00","dateModified":"2020-06-23T13:21:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/"},"wordCount":467,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/","name":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-1.jpg","datePublished":"2020-06-23T13:20:06+00:00","dateModified":"2020-06-23T13:21:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-1.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/06\/Incontro-sindaci-1.jpg","width":776,"height":515},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/06\/23\/dissesto-idrogeologico-il-presidente-pompeo-incontra-i-sindaci-dei-comuni-della-valle-dei-santi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Dissesto idrogeologico: il presidente Pompeo incontra i sindaci dei Comuni della Valle dei Santi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=725"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/725\/revisions"}],"predecessor-version":[{"id":732,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/725\/revisions\/732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/726"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}