{"id":761,"date":"2020-09-16T15:22:14","date_gmt":"2020-09-16T13:22:14","guid":{"rendered":"https:\/\/comunicacity.net\/provinciadifrosinone\/?p=761"},"modified":"2020-09-16T15:22:14","modified_gmt":"2020-09-16T13:22:14","slug":"il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/","title":{"rendered":"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone"},"content":{"rendered":"<p>Il presidente della Provincia, Antonio Pompeo, ha ricevuto, questa mattina, la visita istituzionale del nuovo comandante provinciale dei carabinieri di Frosinone, il colonnello Alfonso Pannone. In un clima di cordialit\u00e0, i rappresentanti dell\u2019istituzione provinciale e dell\u2019Arma hanno avuto modo di conoscersi personalmente ma anche di affrontare alcuni temi importanti.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-764 aligncenter\" src=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone3-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" srcset=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone3-300x212.jpg 300w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone3-768x541.jpg 768w, https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone3.jpg 895w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Da parte sua, il presidente Pompeo ha sottolineato l\u2019assoluta valenza della collaborazione istituzionale e rinnovato al comandante Pannone la piena disponibilit\u00e0 dell\u2019Amministrazione provinciale nei confronti dell\u2019Arma e di qualsiasi iniziativa futura nell&#8217;interesse del territorio.<br \/>\nAl termine dell\u2019incontro, il presidente Pompeo ha omaggiato l\u2019ufficiale dei carabinieri del volume \u2018Arte in Provincia\u2019 e dello schizzo prospettico del palazzo provinciale realizzato dall&#8217;architetto Giovanni Jacobucci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il presidente della Provincia, Antonio Pompeo, ha ricevuto, questa mattina, la visita istituzionale del nuovo comandante provinciale dei carabinieri di Frosinone, il colonnello Alfonso Pannone. In un clima di cordialit\u00e0, [&hellip;]<\/p>\n","protected":false},"author":225,"featured_media":763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone - Provincia di Frosinone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone - Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"Il presidente della Provincia, Antonio Pompeo, ha ricevuto, questa mattina, la visita istituzionale del nuovo comandante provinciale dei carabinieri di Frosinone, il colonnello Alfonso Pannone. In un clima di cordialit\u00e0, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/\" \/>\n<meta property=\"og:site_name\" content=\"Provincia di Frosinone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T13:22:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1257\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pompeo Di Fazio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pompeo Di Fazio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/\"},\"author\":{\"name\":\"Pompeo Di Fazio\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"headline\":\"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone\",\"datePublished\":\"2020-09-16T13:22:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/\"},\"wordCount\":133,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/09\\\/Pompeo-Pannone.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/\",\"name\":\"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone - Provincia di Frosinone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/09\\\/Pompeo-Pannone.jpg\",\"datePublished\":\"2020-09-16T13:22:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/09\\\/Pompeo-Pannone.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/wp-content\\\/uploads\\\/sites\\\/71\\\/2020\\\/09\\\/Pompeo-Pannone.jpg\",\"width\":1257,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/2020\\\/09\\\/16\\\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/\",\"name\":\"Provincia di Frosinone\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/#\\\/schema\\\/person\\\/9e42bc315fe7ade676531f011b43072d\",\"name\":\"Pompeo Di Fazio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g\",\"caption\":\"Pompeo Di Fazio\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/provinciadifrosinone\\\/author\\\/pompeodifazio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone - Provincia di Frosinone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/","og_locale":"it_IT","og_type":"article","og_title":"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone - Provincia di Frosinone","og_description":"Il presidente della Provincia, Antonio Pompeo, ha ricevuto, questa mattina, la visita istituzionale del nuovo comandante provinciale dei carabinieri di Frosinone, il colonnello Alfonso Pannone. In un clima di cordialit\u00e0, [&hellip;]","og_url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/","og_site_name":"Provincia di Frosinone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-09-16T13:22:14+00:00","og_image":[{"width":1257,"height":684,"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone.jpg","type":"image\/jpeg"}],"author":"Pompeo Di Fazio","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Pompeo Di Fazio","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/"},"author":{"name":"Pompeo Di Fazio","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"headline":"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone","datePublished":"2020-09-16T13:22:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/"},"wordCount":133,"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/","name":"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone - Provincia di Frosinone","isPartOf":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone.jpg","datePublished":"2020-09-16T13:22:14+00:00","author":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#primaryimage","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone.jpg","contentUrl":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-content\/uploads\/sites\/71\/2020\/09\/Pompeo-Pannone.jpg","width":1257,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/2020\/09\/16\/il-presidente-della-provincia-pompeo-ha-incontrato-il-nuovo-comandante-provinciale-dei-carabinieri-di-frosinone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/provinciadifrosinone\/"},{"@type":"ListItem","position":2,"name":"Il presidente della Provincia Pompeo ha incontrato il nuovo comandante provinciale dei carabinieri di Frosinone"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#website","url":"https:\/\/comunicacity.net\/provinciadifrosinone\/","name":"Provincia di Frosinone","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/provinciadifrosinone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/provinciadifrosinone\/#\/schema\/person\/9e42bc315fe7ade676531f011b43072d","name":"Pompeo Di Fazio","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59c6533b82fc4759371080dc84b58b29e3db1c76c10e98e94a8c33793e1957ee?s=96&d=mm&r=g","caption":"Pompeo Di Fazio"},"url":"https:\/\/comunicacity.net\/provinciadifrosinone\/author\/pompeodifazio\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/users\/225"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/comments?post=761"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/761\/revisions"}],"predecessor-version":[{"id":765,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/posts\/761\/revisions\/765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media\/763"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/media?parent=761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/categories?post=761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/provinciadifrosinone\/wp-json\/wp\/v2\/tags?post=761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}