{"id":281,"date":"2020-06-17T11:07:29","date_gmt":"2020-06-17T09:07:29","guid":{"rendered":"https:\/\/comunicacity.net\/ragogna\/?p=281"},"modified":"2020-06-17T11:07:29","modified_gmt":"2020-06-17T09:07:29","slug":"anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/","title":{"rendered":"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici."},"content":{"rendered":"<p>In allegato i moduli per il servizio mensa e per il trasporto scolastico A.S. 2020\/2021 &#8211; Scuola dell&#8217;Infanzia, Primaria e Secondaria di I\u00b0.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_282\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ragogna\/wp-content\/uploads\/sites\/177\/2020\/06\/Modulo-Servizi-Scolastici-2020.2021-Scuola-Infanzia-e-Primaria.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ragogna\/wp-content\/uploads\/sites\/177\/2020\/06\/Modulo-Servizi-Scolastici-2020.2021-Scuola-Infanzia-e-Primaria.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulo Servizi Scolastici 2020.2021 Scuola Infanzia e Primaria<\/a><\/li>\n<li><a id=\"wpba_attachment_list_283\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/ragogna\/wp-content\/uploads\/sites\/177\/2020\/06\/Modulo-Servizi-Scolastici-2020.2021-Scuola-Secondaria-I\u00b0.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/ragogna\/wp-content\/uploads\/sites\/177\/2020\/06\/Modulo-Servizi-Scolastici-2020.2021-Scuola-Secondaria-I\u00b0.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Modulo Servizi Scolastici 2020.2021 Scuola Secondaria I\u00b0<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In allegato i moduli per il servizio mensa e per il trasporto scolastico A.S. 2020\/2021 &#8211; Scuola dell&#8217;Infanzia, Primaria e Secondaria di I\u00b0. \ud83d\udcce AllegatiModulo Servizi Scolastici 2020.2021 Scuola Infanzia [&hellip;]<\/p>\n","protected":false},"author":310,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-281","post","type-post","status-publish","format-standard","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici. - Ragogna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici. - Ragogna\" \/>\n<meta property=\"og:description\" content=\"In allegato i moduli per il servizio mensa e per il trasporto scolastico A.S. 2020\/2021 &#8211; Scuola dell&#8217;Infanzia, Primaria e Secondaria di I\u00b0. \ud83d\udcce AllegatiModulo Servizi Scolastici 2020.2021 Scuola Infanzia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/\" \/>\n<meta property=\"og:site_name\" content=\"Ragogna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-17T09:07:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/ragogna\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"sindacoragogna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoragogna\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/\"},\"author\":{\"name\":\"sindacoragogna\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#\\\/schema\\\/person\\\/e8ccafe996589d0c458300a11c1799af\"},\"headline\":\"Anno scolastico 2020\\\/2021. Comunicazione relativa ai Servizi Scolastici.\",\"datePublished\":\"2020-06-17T09:07:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/\"},\"wordCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#organization\"},\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/\",\"name\":\"Anno scolastico 2020\\\/2021. Comunicazione relativa ai Servizi Scolastici. - Ragogna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#website\"},\"datePublished\":\"2020-06-17T09:07:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/2020\\\/06\\\/17\\\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anno scolastico 2020\\\/2021. Comunicazione relativa ai Servizi Scolastici.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/\",\"name\":\"Ragogna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/#\\\/schema\\\/person\\\/e8ccafe996589d0c458300a11c1799af\",\"name\":\"sindacoragogna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7b6bbf8ad01ab1a7cc6ad213721ad9a8647e04a2d1bfe789b41b18e0eeaffba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7b6bbf8ad01ab1a7cc6ad213721ad9a8647e04a2d1bfe789b41b18e0eeaffba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7b6bbf8ad01ab1a7cc6ad213721ad9a8647e04a2d1bfe789b41b18e0eeaffba?s=96&d=mm&r=g\",\"caption\":\"sindacoragogna\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/ragogna\\\/author\\\/sindacoragogna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici. - Ragogna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/","og_locale":"it_IT","og_type":"article","og_title":"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici. - Ragogna","og_description":"In allegato i moduli per il servizio mensa e per il trasporto scolastico A.S. 2020\/2021 &#8211; Scuola dell&#8217;Infanzia, Primaria e Secondaria di I\u00b0. \ud83d\udcce AllegatiModulo Servizi Scolastici 2020.2021 Scuola Infanzia [&hellip;]","og_url":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/","og_site_name":"Ragogna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-17T09:07:29+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/ragogna\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/scuola.png","height":600,"width":1200,"type":""}],"author":"sindacoragogna","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoragogna"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/"},"author":{"name":"sindacoragogna","@id":"https:\/\/comunicacity.net\/ragogna\/#\/schema\/person\/e8ccafe996589d0c458300a11c1799af"},"headline":"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici.","datePublished":"2020-06-17T09:07:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/"},"wordCount":30,"publisher":{"@id":"https:\/\/comunicacity.net\/ragogna\/#organization"},"articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/","url":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/","name":"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici. - Ragogna","isPartOf":{"@id":"https:\/\/comunicacity.net\/ragogna\/#website"},"datePublished":"2020-06-17T09:07:29+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/ragogna\/2020\/06\/17\/anno-scolastico-2020-2021-comunicazione-relativa-ai-servizi-scolastici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/ragogna\/"},{"@type":"ListItem","position":2,"name":"Anno scolastico 2020\/2021. Comunicazione relativa ai Servizi Scolastici."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/ragogna\/#website","url":"https:\/\/comunicacity.net\/ragogna\/","name":"Ragogna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/ragogna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/ragogna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/ragogna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/ragogna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/ragogna\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/ragogna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/ragogna\/#\/schema\/person\/e8ccafe996589d0c458300a11c1799af","name":"sindacoragogna","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/c7b6bbf8ad01ab1a7cc6ad213721ad9a8647e04a2d1bfe789b41b18e0eeaffba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7b6bbf8ad01ab1a7cc6ad213721ad9a8647e04a2d1bfe789b41b18e0eeaffba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7b6bbf8ad01ab1a7cc6ad213721ad9a8647e04a2d1bfe789b41b18e0eeaffba?s=96&d=mm&r=g","caption":"sindacoragogna"},"url":"https:\/\/comunicacity.net\/ragogna\/author\/sindacoragogna\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/posts\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/users\/310"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":284,"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/posts\/281\/revisions\/284"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/ragogna\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}