{"id":18948,"date":"2025-10-30T13:51:49","date_gmt":"2025-10-30T12:51:49","guid":{"rendered":"https:\/\/comunicacity.net\/roisan\/?p=18948"},"modified":"2025-10-30T13:52:38","modified_gmt":"2025-10-30T12:52:38","slug":"avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/","title":{"rendered":"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025."},"content":{"rendered":"<p><em>Adozione variante non sostanziale al vigente P.R.G.C..<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><em>Adozione variante non sostanziale al vigente P.R.G.C..<\/em><\/p>\n<p><em>Modifiche norme tecniche di attuazione, per modifiche di alcune sottozone di tipo B, per variazione di vincolo a servizi e per apposizione di vincoli a servizi previsti decaduti.<\/em><\/p>\n<p>Pubblicazione ai sensi dell&#8217;art. 16 della Legge Regionale 11\/1998<\/p>\n<p>La variante non sostanziale al vigente Piano Regolatore Generale Comunale in epigrafe \u00e8 a disposizione di chiunque voglia prenderne visione;<\/p>\n<p>Chiunque abbia interesse, potr\u00e0 presentare osservazioni, ai fini di un apporto collaborativo dei cittadini al perfezionamento della variante al Piano Regolatore Generale Comunale, entro quarantacinque giorni dal giorno successivo alla data della pubblicazione del presente avviso all\u2019albo comunale <em>(30 ottobre 2025).<\/em><\/p>\n<p>Il complessivo tempo utile di quarantacinque giorni \u00e8 perentorio per Legge, pertanto le osservazioni che dovessero pervenire oltre il termine previsto, non saranno prese in considerazione.<\/p>\n<p>Le osservazioni, redatte in carta legale, potranno essere presentate presso la Segreteria Comunale nel normale orario di apertura al pubblico oppure inviate al seguente indirizzo PEC: <a href=\"mailto:protocollo@pec.comune.roisan.ao.it\">protocollo@pec.comune.roisan.ao.it<\/a> e saranno acquisite al particolare protocollo all\u2019uopo istituito.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18956\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/PRCC-2025-00042-A1.zip\" onclick=\"window.open('https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/PRCC-2025-00042-A1.zip', '_system'); return false;\"><i class='icon attachment'><\/i>PRCC-2025-00042-A1<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Adozione variante non sostanziale al vigente P.R.G.C..&nbsp; Descrizione&nbsp; Adozione variante non sostanziale al vigente P.R.G.C.. Modifiche norme tecniche di attuazione, per modifiche di alcune sottozone di tipo B, per variazione [&hellip;]<\/p>\n","protected":false},"author":379,"featured_media":18955,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-18948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025. - Roisan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025. - Roisan\" \/>\n<meta property=\"og:description\" content=\"Adozione variante non sostanziale al vigente P.R.G.C..&nbsp; Descrizione&nbsp; Adozione variante non sostanziale al vigente P.R.G.C.. Modifiche norme tecniche di attuazione, per modifiche di alcune sottozone di tipo B, per variazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/\" \/>\n<meta property=\"og:site_name\" content=\"Roisan\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T12:51:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T12:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/Variante-PRG-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"914\" \/>\n\t<meta property=\"og:image:height\" content=\"897\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comune Roisan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comune Roisan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/\"},\"author\":{\"name\":\"Comune Roisan\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/person\\\/228f95058d4926746af02ddf42ce5d81\"},\"headline\":\"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025.\",\"datePublished\":\"2025-10-30T12:51:49+00:00\",\"dateModified\":\"2025-10-30T12:52:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2025\\\/10\\\/Variante-PRG-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/\",\"name\":\"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025. - Roisan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2025\\\/10\\\/Variante-PRG-1.jpg\",\"datePublished\":\"2025-10-30T12:51:49+00:00\",\"dateModified\":\"2025-10-30T12:52:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2025\\\/10\\\/Variante-PRG-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2025\\\/10\\\/Variante-PRG-1.jpg\",\"width\":914,\"height\":897},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2025\\\/10\\\/30\\\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\",\"name\":\"Roisan\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/Benvenuti-a-Roisan.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/Benvenuti-a-Roisan.jpg\",\"width\":600,\"height\":400,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/person\\\/228f95058d4926746af02ddf42ce5d81\",\"name\":\"Comune Roisan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f4f9d3ace8ad42c4b7a0d0aee1bbd5f999cacc2d6bf170524114426cf2f9e33?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f4f9d3ace8ad42c4b7a0d0aee1bbd5f999cacc2d6bf170524114426cf2f9e33?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8f4f9d3ace8ad42c4b7a0d0aee1bbd5f999cacc2d6bf170524114426cf2f9e33?s=96&d=mm&r=g\",\"caption\":\"Comune Roisan\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/author\\\/comuneroisan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025. - Roisan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025. - Roisan","og_description":"Adozione variante non sostanziale al vigente P.R.G.C..&nbsp; Descrizione&nbsp; Adozione variante non sostanziale al vigente P.R.G.C.. Modifiche norme tecniche di attuazione, per modifiche di alcune sottozone di tipo B, per variazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/","og_site_name":"Roisan","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-30T12:51:49+00:00","article_modified_time":"2025-10-30T12:52:38+00:00","og_image":[{"width":914,"height":897,"url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/Variante-PRG-1.jpg","type":"image\/jpeg"}],"author":"Comune Roisan","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Comune Roisan","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/"},"author":{"name":"Comune Roisan","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/person\/228f95058d4926746af02ddf42ce5d81"},"headline":"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025.","datePublished":"2025-10-30T12:51:49+00:00","dateModified":"2025-10-30T12:52:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/"},"wordCount":211,"publisher":{"@id":"https:\/\/comunicacity.net\/roisan\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/Variante-PRG-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/","url":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/","name":"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025. - Roisan","isPartOf":{"@id":"https:\/\/comunicacity.net\/roisan\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/Variante-PRG-1.jpg","datePublished":"2025-10-30T12:51:49+00:00","dateModified":"2025-10-30T12:52:38+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#primaryimage","url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/Variante-PRG-1.jpg","contentUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2025\/10\/Variante-PRG-1.jpg","width":914,"height":897},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/roisan\/2025\/10\/30\/avviso-di-deposito-degli-atti-costituenti-ladozione-di-variante-non-sostanziale-al-vigente-piano-regolatore-generale-comunale-avvenuta-con-deliberazione-di-consiglio-comunale-n-ro-40-del-16\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/roisan\/"},{"@type":"ListItem","position":2,"name":"AVVISO DI DEPOSITO DEGLI ATTI COSTITUENTI L\u2019ADOZIONE DI VARIANTE NON SOSTANZIALE AL VIGENTE PIANO REGOLATORE GENERALE COMUNALE, AVVENUTA CON DELIBERAZIONE DI CONSIGLIO COMUNALE N.RO 40 DEL 16 OTTOBRE 2025."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/roisan\/#website","url":"https:\/\/comunicacity.net\/roisan\/","name":"Roisan","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/roisan\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/roisan\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/roisan\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/roisan\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Benvenuti-a-Roisan.jpg","contentUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Benvenuti-a-Roisan.jpg","width":600,"height":400,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/person\/228f95058d4926746af02ddf42ce5d81","name":"Comune Roisan","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8f4f9d3ace8ad42c4b7a0d0aee1bbd5f999cacc2d6bf170524114426cf2f9e33?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8f4f9d3ace8ad42c4b7a0d0aee1bbd5f999cacc2d6bf170524114426cf2f9e33?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8f4f9d3ace8ad42c4b7a0d0aee1bbd5f999cacc2d6bf170524114426cf2f9e33?s=96&d=mm&r=g","caption":"Comune Roisan"},"url":"https:\/\/comunicacity.net\/roisan\/author\/comuneroisan\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000019203"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts\/18948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/users\/379"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/comments?post=18948"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts\/18948\/revisions"}],"predecessor-version":[{"id":18950,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts\/18948\/revisions\/18950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/media\/18955"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/media?parent=18948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/categories?post=18948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/tags?post=18948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}