{"id":472,"date":"2021-05-19T20:28:16","date_gmt":"2021-05-19T18:28:16","guid":{"rendered":"https:\/\/comunicacity.net\/roisan\/?p=472"},"modified":"2021-05-19T20:29:34","modified_gmt":"2021-05-19T18:29:34","slug":"avvio-del-cantiere-sulla-sr-per-valpelline","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/","title":{"rendered":"Avvio del cantiere sulla SR per Valpelline"},"content":{"rendered":"<p><strong>Luned\u00ec 24 maggio<\/strong> sar\u00e0 ufficialmente avviato il cantiere per la sistemazione delle due barriere paramassi sulla SR per Valpelline.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-473\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg 1024w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-300x300.jpg 300w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-150x150.jpg 150w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-768x768.jpg 768w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1536x1536.jpg 1536w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985.jpg 1920w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Stando alle indicazioni del servizio geologico i lavori, assegnati alla Ditta Angelini (del consorzio Valle d&#8217;Aosta), prevedono due squadre di lavoro in contemporanea sul campo.<\/p>\n<p>I primi due mesi saranno impiegati per la sistemazione e pulizia delle aree in cui saranno realizzate le due barriere e la loro realizzazione, comprensiva dei pali di fondazione. Un altro mese per la maturazione dei getti e il relativo collaudo.<\/p>\n<p>Terminato questo tempo, il cantiere proseguir\u00e0 con la sistemazione delle aree antistanti le barriere (vi ricordiamo che saranno realizzate a circa 20 metri di distanza dal ciglio della strada, ci sar\u00e0 quindi un ampia fascia di vegetazione su cui intervenire).<\/p>\n<p>Cortestualmente dovrebbero avviarsi i lavori per la sistemazione del manto stradale (altro assessorato, altro cantiere).<\/p>\n<p>Nonostante le due squadre insomma, per il momento restiamo fissi su un tempo di 5 mesi per la sua riapertura&#8230;<\/p>\n<p>Seguiranno aggiornamenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 24 maggio sar\u00e0 ufficialmente avviato il cantiere per la sistemazione delle due barriere paramassi sulla SR per Valpelline. Stando alle indicazioni del servizio geologico i lavori, assegnati alla Ditta [&hellip;]<\/p>\n","protected":false},"author":375,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-472","post","type-post","status-publish","format-standard","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avvio del cantiere sulla SR per Valpelline - Roisan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avvio del cantiere sulla SR per Valpelline - Roisan\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 24 maggio sar\u00e0 ufficialmente avviato il cantiere per la sistemazione delle due barriere paramassi sulla SR per Valpelline. Stando alle indicazioni del servizio geologico i lavori, assegnati alla Ditta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/\" \/>\n<meta property=\"og:site_name\" content=\"Roisan\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T18:28:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-19T18:29:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg\" \/>\n<meta name=\"author\" content=\"Eleonora Pucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eleonora Pucci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/\"},\"author\":{\"name\":\"Eleonora Pucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/person\\\/9434b30316c2aa25f02fd9d531f599bd\"},\"headline\":\"Avvio del cantiere sulla SR per Valpelline\",\"datePublished\":\"2021-05-19T18:28:16+00:00\",\"dateModified\":\"2021-05-19T18:29:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/\"},\"wordCount\":166,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/05\\\/PhotoCollage_20210519_201210985-1024x1024.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/\",\"name\":\"Avvio del cantiere sulla SR per Valpelline - Roisan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/05\\\/PhotoCollage_20210519_201210985-1024x1024.jpg\",\"datePublished\":\"2021-05-19T18:28:16+00:00\",\"dateModified\":\"2021-05-19T18:29:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/05\\\/PhotoCollage_20210519_201210985-1024x1024.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/05\\\/PhotoCollage_20210519_201210985-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/2021\\\/05\\\/19\\\/avvio-del-cantiere-sulla-sr-per-valpelline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avvio del cantiere sulla SR per Valpelline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\",\"name\":\"Roisan\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/Benvenuti-a-Roisan.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/Benvenuti-a-Roisan.jpg\",\"width\":600,\"height\":400,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/person\\\/9434b30316c2aa25f02fd9d531f599bd\",\"name\":\"Eleonora Pucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3832be22b410ac62d552607cddd652d1d4ac95bd010b6d1aa073370ac6988fc7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3832be22b410ac62d552607cddd652d1d4ac95bd010b6d1aa073370ac6988fc7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3832be22b410ac62d552607cddd652d1d4ac95bd010b6d1aa073370ac6988fc7?s=96&d=mm&r=g\",\"caption\":\"Eleonora Pucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/author\\\/epucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avvio del cantiere sulla SR per Valpelline - Roisan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/","og_locale":"it_IT","og_type":"article","og_title":"Avvio del cantiere sulla SR per Valpelline - Roisan","og_description":"Luned\u00ec 24 maggio sar\u00e0 ufficialmente avviato il cantiere per la sistemazione delle due barriere paramassi sulla SR per Valpelline. Stando alle indicazioni del servizio geologico i lavori, assegnati alla Ditta [&hellip;]","og_url":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/","og_site_name":"Roisan","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-05-19T18:28:16+00:00","article_modified_time":"2021-05-19T18:29:34+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg","type":"","width":"","height":""}],"author":"Eleonora Pucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Eleonora Pucci","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/"},"author":{"name":"Eleonora Pucci","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/person\/9434b30316c2aa25f02fd9d531f599bd"},"headline":"Avvio del cantiere sulla SR per Valpelline","datePublished":"2021-05-19T18:28:16+00:00","dateModified":"2021-05-19T18:29:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/"},"wordCount":166,"publisher":{"@id":"https:\/\/comunicacity.net\/roisan\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/","url":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/","name":"Avvio del cantiere sulla SR per Valpelline - Roisan","isPartOf":{"@id":"https:\/\/comunicacity.net\/roisan\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg","datePublished":"2021-05-19T18:28:16+00:00","dateModified":"2021-05-19T18:29:34+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#primaryimage","url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg","contentUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/05\/PhotoCollage_20210519_201210985-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/roisan\/2021\/05\/19\/avvio-del-cantiere-sulla-sr-per-valpelline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/roisan\/"},{"@type":"ListItem","position":2,"name":"Avvio del cantiere sulla SR per Valpelline"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/roisan\/#website","url":"https:\/\/comunicacity.net\/roisan\/","name":"Roisan","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/roisan\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/roisan\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/roisan\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/roisan\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Benvenuti-a-Roisan.jpg","contentUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Benvenuti-a-Roisan.jpg","width":600,"height":400,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/person\/9434b30316c2aa25f02fd9d531f599bd","name":"Eleonora Pucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3832be22b410ac62d552607cddd652d1d4ac95bd010b6d1aa073370ac6988fc7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3832be22b410ac62d552607cddd652d1d4ac95bd010b6d1aa073370ac6988fc7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3832be22b410ac62d552607cddd652d1d4ac95bd010b6d1aa073370ac6988fc7?s=96&d=mm&r=g","caption":"Eleonora Pucci"},"url":"https:\/\/comunicacity.net\/roisan\/author\/epucci\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts\/472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/users\/375"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/comments?post=472"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts\/472\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/posts\/472\/revisions\/475"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/media?parent=472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/categories?post=472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/tags?post=472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}