{"id":101,"date":"2021-03-18T10:29:28","date_gmt":"2021-03-18T09:29:28","guid":{"rendered":"https:\/\/comunicacity.net\/roisan\/?post_type=turismo&#038;p=101"},"modified":"2021-03-18T10:29:28","modified_gmt":"2021-03-18T09:29:28","slug":"storia","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/","title":{"rendered":"Storia"},"content":{"rendered":"<h3>Le origini del territorio<\/h3>\n<p>Le origini del centro abitato sono probabilmente legate alla via che risaliva la sinistra orografica del torrente Buthier e che costituiva un percorso alternativo alla strada da Aosta al Colle del Gran San Bernardo e che esisteva gi\u00e0 prima dell\u2019occupazione romana della Valle d\u2019Aosta.<\/p>\n<p>Verosimilmente fu proprio il desiderio di controllo di essa che indusse i romani ad intervenire sulle popolazioni salasse qui insediate.<\/p>\n<p>Le origini del suo nome \u201cRoisan\u201d, sono da attribuire invece direttamente ai romani poich\u00e9 il termine rientra fra i toponimi con cui si indicavano i fondi agrico\u00adli (il cui proprietario era denominato \u201cRosius\u201d).<\/p>\n<p>L\u2019origine romana di Roisan sembra testimoniata anche dalle iscrizioni funerarie del I\u00b0 e II\u00b0 secolo d.C. sulle lapidi di bardiglio, ora conservate nel museo archeologico regionale, origi\u00adnariamente utilizzate come predelle per questo altare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-102\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/rhins-torre-fortezza-3-300x229-1.jpg\" alt=\"\" width=\"300\" height=\"229\" \/><\/p>\n<p>Con la forma di \u201cRosiano\u201d il nome del paese appare su un documento del <strong>1105<\/strong> che riguardava una permuta di beni tra Burcardo, Arcivescovo di Lione e Anselmo, Vescovo di Aosta.<\/p>\n<hr \/>\n<h3>I mutamenti nella storia<\/h3>\n<p>Il paese ha vissuto tutti i mutamenti istituzionali imposti dalla storia dei secoli.<\/p>\n<p>Per esempio, nel Duecento d.C. il suo territorio, pur essendo molto piccolo, fu suddiviso in due Signorie, l\u2019una che faceva capo al castello di Rhins e dipendeva dal Vescovo di Aosta e l\u2019altra inserita nel mandamento della famiglia Quart.<\/p>\n<p>La Signoria di Rhins non fu mai controllata direttamente dai Vescovi, ma da loro feudatari intermedi, come i Signori di Bosses e di Sarre, per poi passare a sua volta sotto il controllo dei Quart. Fu qui che la massiccia torre-fortezza di Rhins, \u00e8 il simbolo antico della Signoria di Rhins, divenne a sede della giurisdizione vescovile.<\/p>\n<p>Solo alla fine del Settecento le comunit\u00e0 valdostane riuscirono ad affrancarsi dalle servit\u00f9 feudali pagando grosse somme di denaro a riscatto.<\/p>\n<p>Molte famiglie si succedettero per eredit\u00e0 o per infeudazione al governo di Roisan, fino ad arrivare ai Savoia, ai Closellinaz e ai Champvillair.<\/p>\n<p>Jean de Champvillair ad esempio, fu un illustre cittadino di Roisan priore regolare della Collegiata di S. Orso ad Aosta dal 1356 al 1373 che cur\u00f2 il restauro del chiostro, nel modo in cui lo si pu\u00f2 ammirare ancora oggi.<\/p>\n<p>Nel <strong>1715<\/strong> venne aperta sul territorio una delle prime <strong>scuole<\/strong> \u201c<strong>pubbliche<\/strong>\u201d della regione, grazie al Canonico della Cattedrale, Blaise Marquis, il quale nel fondare la rettoria di San Nicola nella chiesa parrocchiale, impegn\u00f2 il titolare a insegnare ai giovani del luogo a leggere e a scrivere.<\/p>\n<p>Una scuola femminile fu aperta poi nel 1815.<\/p>\n<hr \/>\n<h3>Le guerre mondiali<\/h3>\n<p>Alla fine della prima guerra mondiale, fecero ritorno tutti i combattenti per questo motivo Roisan \u00e8 l\u2019unico paese in Italia a non avere un monumento ai caduti. Gli abitanti attribuiscono questo miracolo alla loro devozione nei confronti del santo Vittore, a cui \u00e8 dedicata la chiesa parrocchiale.<\/p>\n<p>E\u2019 altres\u00ec diffusa la credenza che, tra i motivi per cui in occasione di entrambe le guerre mondiali a Roisan non ci siano state vittime, c\u2019\u00e8 un \u201csecret\u201d (una preghiera votiva).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-103\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/photo_2021-02-15_12-33-51-267x300-1.jpg\" alt=\"\" width=\"267\" height=\"300\" \/><\/p>\n<p>Pare infatti che le mogli dei soldati, cucissero dentro un pezzo di stoffa vicino al cuore una preghiera, preghiera che ancora oggi, trova un riparo al sicuro tra le mani dei credenti di Roisan.<\/p>\n<p>Nel periodo fascista il Comune di Roisan fu soppresso dal regime e ricosti\u00adtuito dal presidente del Consiglio della Valle d\u2019Aosta solo alla fine della seconda guerra mondiale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-104\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Roisan-1-e1613133883426-715x1024-1.jpg\" alt=\"\" width=\"715\" height=\"1024\" srcset=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Roisan-1-e1613133883426-715x1024-1.jpg 715w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Roisan-1-e1613133883426-715x1024-1-209x300.jpg 209w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/><\/p>\n<hr \/>\n<h3>Curiosit\u00e0 del territorio<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-105\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/ru-des-vignes-1.jpg\" alt=\"\" width=\"795\" height=\"943\" srcset=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/ru-des-vignes-1.jpg 795w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/ru-des-vignes-1-253x300.jpg 253w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/ru-des-vignes-1-768x911.jpg 768w\" sizes=\"auto, (max-width: 795px) 100vw, 795px\" \/><\/p>\n<p>Presso il cimitero del paese riposano alcune delle persone che hanno fatto la storia cristiana di Roisan, come i Parroci Auguste Apostolo e Jean Bonin, quest\u2019ultimo tenuto in grande considerazio\u00adne dalla Regina Margherita, uomo forte e di grande temperamento.<\/p>\n<p>Altra particolarit\u00e0 del territorio \u00e8 legata ai suoi terreni, privi di sorgenti naturali. Per questo motivo \u00e8 stato sfruttato il livello del suolo, costruendo ruscelli artificiali chiamati Rus che ancora oggi hanno conservato pressoch\u00e9 intatto il tracciato primitivo e su cui si articolano stupende passeggiate.<\/p>\n<p>5 i Rus principali che lo attraversano: il ru Pr\u00e9v\u00f3t del 1300 (cos\u00ec chiamato perch\u00e9 fu costruito dal Prevosto Henry De Quart); il ru Champapom, il ru Mort, il ru Des Vignes e il ru Pompillard (il pi\u00f9 importante, che nasce nel capoluogo di Valpelline e fu costruito agli inizi del XV\u00b0 secolo per iniziativa del canonico Jean De Macynod).<\/p>\n<hr \/>\n<h3>Di qui pass\u00f2 Calvino?<\/h3>\n<p>Una tradizione popolare consolidata vuole che nell\u2019anno 1536 sia transitato per Roisan, accolto da alcuni adepti, Calvino, in fuga verso il Vallese passando per il Col Durand.<\/p>\n<p>Essi Attraversarono il Buthier utilizzando il ponte di Closellinaz (detto successivamente ponte di Calvino). Tale tradizione \u00e8 tuttora priva di ogni attestazione documentaria\u2026.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-106\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Calvino-258x300-1.jpg\" alt=\"\" width=\"258\" height=\"300\" \/><\/p>\n<p>Il ponte purtroppo, in occasione dell\u2019alluvione del 2000, \u00e8 crollato e la sua ricostruzione \u00e8 in corso di studio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-107\" src=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/calvino-2-768x482-1.jpg\" alt=\"\" width=\"768\" height=\"482\" srcset=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/calvino-2-768x482-1.jpg 768w, https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/calvino-2-768x482-1-300x188.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<hr \/>\n<h3>Curiosit\u00e0<\/h3>\n<p>Sul bollettino parrocchiale del 1999, viene pubblicato uno splendido racconto su Roisan. La sua autrice, <strong>Sonia Fiacchi<\/strong>, accompagna il lettore nel nostro territorio, proiettandolo negli occhi di due pellegrini che, nell\u2019anno del giubileo, si trovano a percorrere i suoi sentieri, accompagnati da Boniface di Roisan.<\/p>\n<p>Boniface fu una delle figure pi\u00f9 importanti nelle chiesa Valdostana del trecento, al contempo famoso medico e scienziato alla corte del conte Amedeo VI di Savoia.<\/p>\n<p>L\u2019intero racconto viene qui allegato per gentile concessione dell\u2019autrice stessa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le origini del territorio Le origini del centro abitato sono probabilmente legate alla via che risaliva la sinistra orografica del torrente Buthier e che costituiva un percorso alternativo alla strada [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":8,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-101","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Storia - Roisan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storia - Roisan\" \/>\n<meta property=\"og:description\" content=\"Le origini del territorio Le origini del centro abitato sono probabilmente legate alla via che risaliva la sinistra orografica del torrente Buthier e che costituiva un percorso alternativo alla strada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/\" \/>\n<meta property=\"og:site_name\" content=\"Roisan\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/rhins-torre-fortezza-3-300x229-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/\",\"name\":\"Storia - Roisan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/rhins-torre-fortezza-3-300x229-1.jpg\",\"datePublished\":\"2021-03-18T09:29:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/rhins-torre-fortezza-3-300x229-1.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/rhins-torre-fortezza-3-300x229-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/turismo\\\/storia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Storia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\",\"name\":\"Roisan\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/Benvenuti-a-Roisan.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/wp-content\\\/uploads\\\/sites\\\/197\\\/2021\\\/03\\\/Benvenuti-a-Roisan.jpg\",\"width\":600,\"height\":400,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/roisan\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Storia - Roisan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/","og_locale":"it_IT","og_type":"article","og_title":"Storia - Roisan","og_description":"Le origini del territorio Le origini del centro abitato sono probabilmente legate alla via che risaliva la sinistra orografica del torrente Buthier e che costituiva un percorso alternativo alla strada [&hellip;]","og_url":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/","og_site_name":"Roisan","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/rhins-torre-fortezza-3-300x229-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/","url":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/","name":"Storia - Roisan","isPartOf":{"@id":"https:\/\/comunicacity.net\/roisan\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/rhins-torre-fortezza-3-300x229-1.jpg","datePublished":"2021-03-18T09:29:28+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/roisan\/turismo\/storia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/#primaryimage","url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/rhins-torre-fortezza-3-300x229-1.jpg","contentUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/rhins-torre-fortezza-3-300x229-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/roisan\/turismo\/storia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/roisan\/"},{"@type":"ListItem","position":2,"name":"Storia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/roisan\/#website","url":"https:\/\/comunicacity.net\/roisan\/","name":"Roisan","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/roisan\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/roisan\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/roisan\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/roisan\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Benvenuti-a-Roisan.jpg","contentUrl":"https:\/\/comunicacity.net\/roisan\/wp-content\/uploads\/sites\/197\/2021\/03\/Benvenuti-a-Roisan.jpg","width":600,"height":400,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/roisan\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/turismo\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/types\/turismo"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/media?parent=101"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/roisan\/wp-json\/wp\/v2\/plugin_turismo?post=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}