{"id":24327,"date":"2023-08-16T16:38:00","date_gmt":"2023-08-16T14:38:00","guid":{"rendered":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/"},"modified":"2023-08-16T16:38:00","modified_gmt":"2023-08-16T14:38:00","slug":"abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/","title":{"rendered":"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli"},"content":{"rendered":"<p style=\"text-align: justify\">La lotta contro l&#8217;abbandono illegale dei rifiuti in luoghi pubblici continua ad intensificarsi, con la Polizia Locale che ha annunciato nuove denunce e sanzioni a seguito di ulteriori violazioni.<\/p>\n<p style=\"text-align: justify\">Nei giorni scorsi, proprio il comandante della Polizia Locale aveva richiamato l&#8217;attenzione sui gravi problemi causati dall&#8217;abbandono di rifiuti in un&#8217;area verde pubblica di Sabaudia. Dopo aver inflitto sanzioni amministrative a persone colpevoli di tale reato, le Autorit\u00e0 avevano consigliato a tutti di usufruire del numero verde (800447270) fornito dalla Societ\u00e0 Del Prete per lo smaltimento corretto dei rifiuti non domestici.<\/p>\n<p style=\"text-align: justify\">Ciononostante, il problema dell&#8217;abbandono dei rifiuti non si \u00e8 placato e nuovi casi sono stati rilevati grazie all&#8217;utilizzo del sistema di videosorveglianza.<\/p>\n<p style=\"text-align: justify\">Gli agenti hanno individuato altre 4 persone responsabili di abbandono e sversamento di rifiuti. Per affrontare l\u2019incresciosa situazione, saranno applicate le sanzioni amministrative stabilite dalla specifica Ordinanza del Sindaco.<\/p>\n<p style=\"text-align: justify\">Nello specifico una delle persone coinvolte sar\u00e0 oggetto di denuncia penale per avere abbandonato rifiuti speciali, tra cui residui di vernici e materiali derivanti da lavori edili, all&#8217;interno dell&#8217;area pubblica. La natura degli scarti richiede, infatti, un trattamento speciale e il loro abbandono rappresenta un grave rischio ambientale.<\/p>\n<p style=\"text-align: justify\">Il Comandante della Polizia Locale ha ribadito l&#8217;appello ai cittadini e ai turisti affinch\u00e9 rispettino le norme e non abbandonino rifiuti in maniera illecita, sottolineando ancora una volta l&#8217;importanza di usufruire dei servizi offerti dalla societ\u00e0 Del Prete, che opera secondo il contratto d&#8217;appalto vigente.<\/p>\n<p style=\"text-align: justify\">L&#8217;abbandono dei rifiuti rappresenta una minaccia per l&#8217;ambiente, la salute pubblica e la bellezza naturale di Sabaudia. Le Autorit\u00e0 locali sono determinate a porre fine a questa pratica dannosa e a promuovere un approccio pi\u00f9 responsabile verso la gestione dei rifiuti.<\/p>\n<p style=\"text-align: right\">Addetta stampa<\/p>\n<p style=\"text-align: right\">dott.ssa Tiziana Cardarelli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lotta contro l&#8217;abbandono illegale dei rifiuti in luoghi pubblici continua ad intensificarsi, con la Polizia Locale che ha annunciato nuove denunce e sanzioni a seguito di ulteriori violazioni. Nei [&hellip;]<\/p>\n","protected":false},"author":386,"featured_media":24328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-24327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli - Sabaudia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli - Sabaudia\" \/>\n<meta property=\"og:description\" content=\"La lotta contro l&#8217;abbandono illegale dei rifiuti in luoghi pubblici continua ad intensificarsi, con la Polizia Locale che ha annunciato nuove denunce e sanzioni a seguito di ulteriori violazioni. Nei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabaudia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-16T14:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/foto-videosorvegliaza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"331\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex Lauretti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex Lauretti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/\"},\"author\":{\"name\":\"Alex Lauretti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\"},\"headline\":\"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli\",\"datePublished\":\"2023-08-16T14:38:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/\"},\"wordCount\":291,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/08\\\/foto-videosorvegliaza.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/\",\"name\":\"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli - Sabaudia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/08\\\/foto-videosorvegliaza.jpg\",\"datePublished\":\"2023-08-16T14:38:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/08\\\/foto-videosorvegliaza.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/08\\\/foto-videosorvegliaza.jpg\",\"width\":331,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/08\\\/16\\\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"name\":\"ComunicaCity\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\",\"name\":\"Alex Lauretti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"caption\":\"Alex Lauretti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli - Sabaudia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/","og_locale":"it_IT","og_type":"article","og_title":"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli - Sabaudia","og_description":"La lotta contro l&#8217;abbandono illegale dei rifiuti in luoghi pubblici continua ad intensificarsi, con la Polizia Locale che ha annunciato nuove denunce e sanzioni a seguito di ulteriori violazioni. Nei [&hellip;]","og_url":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/","og_site_name":"Sabaudia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-08-16T14:38:00+00:00","og_image":[{"width":331,"height":286,"url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/foto-videosorvegliaza.jpg","type":"image\/jpeg"}],"author":"Alex Lauretti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Alex Lauretti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/"},"author":{"name":"Alex Lauretti","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5"},"headline":"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli","datePublished":"2023-08-16T14:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/"},"wordCount":291,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/foto-videosorvegliaza.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/","url":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/","name":"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli - Sabaudia","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/foto-videosorvegliaza.jpg","datePublished":"2023-08-16T14:38:00+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#primaryimage","url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/foto-videosorvegliaza.jpg","contentUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/foto-videosorvegliaza.jpg","width":331,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/08\/16\/abbandono-rifiuti-nuove-denunce-e-sanzioni-la-polizia-locale-intensifica-i-controlli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sabaudia\/"},{"@type":"ListItem","position":2,"name":"Abbandono rifiuti, nuove denunce e sanzioni: la Polizia Locale intensifica i controlli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sabaudia\/#website","url":"https:\/\/comunicacity.net\/sabaudia\/","name":"ComunicaCity","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sabaudia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sabaudia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sabaudia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5","name":"Alex Lauretti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","caption":"Alex Lauretti"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"24164"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/users\/386"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/comments?post=24327"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media\/24328"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media?parent=24327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/categories?post=24327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/tags?post=24327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}