{"id":24550,"date":"2023-09-29T11:34:28","date_gmt":"2023-09-29T09:34:28","guid":{"rendered":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/"},"modified":"2023-09-29T11:34:28","modified_gmt":"2023-09-29T09:34:28","slug":"gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/","title":{"rendered":"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola"},"content":{"rendered":"<p style=\"text-align: justify\">La delegazione della citt\u00e0 di Sabaudia ha salutato gli amici di Leros con un caloroso \u201carrivederci\u201d. Il prossimo 28 ottobre, infatti, il presidente dell\u2019Aial, Associazione italiani amici di Leros, raggiunger\u00e0 la citt\u00e0 delle dune insieme al segretario Enzo Bonanno per la presentazione del libro \u2018Portolago e dintorni, il patrimonio storico e architettonico di Leros\u2019.<\/p>\n<p style=\"text-align: justify\">Il volume, curato da Bonanno \u00e8 stato scritto in italiano e tradotto in greco.<\/p>\n<p style=\"text-align: justify\">Intenso come gli altri, l\u2019ultimo giorno sull\u2019isola greca. Nella mattinata di mercoled\u00ec scorso infatti, la delegazione di Sabaudia ha partecipato alla deposizione di corone ai monumenti esistenti in vari punti dell\u2019Isola e dedicati ai soldati italiani, tedeschi, inglesi e greci. Oltre alla delegazione della citt\u00e0 di Sabaudia erano presenti alla cerimonia istituzionale l\u2019Addetto Militare dell\u2019Ambasciata, il Metropolitis, il Vicario dell\u2019Arcidiocesi di Rodi e numerose altre Autorit\u00e0 civili, militari e religiose.<\/p>\n<div id='gallery-1' class='gallery galleryid-24550 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2023\/08\/29\/comitato-gemellaggi-approvato-il-nuovo-regolamento\/whatsapp-image-2023-08-29-at-12-33-13-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/WhatsApp-Image-2023-08-29-at-12.33.13-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2023\/08\/31\/erosione-costiera-il-sindaco-interventi-strutturali-con-regione-capofila\/notizie-ed-informazioni-20-png-8\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/Notizie-ed-informazioni-20-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/09\/05\/oggi-sposi\/notizie-ed-informazioni-21-png-8\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/Notizie-ed-informazioni-21-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/09\/05\/oggi-sposi\/notizie-ed-informazioni-22-png-7\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/08\/Notizie-ed-informazioni-22-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify\">Un lunch \u00e8 seguito al circolo ufficiale di Lakki prima del convegno storico al teatro comunale, sempre nella stessa zona dell\u2019Isola. L\u2019interessante convention ha visto 12 relatori che hanno spiegato, ognuno in base alle proprie competenze, passo passo,<\/p>\n<p style=\"text-align: justify\">la battaglia di Leros, con l\u2019invasione delle truppe tedesche, l\u2019uccisione di oltre 4000 nostri soldati e tantissime altre vittime. Un conflitto durato 50 giorni.<\/p>\n<p style=\"text-align: justify\">La delegazione ha saluto gli amici di Leros a un incontro conviviale prima di imbarcarsi in piena notte, per tornare a casa. Un caloroso \u201carrivederci\u201d, portando con s\u00e9 il ricordo indelebile di questa straordinaria esperienza di condivisione di storie e di tributo alla memoria di coloro che hanno sacrificato tutto per la libert\u00e0.<\/p>\n<p style=\"text-align: right\">Addetta stampa<\/p>\n<p style=\"text-align: right\">d.ssa Tiziana Cardarelli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La delegazione della citt\u00e0 di Sabaudia ha salutato gli amici di Leros con un caloroso \u201carrivederci\u201d. Il prossimo 28 ottobre, infatti, il presidente dell\u2019Aial, Associazione italiani amici di Leros, raggiunger\u00e0 [&hellip;]<\/p>\n","protected":false},"author":386,"featured_media":24551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-24550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola - Sabaudia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola - Sabaudia\" \/>\n<meta property=\"og:description\" content=\"La delegazione della citt\u00e0 di Sabaudia ha salutato gli amici di Leros con un caloroso \u201carrivederci\u201d. Il prossimo 28 ottobre, infatti, il presidente dell\u2019Aial, Associazione italiani amici di Leros, raggiunger\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabaudia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T09:34:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/09\/Leros-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex Lauretti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex Lauretti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/\"},\"author\":{\"name\":\"Alex Lauretti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\"},\"headline\":\"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola\",\"datePublished\":\"2023-09-29T09:34:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/09\\\/Leros-4.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/\",\"name\":\"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola - Sabaudia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/09\\\/Leros-4.jpeg\",\"datePublished\":\"2023-09-29T09:34:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/09\\\/Leros-4.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2023\\\/09\\\/Leros-4.jpeg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/09\\\/29\\\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"name\":\"ComunicaCity\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\",\"name\":\"Alex Lauretti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"caption\":\"Alex Lauretti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola - Sabaudia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/","og_locale":"it_IT","og_type":"article","og_title":"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola - Sabaudia","og_description":"La delegazione della citt\u00e0 di Sabaudia ha salutato gli amici di Leros con un caloroso \u201carrivederci\u201d. Il prossimo 28 ottobre, infatti, il presidente dell\u2019Aial, Associazione italiani amici di Leros, raggiunger\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/","og_site_name":"Sabaudia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-09-29T09:34:28+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/09\/Leros-4.jpeg","type":"image\/jpeg"}],"author":"Alex Lauretti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Alex Lauretti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/"},"author":{"name":"Alex Lauretti","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5"},"headline":"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola","datePublished":"2023-09-29T09:34:28+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/09\/Leros-4.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/","url":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/","name":"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola - Sabaudia","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/09\/Leros-4.jpeg","datePublished":"2023-09-29T09:34:28+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#primaryimage","url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/09\/Leros-4.jpeg","contentUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/09\/Leros-4.jpeg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/09\/29\/gemellaggi-la-delegazione-di-sabaudia-onora-la-memoria-dei-caduti-a-leros-e-saluta-lisola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sabaudia\/"},{"@type":"ListItem","position":2,"name":"Gemellaggi, la Delegazione di Sabaudia onora la memoria dei caduti a Leros e \u2018saluta\u2019 l\u2019isola"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sabaudia\/#website","url":"https:\/\/comunicacity.net\/sabaudia\/","name":"ComunicaCity","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sabaudia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sabaudia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sabaudia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5","name":"Alex Lauretti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","caption":"Alex Lauretti"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"24392"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/users\/386"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/comments?post=24550"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media\/24551"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media?parent=24550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/categories?post=24550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/tags?post=24550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}