{"id":24773,"date":"2023-11-16T17:42:59","date_gmt":"2023-11-16T16:42:59","guid":{"rendered":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/"},"modified":"2023-11-16T18:26:26","modified_gmt":"2023-11-16T17:26:26","slug":"la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/","title":{"rendered":"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni"},"content":{"rendered":"<p style=\"margin-bottom: 0cm;text-align: center\"><b><i><span style=\"font-family: 'Aptos',sans-serif;color: black\">Il sindaco Mosca e una delegazione sono stati ricevuti dalla Giunta<\/span><\/i><\/b><\/p>\n<p style=\"margin-bottom: 0cm;text-align: justify\"><span style=\"font-family: 'Aptos',sans-serif;color: black\">Cinque gruppi elettrogeni da 7kW e uno da 14 kW, \u00e8 la donazione della Citt\u00e0 di Sabaudia al Comune di Lugo dopo l&#8217;alluvione. Una dotazione di estrema importanza che sar\u00e0 ora a disposizione dell&#8217;Area Servizi al Territorio del Comune e che potr\u00e0 essere utilizzata anche per operazioni di Protezione Civile. Il gesto di grande generosit\u00e0 e solidariet\u00e0 del comune laziale \u00e8 stato suggellato dalla visita a Lugo del sindaco Alberto Mosca, accompagnato da una delegazione. Sindaco e collaboratori hanno visitato il Museo Baracca, guidati dal direttore Massimiliano Fabbri, e il Teatro Rossini, accompagnati dal direttore Giovanni Barberini che ha spiegato i danni dovuti all&#8217;alluvione.<\/span><\/p>\n<p style=\"margin-bottom: 0cm;text-align: justify\"><span style=\"font-family: 'Aptos',sans-serif;color: black\">Nel primo pomeriggio, infine, incontro con il sindaco Davide Ranalli e la Giunta per un ringraziamento corale a nome della citt\u00e0. Al sindaco Mosca \u00e8 stata consegnata un&#8217;acquaforte raffigurante la Rocca di Lugo e due libri della mostra \u201cCome un&#8217;onda, come in volo [1923-2023] 100 cavalli per Francesco Baracca\u201d<\/span><\/p>\n<p style=\"margin-bottom: 0cm;text-align: justify\"><span style=\"font-family: 'Aptos',sans-serif;color: black\">Il sindaco Mosca dichiara: \u201cCome primo cittadino della Citt\u00e0 di Sabaudia sono particolarmente grato e onorato per l\u2019invito che il collega di Lugo Davide Ranalli ha voluto rivolgermi per ringraziare me e la mia Amministrazione della donazione di sei gruppi elettrogeni di continuit\u00e0 che abbiamo effettuato per dare il nostro tangibile contributo all\u2019indomani dell\u2019alluvione che ha colpito i vostri territori. Sono fermamente convinto che la solidariet\u00e0 sia una delle linee guida fondamentali che devono ispirare costantemente l\u2019azione amministrativa dei Sindaci, specie quelli dei centri pi\u00f9 piccoli\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-family: 'Aptos',sans-serif;color: black\">\u201cGrazie sindaco Mosca, grazie Sabaudia \u2013 aggiunge il sindaco Ranalli -. In questi mesi abbiamo composto una mappa d&#8217;Italia\u00a0straordinaria grazie alla solidariet\u00e0 di Comuni, Associazioni fino ai singoli cittadini. Questo bene comune \u00e8 un segno di grande vitalit\u00e0 delle comunit\u00e0 e ci permette anche di costruire rapporti destinati a durare\u201d.<\/span><\/p>\n<p class=\"xelementtoproof\" style=\"text-align: right\"><span style=\"font-family: 'Aptos',sans-serif;color: black\">Ufficio Stampa del Comune di Lugo<\/span><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Il sindaco Mosca e una delegazione sono stati ricevuti dalla Giunta Cinque gruppi elettrogeni da 7kW e uno da 14 kW, \u00e8 la donazione della Citt\u00e0 di Sabaudia al Comune [&hellip;]<\/p>\n","protected":false},"author":386,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-24773","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni - Sabaudia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni - Sabaudia\" \/>\n<meta property=\"og:description\" content=\"Il sindaco Mosca e una delegazione sono stati ricevuti dalla Giunta Cinque gruppi elettrogeni da 7kW e uno da 14 kW, \u00e8 la donazione della Citt\u00e0 di Sabaudia al Comune [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabaudia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T16:42:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T17:26:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/11\/WhatsApp-Image-2023-11-16-at-17.31.22-5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex Lauretti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex Lauretti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/\"},\"author\":{\"name\":\"Alex Lauretti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\"},\"headline\":\"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni\",\"datePublished\":\"2023-11-16T16:42:59+00:00\",\"dateModified\":\"2023-11-16T17:26:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/\"},\"wordCount\":317,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/\",\"name\":\"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni - Sabaudia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\"},\"datePublished\":\"2023-11-16T16:42:59+00:00\",\"dateModified\":\"2023-11-16T17:26:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2023\\\/11\\\/16\\\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"name\":\"ComunicaCity\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\",\"name\":\"Alex Lauretti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"caption\":\"Alex Lauretti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni - Sabaudia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/","og_locale":"it_IT","og_type":"article","og_title":"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni - Sabaudia","og_description":"Il sindaco Mosca e una delegazione sono stati ricevuti dalla Giunta Cinque gruppi elettrogeni da 7kW e uno da 14 kW, \u00e8 la donazione della Citt\u00e0 di Sabaudia al Comune [&hellip;]","og_url":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/","og_site_name":"Sabaudia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-11-16T16:42:59+00:00","article_modified_time":"2023-11-16T17:26:26+00:00","og_image":[{"width":1600,"height":1580,"url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2023\/11\/WhatsApp-Image-2023-11-16-at-17.31.22-5.jpeg","type":"image\/jpeg"}],"author":"Alex Lauretti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Alex Lauretti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/"},"author":{"name":"Alex Lauretti","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5"},"headline":"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni","datePublished":"2023-11-16T16:42:59+00:00","dateModified":"2023-11-16T17:26:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/"},"wordCount":317,"publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/","url":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/","name":"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni - Sabaudia","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#website"},"datePublished":"2023-11-16T16:42:59+00:00","dateModified":"2023-11-16T17:26:26+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sabaudia\/2023\/11\/16\/la-citta-di-sabaudia-dona-a-lugo-sei-gruppi-elettrogeni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sabaudia\/"},{"@type":"ListItem","position":2,"name":"La Citt\u00e0 di Sabaudia dona a Lugo sei gruppi elettrogeni"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sabaudia\/#website","url":"https:\/\/comunicacity.net\/sabaudia\/","name":"ComunicaCity","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sabaudia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sabaudia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sabaudia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5","name":"Alex Lauretti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","caption":"Alex Lauretti"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"24614"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/users\/386"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/comments?post=24773"}],"version-history":[{"count":8,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24773\/revisions"}],"predecessor-version":[{"id":24789,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/24773\/revisions\/24789"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media?parent=24773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/categories?post=24773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/tags?post=24773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}