{"id":25224,"date":"2024-03-13T14:02:24","date_gmt":"2024-03-13T13:02:24","guid":{"rendered":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/"},"modified":"2024-03-13T14:06:38","modified_gmt":"2024-03-13T13:06:38","slug":"la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/","title":{"rendered":"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia"},"content":{"rendered":"<p><strong><em>In collegamento da remoto il racconto emozionante del fratello del Giudice assassinato ai ragazzi del Giulio Cesare<\/em><\/strong><\/p>\n<p style=\"text-align: justify\">La lettura del libro \u201cLa casa di Paolo\u201d ha portato i ragazzi dell\u2019Istituto Omnicomprensivo Giulio Celare di Sabaudia a un approfondimento sulla mafia e sul tragico massacro di Giovanni Falcone e Paolo Borsellino. Questa mattina nell\u2019aula consiliare gli studenti, alla presenza del vice sindaco Secci, dell\u2019assessore Schintu, della dirigente scolastica Zannella e delle insegnanti, hanno avuto l&#8217;opportunit\u00e0 di ascoltare Salvatore Borsellino, il fratello di Paolo, in un collegamento emozionante.<\/p>\n<p style=\"text-align: justify\">Salvatore Borsellino ha condiviso ricordi dell&#8217;infanzia trascorsa con suo fratello Paolo, per poi affrontare il doloroso ricordo della strage di via d\u2019Amelio.<\/p>\n<p style=\"text-align: justify\">&#8220;Paolo \u00e8 stato massacrato insieme alla sua scorta a soli 52 anni. Avevano sogni e speranze, tutte spezzate &#8211; ha raccontato il fratello di Paolo Borsellino -. Nostra madre mi ha sempre raccomandato di ricordare i nomi della scorta. Coloro che hanno perso la vita insieme a Paolo sono Agostino, Claudio, Vincenzo, Francesca e Eddy. Loro erano i cinque della scorta rimasti massacrati e che hanno sacrificato la loro vita insieme a mio fratello\u201d.<\/p>\n<p style=\"text-align: justify\">La perdita di Paolo Borsellino e Giovanni Falcone, assassinati a distanza di soli 57 giorni l&#8217;uno dall&#8217;altro, ha lasciato un vuoto incolmabile. &#8220;Uccidere Falcone senza Borsellino non sarebbe servito a nulla. Paolo sapeva che sarebbe stato ucciso anche lui e ha vissuto gli ultimi giorni della sua vita sempre a testa alta&#8221;.<\/p>\n<p style=\"text-align: justify\">Salvatore Borsellino dopo la laurea in ingegneria ha lasciato Palermo e si \u00e8 trasferito a Milano. &#8220;Sono trascorsi 50 anni da quando ho lasciato Palermo &#8211; ha aggiunto -. Ma quando mio fratello \u00e8 stato ucciso, sono tornato a Palermo e il cuore mi si \u00e8 stretto ripassando per le strade dove giocavamo da bambini&#8221;.<\/p>\n<div id='gallery-1' class='gallery galleryid-25224 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/borsellino-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/borsellino-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/borsellino-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/borsellino-5\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/borsellino-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify\">La farmacia della famiglia Borsellino \u00e8 diventata un luogo di accoglienza per i giovani. Nella casa di Paolo, volontari dedicati aiutano i bambini provenienti da famiglie disagiate a studiare, offrendo loro non solo istruzione, ma anche amore e supporto.<\/p>\n<p style=\"text-align: justify\">&#8220;La casa di Paolo vive grazie al volontariato &#8211; ha spiegato Salvatore Borsellino -. Non abbiamo molto spazio, ma ospitiamo famiglie bisognose. Anche se abbiamo solo una stanza con otto letti a castello, facciamo del nostro meglio per aiutare queste famiglie.&#8221;<\/p>\n<p style=\"text-align: justify\">Le domande degli studenti rivolte a Salvatore Borsellino riflettono l&#8217;impatto del libro, di Sara Loffredi e Marco Lillo, e la sua importanza nel trasmettere la storia e il messaggio di speranza che La casa di Paolo rappresenta. La prefazione scritta proprio da Salvatore ha reso il volume ancora pi\u00f9 significativo, rendendo possibile questo prezioso momento di condivisione e riflessione.<\/p>\n<p style=\"text-align: justify\">A ringraziare Salvatore Borsellino per la disponibilit\u00e0 dimostrata, il giornalista Marco Lillo, la dirigente scolastica Miriana Zannella e i docenti per l\u2019encomiabile iniziativa, sono stati il vice sindaco Giovanni Secci e l\u2019assessore alla Pubblica Istruzione Pia Schintu.<\/p>\n<p style=\"text-align: right\">Addetta stampa<\/p>\n<p style=\"text-align: right\">d.ssa Tiziana Cardarelli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In collegamento da remoto il racconto emozionante del fratello del Giudice assassinato ai ragazzi del Giulio Cesare La lettura del libro \u201cLa casa di Paolo\u201d ha portato i ragazzi dell\u2019Istituto [&hellip;]<\/p>\n","protected":false},"author":386,"featured_media":25227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-25224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia - Sabaudia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia - Sabaudia\" \/>\n<meta property=\"og:description\" content=\"In collegamento da remoto il racconto emozionante del fratello del Giudice assassinato ai ragazzi del Giulio Cesare La lettura del libro \u201cLa casa di Paolo\u201d ha portato i ragazzi dell\u2019Istituto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabaudia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-13T13:02:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-13T13:06:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex Lauretti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex Lauretti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/\"},\"author\":{\"name\":\"Alex Lauretti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\"},\"headline\":\"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia\",\"datePublished\":\"2024-03-13T13:02:24+00:00\",\"dateModified\":\"2024-03-13T13:06:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Borsellino-3-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/\",\"name\":\"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia - Sabaudia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Borsellino-3-1.jpg\",\"datePublished\":\"2024-03-13T13:02:24+00:00\",\"dateModified\":\"2024-03-13T13:06:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Borsellino-3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Borsellino-3-1.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/13\\\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"name\":\"ComunicaCity\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\",\"name\":\"Alex Lauretti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"caption\":\"Alex Lauretti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia - Sabaudia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/","og_locale":"it_IT","og_type":"article","og_title":"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia - Sabaudia","og_description":"In collegamento da remoto il racconto emozionante del fratello del Giudice assassinato ai ragazzi del Giulio Cesare La lettura del libro \u201cLa casa di Paolo\u201d ha portato i ragazzi dell\u2019Istituto [&hellip;]","og_url":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/","og_site_name":"Sabaudia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-03-13T13:02:24+00:00","article_modified_time":"2024-03-13T13:06:38+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-1.jpg","type":"image\/jpeg"}],"author":"Alex Lauretti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Alex Lauretti","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/"},"author":{"name":"Alex Lauretti","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5"},"headline":"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia","datePublished":"2024-03-13T13:02:24+00:00","dateModified":"2024-03-13T13:06:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/"},"wordCount":484,"publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/","url":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/","name":"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia - Sabaudia","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-1.jpg","datePublished":"2024-03-13T13:02:24+00:00","dateModified":"2024-03-13T13:06:38+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#primaryimage","url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Borsellino-3-1.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/13\/la-casa-di-paolo-un-simbolo-di-speranza-e-resistenza-contro-la-mafia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sabaudia\/"},{"@type":"ListItem","position":2,"name":"La Casa di Paolo, un simbolo di speranza e resistenza contro la mafia"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sabaudia\/#website","url":"https:\/\/comunicacity.net\/sabaudia\/","name":"ComunicaCity","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sabaudia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sabaudia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sabaudia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5","name":"Alex Lauretti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","caption":"Alex Lauretti"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"25073"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/25224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/users\/386"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/comments?post=25224"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/25224\/revisions"}],"predecessor-version":[{"id":25233,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/25224\/revisions\/25233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media\/25227"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media?parent=25224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/categories?post=25224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/tags?post=25224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}