{"id":25296,"date":"2024-03-22T12:20:44","date_gmt":"2024-03-22T11:20:44","guid":{"rendered":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/"},"modified":"2024-03-22T12:22:57","modified_gmt":"2024-03-22T11:22:57","slug":"amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/","title":{"rendered":"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica"},"content":{"rendered":"<p>I quattrocentomila euro di fondi PNRR destinati alla realizzazione della pista di atletica all\u2019interno dell&#8217;Arena del mare, nell&#8217;area ex Spes, non sono stati persi dall\u2019attuale Amministrazione, bens\u00ec sono stati persi dall\u2019Amministrazione Gervasi che ha dimostrato inefficienza nella gestione dei progetti afferenti ai fondi PNRR. Nonostante la partecipazione al bando, con un mero progetto di fattibilit\u00e0, l\u2019ex Amministrazione non ha conseguito la necessaria approvazione del Piano Particolareggiato, n\u00e9 avviato la procedura di variante puntuale per opera pubblica, alternativamente necessarie per l&#8217;approvazione del progetto e l\u2019assegnazione definitiva dei fondi, portando inevitabilmente alla perdita dell&#8217;intera somma.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25139 alignright\" src=\"https:\/\/www.comune.sabaudia.lt.it\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-22-at-11.08.52-1-188x300.jpeg\" alt=\"\" width=\"188\" height=\"300\" \/><\/p>\n<p>Tale negligenza ha impedito all&#8217;attuale Amministrazione di procedere con il progetto esecutivo, attesa l&#8217;impossibilit\u00e0 di rispettare i tempi richiesti dalla norma per la contrattualizzazione dell\u2019opera da realizzare entro e non oltre il 30 luglio 2023.<\/p>\n<p>Ciononostante, per non lasciare abbandonata l&#8217;Arena del mare, ridotta ormai ad uno stato di degrado, l&#8217;Amministrazione Mosca, in particolare l\u2019Assessorato al Turismo, ha dato indirizzo agli Uffici preposti, di indire una gara finalizzata ad affidare l&#8217;area in concessione a qualificata societ\u00e0 per la gestione di eventi di rilevanza nazionale. L\u2019unica ad aver risposto al bando \u00e8 stata la Ventidieci srl.<\/p>\n<p>\u201cQuesta societ\u00e0 si occuper\u00e0 di realizzare serate con artisti nazionali e internazionali per la prossima stagione estiva a Sabaudia, restituendo cos\u00ec alla citt\u00e0 delle dune il suo antico splendore, gi\u00e0 ottenuto negli anni dal 2002 al 2012, quando gi\u00e0 assessore al turismo, lanciai l\u2019idea dell\u2019Arena del Mare, palcoscenico divenuto di importanza nazionale, che ha visto l\u2019esibizione di otre 70 artisti. Per citarne qualcuno, Fiorello, Gigi Proietti, I Pooh, Aldo, Giovanni e Giacomo, Gianna Nannini, Litfiba, Renzo Arbore, Massimo Ranieri.<\/p>\n<p>Grazie alla mossa decisa e tempestiva dell\u2019attuale Amministrazione comunale, Sabaudia potr\u00e0 tornare ad essere un punto di <img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-25140 alignright\" src=\"https:\/\/www.comune.sabaudia.lt.it\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-22-at-11.08.52-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" \/> riferimento per eventi di prestigio, contribuendo anche cos\u00ec al suo sviluppo culturale e turistico, con il conseguente ritorno economico.<\/p>\n<p>Pertanto il maldestro tentativo da parte dei consiglieri comunali di minoranza, appartenenti al gruppo \u201cCittadini per Sabaudia\u201d, di incolpare la nostra Amministrazione di avere volutamente rinunciato a realizzare la pista di atletica in favore di altro, lo rispediamo al mittente\u201d.<\/p>\n<p>Cos\u00ec il vicesindaco e assessore al Turismo e alla Cultura, Giovanni Secci.<\/p>\n<p style=\"text-align: right\">Addetta Stampa<\/p>\n<p style=\"text-align: right\">d.ssa Tiziana Cardarelli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I quattrocentomila euro di fondi PNRR destinati alla realizzazione della pista di atletica all\u2019interno dell&#8217;Arena del mare, nell&#8217;area ex Spes, non sono stati persi dall\u2019attuale Amministrazione, bens\u00ec sono stati persi [&hellip;]<\/p>\n","protected":false},"author":386,"featured_media":25299,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-25296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica - Sabaudia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica - Sabaudia\" \/>\n<meta property=\"og:description\" content=\"I quattrocentomila euro di fondi PNRR destinati alla realizzazione della pista di atletica all\u2019interno dell&#8217;Arena del mare, nell&#8217;area ex Spes, non sono stati persi dall\u2019attuale Amministrazione, bens\u00ec sono stati persi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/\" \/>\n<meta property=\"og:site_name\" content=\"Sabaudia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-22T11:20:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T11:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Notizie-ed-informazioni-24.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alex Lauretti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex Lauretti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/\"},\"author\":{\"name\":\"Alex Lauretti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\"},\"headline\":\"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica\",\"datePublished\":\"2024-03-22T11:20:44+00:00\",\"dateModified\":\"2024-03-22T11:22:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/\"},\"wordCount\":386,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Notizie-ed-informazioni-25.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/\",\"name\":\"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica - Sabaudia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Notizie-ed-informazioni-25.png\",\"datePublished\":\"2024-03-22T11:20:44+00:00\",\"dateModified\":\"2024-03-22T11:22:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Notizie-ed-informazioni-25.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/wp-content\\\/uploads\\\/sites\\\/202\\\/2024\\\/03\\\/Notizie-ed-informazioni-25.png\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/2024\\\/03\\\/22\\\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"name\":\"ComunicaCity\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sabaudia\\\/#\\\/schema\\\/person\\\/34972c9159bd2aafc4f313788b91e0b5\",\"name\":\"Alex Lauretti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g\",\"caption\":\"Alex Lauretti\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica - Sabaudia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/","og_locale":"it_IT","og_type":"article","og_title":"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica - Sabaudia","og_description":"I quattrocentomila euro di fondi PNRR destinati alla realizzazione della pista di atletica all\u2019interno dell&#8217;Arena del mare, nell&#8217;area ex Spes, non sono stati persi dall\u2019attuale Amministrazione, bens\u00ec sono stati persi [&hellip;]","og_url":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/","og_site_name":"Sabaudia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-03-22T11:20:44+00:00","article_modified_time":"2024-03-22T11:22:57+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Notizie-ed-informazioni-24.png","type":"image\/png"}],"author":"Alex Lauretti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Alex Lauretti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/"},"author":{"name":"Alex Lauretti","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5"},"headline":"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica","datePublished":"2024-03-22T11:20:44+00:00","dateModified":"2024-03-22T11:22:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/"},"wordCount":386,"publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Notizie-ed-informazioni-25.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/","url":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/","name":"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica - Sabaudia","isPartOf":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Notizie-ed-informazioni-25.png","datePublished":"2024-03-22T11:20:44+00:00","dateModified":"2024-03-22T11:22:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#primaryimage","url":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Notizie-ed-informazioni-25.png","contentUrl":"https:\/\/comunicacity.net\/sabaudia\/wp-content\/uploads\/sites\/202\/2024\/03\/Notizie-ed-informazioni-25.png","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sabaudia\/2024\/03\/22\/amministrazione-gervasi-non-presenta-la-variante-puntuale-al-piano-e-perde-i-fondi-pnrr-per-la-pista-di-atletica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sabaudia\/"},{"@type":"ListItem","position":2,"name":"Amministrazione Gervasi non presenta la variante puntuale al piano e perde i fondi PNRR per la pista di atletica"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sabaudia\/#website","url":"https:\/\/comunicacity.net\/sabaudia\/","name":"ComunicaCity","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sabaudia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sabaudia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sabaudia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sabaudia\/#\/schema\/person\/34972c9159bd2aafc4f313788b91e0b5","name":"Alex Lauretti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39449a1e438782f6545b40ba5d25f2c1be007b482ca550fe217067bf3385647d?s=96&d=mm&r=g","caption":"Alex Lauretti"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"25138"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/25296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/users\/386"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/comments?post=25296"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/25296\/revisions"}],"predecessor-version":[{"id":25298,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/posts\/25296\/revisions\/25298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media\/25299"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/media?parent=25296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/categories?post=25296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sabaudia\/wp-json\/wp\/v2\/tags?post=25296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}