{"id":444,"date":"2018-11-06T13:51:56","date_gmt":"2018-11-06T12:51:56","guid":{"rendered":"https:\/\/comunicacity.net\/sambuci\/?p=444"},"modified":"2018-11-06T13:51:56","modified_gmt":"2018-11-06T12:51:56","slug":"presentazione-sportello-antiviolenza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/","title":{"rendered":"Presentazione Sportello Antiviolenza"},"content":{"rendered":"<p>Sabato 10 Novembre alle ore 16 presso Castello Theodoli di Sambuci verr\u00e0 presentato lo sportello per l\u2019accoglienza di donne vittime di violenza.<br \/>\nUn importante traguardo per il nostro Comune che ospiter\u00e0 questo sportello, utile per tutte le donne della Valle del Giovenzano e non solo! Si invita tutta la cittadinanza a partecipare.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato 10 Novembre alle ore 16 presso Castello Theodoli di Sambuci verr\u00e0 presentato lo sportello per l\u2019accoglienza di donne vittime di violenza. Un importante traguardo per il nostro Comune che [&hellip;]<\/p>\n","protected":false},"author":219,"featured_media":445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentazione Sportello Antiviolenza - Sambuci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentazione Sportello Antiviolenza - Sambuci\" \/>\n<meta property=\"og:description\" content=\"Sabato 10 Novembre alle ore 16 presso Castello Theodoli di Sambuci verr\u00e0 presentato lo sportello per l\u2019accoglienza di donne vittime di violenza. Un importante traguardo per il nostro Comune che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Sambuci\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-06T12:51:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sambuci\/wp-content\/uploads\/sites\/95\/2018\/11\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"1030\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pfratini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pfratini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/\"},\"author\":{\"name\":\"pfratini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/#\\\/schema\\\/person\\\/d21ec1c145185c17123fe8328f9fb557\"},\"headline\":\"Presentazione Sportello Antiviolenza\",\"datePublished\":\"2018-11-06T12:51:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/\"},\"wordCount\":54,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/wp-content\\\/uploads\\\/sites\\\/95\\\/2018\\\/11\\\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/\",\"name\":\"Presentazione Sportello Antiviolenza - Sambuci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/wp-content\\\/uploads\\\/sites\\\/95\\\/2018\\\/11\\\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg\",\"datePublished\":\"2018-11-06T12:51:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/#\\\/schema\\\/person\\\/d21ec1c145185c17123fe8328f9fb557\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/wp-content\\\/uploads\\\/sites\\\/95\\\/2018\\\/11\\\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/wp-content\\\/uploads\\\/sites\\\/95\\\/2018\\\/11\\\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg\",\"width\":730,\"height\":1030},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/2018\\\/11\\\/06\\\/presentazione-sportello-antiviolenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentazione Sportello Antiviolenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/\",\"name\":\"Sambuci\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/#\\\/schema\\\/person\\\/d21ec1c145185c17123fe8328f9fb557\",\"name\":\"pfratini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3132be6b5bc948d8164a3b4000233a413849fc6f2ff89e63d50ecdac21f5f990?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3132be6b5bc948d8164a3b4000233a413849fc6f2ff89e63d50ecdac21f5f990?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3132be6b5bc948d8164a3b4000233a413849fc6f2ff89e63d50ecdac21f5f990?s=96&d=mm&r=g\",\"caption\":\"pfratini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sambuci\\\/author\\\/pfratini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentazione Sportello Antiviolenza - Sambuci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/","og_locale":"it_IT","og_type":"article","og_title":"Presentazione Sportello Antiviolenza - Sambuci","og_description":"Sabato 10 Novembre alle ore 16 presso Castello Theodoli di Sambuci verr\u00e0 presentato lo sportello per l\u2019accoglienza di donne vittime di violenza. Un importante traguardo per il nostro Comune che [&hellip;]","og_url":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/","og_site_name":"Sambuci","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-06T12:51:56+00:00","og_image":[{"width":730,"height":1030,"url":"https:\/\/comunicacity.net\/sambuci\/wp-content\/uploads\/sites\/95\/2018\/11\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg","type":"image\/jpeg"}],"author":"pfratini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pfratini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/"},"author":{"name":"pfratini","@id":"https:\/\/comunicacity.net\/sambuci\/#\/schema\/person\/d21ec1c145185c17123fe8328f9fb557"},"headline":"Presentazione Sportello Antiviolenza","datePublished":"2018-11-06T12:51:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/"},"wordCount":54,"image":{"@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sambuci\/wp-content\/uploads\/sites\/95\/2018\/11\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/","url":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/","name":"Presentazione Sportello Antiviolenza - Sambuci","isPartOf":{"@id":"https:\/\/comunicacity.net\/sambuci\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sambuci\/wp-content\/uploads\/sites\/95\/2018\/11\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg","datePublished":"2018-11-06T12:51:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/sambuci\/#\/schema\/person\/d21ec1c145185c17123fe8328f9fb557"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#primaryimage","url":"https:\/\/comunicacity.net\/sambuci\/wp-content\/uploads\/sites\/95\/2018\/11\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg","contentUrl":"https:\/\/comunicacity.net\/sambuci\/wp-content\/uploads\/sites\/95\/2018\/11\/1B03CE17-C28A-4C1C-B29C-BA8D8BF49B92.jpeg","width":730,"height":1030},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sambuci\/2018\/11\/06\/presentazione-sportello-antiviolenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sambuci\/"},{"@type":"ListItem","position":2,"name":"Presentazione Sportello Antiviolenza"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sambuci\/#website","url":"https:\/\/comunicacity.net\/sambuci\/","name":"Sambuci","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sambuci\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sambuci\/#\/schema\/person\/d21ec1c145185c17123fe8328f9fb557","name":"pfratini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3132be6b5bc948d8164a3b4000233a413849fc6f2ff89e63d50ecdac21f5f990?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3132be6b5bc948d8164a3b4000233a413849fc6f2ff89e63d50ecdac21f5f990?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3132be6b5bc948d8164a3b4000233a413849fc6f2ff89e63d50ecdac21f5f990?s=96&d=mm&r=g","caption":"pfratini"},"url":"https:\/\/comunicacity.net\/sambuci\/author\/pfratini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/users\/219"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"predecessor-version":[{"id":446,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/posts\/444\/revisions\/446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/media\/445"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sambuci\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}