{"id":16314,"date":"2022-08-16T11:25:16","date_gmt":"2022-08-16T09:25:16","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/"},"modified":"2022-08-16T12:33:38","modified_gmt":"2022-08-16T10:33:38","slug":"16314","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/","title":{"rendered":"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione."},"content":{"rendered":"<p>Si informano gli elettori affetti da gravissime infermit\u00e0, tali che l&#8217;allontanamento dall&#8217;abitazione in cui dimorano risulti impossibile, anche con l&#8217;ausilio dei servizi di cui all&#8217;articolo 29 della legge 5 febbraio 1992, n. 104, e gli elettori affetti da gravi infermit\u00e0 che si trovino in condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali tali da impedirne l&#8217;allontanamento dall&#8217;abitazione in cui dimorano, sono ammessi al voto nelle predette dimore.<br \/>\nI suddetti elettori devono far pervenire, in un periodo compreso <strong>tra il giorno 16 agosto al giorno 5 settembre 2022<\/strong>, al sindaco del comune nelle cui liste elettorali sono iscritti:<br \/>\na) una dichiarazione in carta libera, attestante la volont\u00e0 di esprimere il voto presso l&#8217;abitazione in cui dimorano e recante l&#8217;indicazione dell&#8217;indirizzo completo di questa;<br \/>\nb) un certificato, rilasciato dal funzionario medico, designato dai competenti organi dell&#8217;azienda sanitaria locale, in data non anteriore al quarantacinquesimo giorno antecedente la data della votazione, che attesti l&#8217;esistenza delle condizioni di infermit\u00e0 di cui al comma 1, con prognosi di almeno sessanta giorni decorrenti dalla data di rilascio del certificato, ovvero delle condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali.<\/p>\n<p>vedi manifesto e modello istanza in calce<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16324\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/MANIFESTO-Voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/MANIFESTO-Voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MANIFESTO Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#039;allontanamento dall&#039;abitazione<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16325\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/MODULO-Voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/MODULO-Voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MODULO Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#039;allontanamento dall&#039;abitazione<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informano gli elettori affetti da gravissime infermit\u00e0, tali che l&#8217;allontanamento dall&#8217;abitazione in cui dimorano risulti impossibile, anche con l&#8217;ausilio dei servizi di cui all&#8217;articolo 29 della legge 5 febbraio [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":16323,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#039;allontanamento dall&#039;abitazione. - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#039;allontanamento dall&#039;abitazione. - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Si informano gli elettori affetti da gravissime infermit\u00e0, tali che l&#8217;allontanamento dall&#8217;abitazione in cui dimorano risulti impossibile, anche con l&#8217;ausilio dei servizi di cui all&#8217;articolo 29 della legge 5 febbraio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T09:25:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-16T10:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/Immagine-in-evidenza-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Elezioni Politiche del 25\\\/09\\\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione.\",\"datePublished\":\"2022-08-16T09:25:16+00:00\",\"dateModified\":\"2022-08-16T10:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/\"},\"wordCount\":200,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Immagine-in-evidenza-1-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/\",\"name\":\"Elezioni Politiche del 25\\\/09\\\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione. - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Immagine-in-evidenza-1-1.jpg\",\"datePublished\":\"2022-08-16T09:25:16+00:00\",\"dateModified\":\"2022-08-16T10:33:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Immagine-in-evidenza-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/08\\\/Immagine-in-evidenza-1-1.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2022\\\/08\\\/16\\\/16314\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni Politiche del 25\\\/09\\\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione. - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione. - San Giorgio a Liri","og_description":"Si informano gli elettori affetti da gravissime infermit\u00e0, tali che l&#8217;allontanamento dall&#8217;abitazione in cui dimorano risulti impossibile, anche con l&#8217;ausilio dei servizi di cui all&#8217;articolo 29 della legge 5 febbraio [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/","og_site_name":"San Giorgio a Liri","article_published_time":"2022-08-16T09:25:16+00:00","article_modified_time":"2022-08-16T10:33:38+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/Immagine-in-evidenza-1-1.jpg","type":"image\/jpeg"}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione.","datePublished":"2022-08-16T09:25:16+00:00","dateModified":"2022-08-16T10:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/"},"wordCount":200,"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/Immagine-in-evidenza-1-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/","name":"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione. - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/Immagine-in-evidenza-1-1.jpg","datePublished":"2022-08-16T09:25:16+00:00","dateModified":"2022-08-16T10:33:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#primaryimage","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/Immagine-in-evidenza-1-1.jpg","contentUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2022\/08\/Immagine-in-evidenza-1-1.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2022\/08\/16\/16314\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Elezioni Politiche del 25\/09\/2022: Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"16380"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=16314"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16314\/revisions"}],"predecessor-version":[{"id":16322,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16314\/revisions\/16322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media\/16323"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=16314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=16314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=16314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}