{"id":16649,"date":"2024-04-30T11:57:50","date_gmt":"2024-04-30T09:57:50","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/"},"modified":"2024-04-30T17:13:19","modified_gmt":"2024-04-30T15:13:19","slug":"voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/","title":{"rendered":"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione"},"content":{"rendered":"<p><em>In un significativo avanzamento verso l&#8217;inclusivit\u00e0 e l&#8217;accessibilit\u00e0 delle pratiche elettorali, \u00e8 stata introdotta una nuova misura legislativa che permette il voto domiciliare per gli elettori affetti da infermit\u00e0.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Gli elettori interessati dovranno far prevenire la prescritta dichiarazione entro il giorno 20 Maggio 2024 utilizzando preferibilmente l&#8217;apposito modulo da ritirare presso l&#8217;ufficio elettorale comunale o scaricabile dalla sezione Allegati.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16655\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2024\/04\/MANIFESTO-1-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2024\/04\/MANIFESTO-1-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MANIFESTO<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16656\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2024\/04\/DOMANDA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2024\/04\/DOMANDA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>DOMANDA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In un significativo avanzamento verso l&#8217;inclusivit\u00e0 e l&#8217;accessibilit\u00e0 delle pratiche elettorali, \u00e8 stata introdotta una nuova misura legislativa che permette il voto domiciliare per gli elettori affetti da infermit\u00e0.&nbsp; Descrizione&nbsp; [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16649","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#039;allontanamento dall&#039;abitazione - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#039;allontanamento dall&#039;abitazione - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"In un significativo avanzamento verso l&#8217;inclusivit\u00e0 e l&#8217;accessibilit\u00e0 delle pratiche elettorali, \u00e8 stata introdotta una nuova misura legislativa che permette il voto domiciliare per gli elettori affetti da infermit\u00e0.&nbsp; Descrizione&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T09:57:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T15:13:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione\",\"datePublished\":\"2024-04-30T09:57:50+00:00\",\"dateModified\":\"2024-04-30T15:13:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/\"},\"wordCount\":72,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/\",\"name\":\"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2024-04-30T09:57:50+00:00\",\"dateModified\":\"2024-04-30T15:13:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2024\\\/04\\\/30\\\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/","og_locale":"it_IT","og_type":"article","og_title":"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione - San Giorgio a Liri","og_description":"In un significativo avanzamento verso l&#8217;inclusivit\u00e0 e l&#8217;accessibilit\u00e0 delle pratiche elettorali, \u00e8 stata introdotta una nuova misura legislativa che permette il voto domiciliare per gli elettori affetti da infermit\u00e0.&nbsp; Descrizione&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/","og_site_name":"San Giorgio a Liri","article_published_time":"2024-04-30T09:57:50+00:00","article_modified_time":"2024-04-30T15:13:19+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione","datePublished":"2024-04-30T09:57:50+00:00","dateModified":"2024-04-30T15:13:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/"},"wordCount":72,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/","name":"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l'allontanamento dall'abitazione - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2024-04-30T09:57:50+00:00","dateModified":"2024-04-30T15:13:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2024\/04\/30\/voto-domiciliare-per-elettori-affetti-da-infermita-che-ne-rendano-impossibile-lallontanamento-dallabitazione-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Voto domiciliare per elettori affetti da infermit\u00e0 che ne rendano impossibile l&#8217;allontanamento dall&#8217;abitazione"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000016827"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=16649"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16649\/revisions"}],"predecessor-version":[{"id":16652,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16649\/revisions\/16652"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=16649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=16649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=16649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}