{"id":16838,"date":"2025-04-24T12:38:26","date_gmt":"2025-04-24T10:38:26","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/"},"modified":"2025-04-29T13:58:33","modified_gmt":"2025-04-29T11:58:33","slug":"referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/","title":{"rendered":"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi"},"content":{"rendered":"<p><em>Consultazioni Referendarie di domenica 8 e luned\u00ec 9 giugno 2025 &#8211; Manifesto di Convocazione dei Comizi.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<h2><span style=\"font-size: 16px\">IL SINDACO<\/span><\/h2>\n<div class=\"richtext-wrapper lora\">\n<p>Visto l\u2019articolo 75 della Costituzione;<br \/>\nVista la legge 25 maggio 1970, n. 352, recante \u00abNorme sui referendum previsti dalla Costituzione e sulla iniziativa legislativa del popolo\u00bb, e successive modificazioni;<br \/>\nVisto l\u2019articolo 11 del testo unico delle leggi recanti norme per la elezione della Camera dei deputati, approvato con decreto del Presidente della Repubblica 30 marzo 1957, n. 361, e successive modificazioni, applicabile ai referendum a norma dell\u2019articolo 50 della legge 25 maggio 1970, n. 352;<br \/>\nVisto l\u2019articolo 1, comma 1, del decreto-legge 19 marzo 2025, n. 27, recante \u00abDisposizioni urgenti per le consultazioni elettorali e referendarie dell\u2019anno 2025\u00bb;<\/p>\n<p>RENDE NOTO<\/p>\n<p>che, con decreti del Presidente della Repubblica del 31 marzo 2025, pubblicati nella Gazzetta Ufficiale &#8211; Serie Generale n. 75 del 31 marzo 2025, sono stati convocati per i giorni di domenica 8 giugno e di luned\u00ec 9 giugno 2025 i comizi per lo svolgimento dei seguenti referendum popolari:<\/p>\n<ul>\n<li><strong>REFERENDUM POPOLARE N. 1<\/strong><br \/>\nContratto di lavoro a tutele crescenti \u2013\u00a0Disciplina dei licenziamenti illegittimi: Abrogazione<\/li>\n<li><strong>REFERENDUM POPOLARE N. 2<\/strong><br \/>\nPiccole imprese \u2013\u00a0Licenziamenti e relativa indennit\u00e0: Abrogazione parziale<\/li>\n<li><strong>REFERENDUM POPOLARE N. 3<\/strong><br \/>\nAbrogazione parziale di norme in materia\u00a0di apposizione di termine al contratto di lavoro subordinato,\u00a0durata massima e condizioni per proroghe e rinnovi<\/li>\n<li><strong>REFERENDUM POPOLARE N. 4<\/strong><br \/>\nEsclusione della responsabilit\u00e0 solidale\u00a0del committente, dell\u2019appaltatore e del subappaltatore\u00a0per infortuni subiti dal lavoratore dipendente\u00a0di impresa appaltatrice o subappaltatrice,\u00a0come conseguenza dei rischi specifici propri dell\u2019attivit\u00e0\u00a0delle imprese appaltatrici o subappaltatrici: Abrogazione<\/li>\n<li><strong>REFERENDUM POPOLARE N. 5<\/strong><br \/>\nCittadinanza italiana: Dimezzamento da 10 a 5 anni\u00a0dei tempi di residenza legale in Italia\u00a0dello straniero maggiorenne extracomunitario\u00a0per la richiesta di concessione della cittadinanza italiana<\/li>\n<\/ul>\n<p>* * *<\/p>\n<p>Le operazioni preliminari degli uffici di sezione cominceranno alle ore 16 di sabato 7 giugno 2025.<br \/>\nLA VOTAZIONE SI SVOLGER\u00c0 NEI GIORNI DI<\/p>\n<p>DOMENICA 8 GIUGNO 2025, DALLE ORE 7 ALLE ORE 23, e di<\/p>\n<p>LUNED\u00cc 9 GIUGNO 2025, DALLE ORE 7 ALLE ORE 15.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16856\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/Manifesto-di-convocazione-dei-comizi-modello-n.-1REF.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/Manifesto-di-convocazione-dei-comizi-modello-n.-1REF.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Manifesto di convocazione dei comizi (modello n. 1REF)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Consultazioni Referendarie di domenica 8 e luned\u00ec 9 giugno 2025 &#8211; Manifesto di Convocazione dei Comizi.&nbsp; Descrizione&nbsp; IL SINDACO Visto l\u2019articolo 75 della Costituzione; Vista la legge 25 maggio 1970, [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":16855,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Consultazioni Referendarie di domenica 8 e luned\u00ec 9 giugno 2025 &#8211; Manifesto di Convocazione dei Comizi.&nbsp; Descrizione&nbsp; IL SINDACO Visto l\u2019articolo 75 della Costituzione; Vista la legge 25 maggio 1970, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-24T10:38:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T11:58:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/referendum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"885\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi\",\"datePublished\":\"2025-04-24T10:38:26+00:00\",\"dateModified\":\"2025-04-29T11:58:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/\"},\"wordCount\":309,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/referendum.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/\",\"name\":\"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/referendum.jpg\",\"datePublished\":\"2025-04-24T10:38:26+00:00\",\"dateModified\":\"2025-04-29T11:58:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/referendum.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/04\\\/referendum.jpg\",\"width\":885,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/24\\\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/","og_locale":"it_IT","og_type":"article","og_title":"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi - San Giorgio a Liri","og_description":"Consultazioni Referendarie di domenica 8 e luned\u00ec 9 giugno 2025 &#8211; Manifesto di Convocazione dei Comizi.&nbsp; Descrizione&nbsp; IL SINDACO Visto l\u2019articolo 75 della Costituzione; Vista la legge 25 maggio 1970, [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/","og_site_name":"San Giorgio a Liri","article_published_time":"2025-04-24T10:38:26+00:00","article_modified_time":"2025-04-29T11:58:33+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/referendum.jpg","height":400,"width":885,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi","datePublished":"2025-04-24T10:38:26+00:00","dateModified":"2025-04-29T11:58:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/"},"wordCount":309,"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/referendum.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/","name":"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/referendum.jpg","datePublished":"2025-04-24T10:38:26+00:00","dateModified":"2025-04-29T11:58:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#primaryimage","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/referendum.jpg","contentUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/referendum.jpg","width":885,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/24\/referendum-popolari-di-domenica-8-e-lunedi-9-giugno-2025-convocazione-dei-comizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Referendum Popolari di domenica 8 e luned\u00ec 9 giugno 2025: Convocazione dei Comizi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017079"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=16838"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16838\/revisions"}],"predecessor-version":[{"id":16848,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16838\/revisions\/16848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media\/16855"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=16838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=16838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=16838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}