{"id":16842,"date":"2025-04-28T12:05:01","date_gmt":"2025-04-28T10:05:01","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/"},"modified":"2025-04-29T13:52:51","modified_gmt":"2025-04-29T11:52:51","slug":"avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/","title":{"rendered":"Avviso agli elettori temporaneamente all&#8217;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi"},"content":{"rendered":"<p><em>Referendum 2025 &#8211; Scadenza presentazione domanda per elettori temporaneamente all&#8217;estero: 7 maggio 2025.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In vista dei <em>Referendum abrogativi dell\u20198 e 9 giugno 2025<\/em>, gli elettori temporaneamente all&#8217;estero, per motivi di lavoro, studio o cure mediche nonch\u00e9 i loro familiari conviventi, per un periodo minimo di almeno tre mesi nel quale ricade la data di svolgimento della consultazione, possono presentare al Comune di iscrizione nelle liste elettorali\u00a0l&#8217;opzione di voto per corrispondenza <strong><u>entro il 7 maggio 2025<\/u><\/strong>.<\/p>\n<p>Si precisa che la domanda si ritiene validamente prodotta ove si dichiari espressamente tale circostanza, ed anche se l\u2019interessato non si trovi all\u2019estero al momento della domanda stessa, purch\u00e9 il periodo previsto e dichiarato di temporanea residenza comprenda la data stabilita per la votazione.<\/p>\n<p>Per i familiari conviventi dei temporaneamente all\u2019estero aventi diritto al voto per corrispondenza, la legge non richiede il periodo previsto di tre mesi di temporanea residenza all\u2019estero.<\/p>\n<p>L\u2019opzione di voto, redatta sul modello allegato o su carta libera, deve essere necessariamente corredata da una\u00a0copia del documento d&#8217;identit\u00e0 valido dell&#8217;elettore\u00a0e dovr\u00e0 contenere l&#8217;indirizzo postale estero cui va inviato il plico elettorale e una dichiarazione attestante il possesso dei requisiti di cui al comma 1 dell&#8217;art. 4-bis, resa ai sensi degli artt. 46 e 47 del testo unico di cui al DPR 445\/2000.<\/p>\n<p>L&#8217;opzione medesima potr\u00e0 pervenire al Comune per posta ordinaria o per posta elettronica all\u2019indirizzo p.e.c.: <a href=\"mailto:posta@pec.comunedisangiorgioaliri.it\">posta@pec.comunedisangiorgioaliri.it<\/a>, o a mano anche da persona diversa dall\u2019interessato.<\/p>\n<p>&nbsp;<\/p>\n<p>Per informazioni: ufficio elettorale tel. 0776.914811<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16853\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/AVVISO-DOMANDA-3-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/AVVISO-DOMANDA-3-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO + DOMANDA<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16854\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/CIRC24-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/04\/CIRC24-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>CIRC24<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Referendum 2025 &#8211; Scadenza presentazione domanda per elettori temporaneamente all&#8217;estero: 7 maggio 2025.&nbsp; Descrizione&nbsp; In vista dei Referendum abrogativi dell\u20198 e 9 giugno 2025, gli elettori temporaneamente all&#8217;estero, per motivi [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16842","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso agli elettori temporaneamente all&#039;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso agli elettori temporaneamente all&#039;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Referendum 2025 &#8211; Scadenza presentazione domanda per elettori temporaneamente all&#8217;estero: 7 maggio 2025.&nbsp; Descrizione&nbsp; In vista dei Referendum abrogativi dell\u20198 e 9 giugno 2025, gli elettori temporaneamente all&#8217;estero, per motivi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T10:05:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T11:52:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Avviso agli elettori temporaneamente all&#8217;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi\",\"datePublished\":\"2025-04-28T10:05:01+00:00\",\"dateModified\":\"2025-04-29T11:52:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/\"},\"wordCount\":264,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/\",\"name\":\"Avviso agli elettori temporaneamente all'estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2025-04-28T10:05:01+00:00\",\"dateModified\":\"2025-04-29T11:52:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/04\\\/28\\\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso agli elettori temporaneamente all&#8217;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso agli elettori temporaneamente all'estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso agli elettori temporaneamente all'estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi - San Giorgio a Liri","og_description":"Referendum 2025 &#8211; Scadenza presentazione domanda per elettori temporaneamente all&#8217;estero: 7 maggio 2025.&nbsp; Descrizione&nbsp; In vista dei Referendum abrogativi dell\u20198 e 9 giugno 2025, gli elettori temporaneamente all&#8217;estero, per motivi [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/","og_site_name":"San Giorgio a Liri","article_published_time":"2025-04-28T10:05:01+00:00","article_modified_time":"2025-04-29T11:52:51+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Avviso agli elettori temporaneamente all&#8217;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi","datePublished":"2025-04-28T10:05:01+00:00","dateModified":"2025-04-29T11:52:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/"},"wordCount":264,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/","name":"Avviso agli elettori temporaneamente all'estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2025-04-28T10:05:01+00:00","dateModified":"2025-04-29T11:52:51+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/04\/28\/avviso-agli-elettori-temporaneamente-allestero-per-motivi-di-lavoro-studio-o-cure-mediche-e-loro-familiari-conviventi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Avviso agli elettori temporaneamente all&#8217;estero per motivi di lavoro, studio o cure mediche e loro familiari conviventi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017085"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=16842"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16842\/revisions"}],"predecessor-version":[{"id":16852,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16842\/revisions\/16852"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=16842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=16842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=16842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}