{"id":16977,"date":"2025-09-11T14:52:22","date_gmt":"2025-09-11T12:52:22","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?p=16977"},"modified":"2025-09-11T14:52:24","modified_gmt":"2025-09-11T12:52:24","slug":"avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/","title":{"rendered":"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028"},"content":{"rendered":"<p><em>Procedura aperta per l\u2019affidamento del servizio di mensa<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>L\u2019Ente rende noto che \u00e8 indetta procedura di gara per l\u2019affidamento del <strong data-start=\"414\" data-end=\"435\">servizio di mensa<\/strong> da attuarsi presso la scuola dell\u2019Infanzia e la scuola Primaria, per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028. Si invita a leggere attentamente la documentazione e gli allegati, che formano parte integrante del presente avviso.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16982\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/bando-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/bando-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>bando<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16983\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Disciplinare-di-gara-signed-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Disciplinare-di-gara-signed-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Disciplinare di gara -signed<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16984\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Avviso-indizione-gara-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Avviso-indizione-gara-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso indizione gara<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Procedura aperta per l\u2019affidamento del servizio di mensa&nbsp; Descrizione&nbsp; L\u2019Ente rende noto che \u00e8 indetta procedura di gara per l\u2019affidamento del servizio di mensa da attuarsi presso la scuola dell\u2019Infanzia [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16977","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028 - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028 - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Procedura aperta per l\u2019affidamento del servizio di mensa&nbsp; Descrizione&nbsp; L\u2019Ente rende noto che \u00e8 indetta procedura di gara per l\u2019affidamento del servizio di mensa da attuarsi presso la scuola dell\u2019Infanzia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T12:52:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T12:52:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\\\/2026, 2026\\\/2027, 2027\\\/2028\",\"datePublished\":\"2025-09-11T12:52:22+00:00\",\"dateModified\":\"2025-09-11T12:52:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/\"},\"wordCount\":71,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/\",\"name\":\"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\\\/2026, 2026\\\/2027, 2027\\\/2028 - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2025-09-11T12:52:22+00:00\",\"dateModified\":\"2025-09-11T12:52:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/11\\\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\\\/2026, 2026\\\/2027, 2027\\\/2028\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028 - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028 - San Giorgio a Liri","og_description":"Procedura aperta per l\u2019affidamento del servizio di mensa&nbsp; Descrizione&nbsp; L\u2019Ente rende noto che \u00e8 indetta procedura di gara per l\u2019affidamento del servizio di mensa da attuarsi presso la scuola dell\u2019Infanzia [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/","og_site_name":"San Giorgio a Liri","article_published_time":"2025-09-11T12:52:22+00:00","article_modified_time":"2025-09-11T12:52:24+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028","datePublished":"2025-09-11T12:52:22+00:00","dateModified":"2025-09-11T12:52:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/"},"wordCount":71,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/","name":"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028 - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2025-09-11T12:52:22+00:00","dateModified":"2025-09-11T12:52:24+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/11\/avviso-indizione-gara-servizio-di-refezione-scolastica-per-gli-anni-scolastici-2025-2026-2026-2027-2027-2028\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"AVVISO INDIZIONE GARA: Servizio di refezione scolastica per gli anni scolastici 2025\/2026, 2026\/2027, 2027\/2028"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017187"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=16977"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16977\/revisions"}],"predecessor-version":[{"id":16981,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16977\/revisions\/16981"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=16977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=16977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=16977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}