{"id":16985,"date":"2025-09-16T12:13:17","date_gmt":"2025-09-16T10:13:17","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/"},"modified":"2025-09-16T12:13:17","modified_gmt":"2025-09-16T10:13:17","slug":"avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/","title":{"rendered":"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato"},"content":{"rendered":"<p><em>AVVISO PUBBLICO  PER INTERVENTI DI ACQUISTO\/RECUPERO DEL PATRIMONIO IMMOBILIARE PUBBLICO E PRIVATO NON UTILIZZATO (SFITTO INVENDUTO) O SOTTOUTILIZZATO INVITO A MANIFESTARE INTERESSE &#8211; INDAGINE DI MERCATO  PER L\u2019ACQUISTO DI IMMOBILI IN SAN GIORGIO A LIRI <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato (sfitto invenduto) o sottoutilizzato invito a manifestare interesse &#8211; indagine di mercato per l\u2019acquisto di immobili in San Giorgio a Liri<\/p>\n<p>I soggetti interessati possono presentare all\u2019Amministrazione la manifestazione d\u2019interesse in relazione a un immobile che presenti le caratteristiche richieste nel presente invito e nel capitolato tecnico. La manifestazione d\u2019interesse pu\u00f2 essere redatta utilizzando il modello allegato al presente invito (All. 2). Essa deve essere sottoscritta digitalmente dalla persona fisica ovvero dal legale rappresentante della persona giuridica titolare del diritto di propriet\u00e0 sull\u2019immobile indicato nella manifestazione d\u2019interesse. Nel caso in cui il diritto di propriet\u00e0 sia frazionato tra pi\u00f9 soggetti, ognuno titolare del diritto per la propria quota, la manifestazione d\u2019interesse dovr\u00e0 essere sottoscritta digitalmente da ciascuno di essi. I Soggetti interessati devono indicare nella manifestazione d\u2019interesse uno o pi\u00f9 referenti &#8211; specificandone la qualifica, l\u2019indirizzo di posta elettronica e possibilmente un contatto telefonico \u2013 che potranno essere contattati dal Comune per tutti gli eventuali chiarimenti che dovessero ritenersi necessari.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16986\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Avviso_.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Avviso_.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso_<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16987\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/ALL.2_Manifestazione-di-interesse.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/ALL.2_Manifestazione-di-interesse.docx', '_system'); return false;\"><i class='icon attachment'><\/i>ALL.2_Manifestazione di interesse<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16988\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/ALL.1_Capitolato.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/ALL.1_Capitolato.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ALL.1_Capitolato<\/a><\/li>\n<li><a id=\"wpba_attachment_list_16989\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Atto-copia-uso-amministrativo-16.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/Atto-copia-uso-amministrativo-16.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Atto copia uso amministrativo (16)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AVVISO PUBBLICO PER INTERVENTI DI ACQUISTO\/RECUPERO DEL PATRIMONIO IMMOBILIARE PUBBLICO E PRIVATO NON UTILIZZATO (SFITTO INVENDUTO) O SOTTOUTILIZZATO INVITO A MANIFESTARE INTERESSE &#8211; INDAGINE DI MERCATO PER L\u2019ACQUISTO DI IMMOBILI [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-16985","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"AVVISO PUBBLICO PER INTERVENTI DI ACQUISTO\/RECUPERO DEL PATRIMONIO IMMOBILIARE PUBBLICO E PRIVATO NON UTILIZZATO (SFITTO INVENDUTO) O SOTTOUTILIZZATO INVITO A MANIFESTARE INTERESSE &#8211; INDAGINE DI MERCATO PER L\u2019ACQUISTO DI IMMOBILI [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T10:13:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Avviso pubblico per interventi di acquisto\\\/recupero del patrimonio immobiliare pubblico e privato non utilizzato\",\"datePublished\":\"2025-09-16T10:13:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/\"},\"wordCount\":237,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/\",\"name\":\"Avviso pubblico per interventi di acquisto\\\/recupero del patrimonio immobiliare pubblico e privato non utilizzato - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2025-09-16T10:13:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/16\\\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico per interventi di acquisto\\\/recupero del patrimonio immobiliare pubblico e privato non utilizzato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato - San Giorgio a Liri","og_description":"AVVISO PUBBLICO PER INTERVENTI DI ACQUISTO\/RECUPERO DEL PATRIMONIO IMMOBILIARE PUBBLICO E PRIVATO NON UTILIZZATO (SFITTO INVENDUTO) O SOTTOUTILIZZATO INVITO A MANIFESTARE INTERESSE &#8211; INDAGINE DI MERCATO PER L\u2019ACQUISTO DI IMMOBILI [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/","og_site_name":"San Giorgio a Liri","article_published_time":"2025-09-16T10:13:17+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato","datePublished":"2025-09-16T10:13:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/"},"wordCount":237,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/","name":"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2025-09-16T10:13:17+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/16\/avviso-pubblico-per-interventi-di-acquisto-recupero-del-patrimonio-immobiliare-pubblico-e-privato-non-utilizzato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico per interventi di acquisto\/recupero del patrimonio immobiliare pubblico e privato non utilizzato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017192"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=16985"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/16985\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=16985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=16985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=16985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}