{"id":17007,"date":"2025-09-23T10:54:25","date_gmt":"2025-09-23T08:54:25","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?p=17007"},"modified":"2025-09-23T10:54:25","modified_gmt":"2025-09-23T08:54:25","slug":"chiusura-locali-del-centro-polifunzionale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/","title":{"rendered":"Chiusura locali del centro Polifunzionale"},"content":{"rendered":"<p><em>IL SINDACO Premesso che sono in corso lavori finalizzati alla ristrutturazione del C. polif<br \/>\nORDINA<br \/>\nper i motivi espressi in premessa, dalla data odierna fino al termine dei lavori, ovvero il 31.12.2025, la chiusura dei locali specificati in premessa.<br \/>\n<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>IL SINDACO<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>Premesso<\/strong> che sono in corso lavori finalizzati alla ristrutturazione del Centro polifunzionale \u201cA. Livatino\u201d sito in Via Roma nel Comune di San Giorgio a Liri;<\/p>\n<p><strong>Considerato<\/strong> che tali lavori termineranno nel mese di Dicembre 2025;<\/p>\n<p><strong>Visto<\/strong> che non \u00e8 possibile garantire la sicurezza degli utenti che frequentano i locali situati al Piano Primo dell\u2019edificio, tra i quali la Biblioteca Comunale, e i locali situati al Piano Terra tra i quali il locale adibito ad auditorium, ad eccezione dei locali destinati al Centro diurno per anziani;<\/p>\n<p>Sentiti i tecnici competenti;<\/p>\n<p><strong>Ritenuto<\/strong> opportuno ed urgente disporre la chiusura dei suddetti locali al fine di eliminare ogni pericolo per la pubblica incolumit\u00e0;<\/p>\n<p><strong>Visto<\/strong> l\u2019art. 54 del Testo Unico 18 agosto 2000, n. 267 delle Leggi sull\u2019Ordinamento degli enti Locali;<\/p>\n<p><strong>ORDINA<\/strong><\/p>\n<p>per i motivi espressi in premessa, dalla data odierna fino al termine dei lavori, ovvero il 31.12.2025, la chiusura dei locali specificati in premessa.<\/p>\n<p>Il presente provvedimento viene reso noto mediante:<\/p>\n<ul>\n<li>l\u2019inoltro a tutte le Associazioni che utilizzano il centro polifunzionale,<\/li>\n<li>l\u2019affissione della presente Ordinanza presso il Centro Polifunzionale<\/li>\n<li>attraverso la pubblicazione della presente ordinanza sul sito istituzionale e i canali social ufficiali del Comune di San Giorgio a Liri,<\/li>\n<\/ul>\n<p>al fine di dare adeguata informazione a tutta l\u2019utenza.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17008\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/ORDINANZA-N-29_signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2025\/09\/ORDINANZA-N-29_signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORDINANZA N 29_signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>IL SINDACO Premesso che sono in corso lavori finalizzati alla ristrutturazione del C. polif ORDINA per i motivi espressi in premessa, dalla data odierna fino al termine dei lavori, ovvero [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-17007","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiusura locali del centro Polifunzionale - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiusura locali del centro Polifunzionale - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"IL SINDACO Premesso che sono in corso lavori finalizzati alla ristrutturazione del C. polif ORDINA per i motivi espressi in premessa, dalla data odierna fino al termine dei lavori, ovvero [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-23T08:54:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Chiusura locali del centro Polifunzionale\",\"datePublished\":\"2025-09-23T08:54:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/\"},\"wordCount\":253,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/\",\"name\":\"Chiusura locali del centro Polifunzionale - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2025-09-23T08:54:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2025\\\/09\\\/23\\\/chiusura-locali-del-centro-polifunzionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiusura locali del centro Polifunzionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiusura locali del centro Polifunzionale - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/","og_locale":"it_IT","og_type":"article","og_title":"Chiusura locali del centro Polifunzionale - San Giorgio a Liri","og_description":"IL SINDACO Premesso che sono in corso lavori finalizzati alla ristrutturazione del C. polif ORDINA per i motivi espressi in premessa, dalla data odierna fino al termine dei lavori, ovvero [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/","og_site_name":"San Giorgio a Liri","article_published_time":"2025-09-23T08:54:25+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Chiusura locali del centro Polifunzionale","datePublished":"2025-09-23T08:54:25+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/"},"wordCount":253,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/","name":"Chiusura locali del centro Polifunzionale - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2025-09-23T08:54:25+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2025\/09\/23\/chiusura-locali-del-centro-polifunzionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Chiusura locali del centro Polifunzionale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017204"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=17007"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17007\/revisions"}],"predecessor-version":[{"id":17009,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17007\/revisions\/17009"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=17007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=17007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=17007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}