{"id":17153,"date":"2026-01-28T13:58:17","date_gmt":"2026-01-28T12:58:17","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?p=17153"},"modified":"2026-01-28T13:58:19","modified_gmt":"2026-01-28T12:58:19","slug":"borse-di-studio-a-s-2024-2025-avviso-di-pagamento","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/","title":{"rendered":"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento"},"content":{"rendered":"<p><em>Comunicazione rivolta ai beneficiari delle borse di studio per l\u2019anno scolastico 2024\/2025<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si informa la cittadinanza che le Borse di Studio relative all\u2019anno scolastico 2024\/2025 risultano attualmente in fase di pagamento.<\/p>\n<p>L\u2019importo della singola borsa di studio \u00e8 stato determinato in euro 192,50.<\/p>\n<p>Tutti i soggetti beneficiari possono pertanto recarsi presso l&#8217;Ufficio Postale .<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunicazione rivolta ai beneficiari delle borse di studio per l\u2019anno scolastico 2024\/2025&nbsp; Descrizione&nbsp; Si informa la cittadinanza che le Borse di Studio relative all\u2019anno scolastico 2024\/2025 risultano attualmente in fase [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-17153","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Comunicazione rivolta ai beneficiari delle borse di studio per l\u2019anno scolastico 2024\/2025&nbsp; Descrizione&nbsp; Si informa la cittadinanza che le Borse di Studio relative all\u2019anno scolastico 2024\/2025 risultano attualmente in fase [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-28T12:58:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T12:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Borse di Studio A.S. 2024\\\/2025 \u2013 Avviso di pagamento\",\"datePublished\":\"2026-01-28T12:58:17+00:00\",\"dateModified\":\"2026-01-28T12:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/\"},\"wordCount\":64,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/\",\"name\":\"Borse di Studio A.S. 2024\\\/2025 \u2013 Avviso di pagamento - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2026-01-28T12:58:17+00:00\",\"dateModified\":\"2026-01-28T12:58:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/01\\\/28\\\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Borse di Studio A.S. 2024\\\/2025 \u2013 Avviso di pagamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/","og_locale":"it_IT","og_type":"article","og_title":"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento - San Giorgio a Liri","og_description":"Comunicazione rivolta ai beneficiari delle borse di studio per l\u2019anno scolastico 2024\/2025&nbsp; Descrizione&nbsp; Si informa la cittadinanza che le Borse di Studio relative all\u2019anno scolastico 2024\/2025 risultano attualmente in fase [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/","og_site_name":"San Giorgio a Liri","article_published_time":"2026-01-28T12:58:17+00:00","article_modified_time":"2026-01-28T12:58:19+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento","datePublished":"2026-01-28T12:58:17+00:00","dateModified":"2026-01-28T12:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/"},"wordCount":64,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/","name":"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2026-01-28T12:58:17+00:00","dateModified":"2026-01-28T12:58:19+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/01\/28\/borse-di-studio-a-s-2024-2025-avviso-di-pagamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Borse di Studio A.S. 2024\/2025 \u2013 Avviso di pagamento"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017304"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=17153"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17153\/revisions"}],"predecessor-version":[{"id":17154,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17153\/revisions\/17154"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=17153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=17153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=17153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}