{"id":17187,"date":"2026-02-10T09:21:56","date_gmt":"2026-02-10T08:21:56","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/"},"modified":"2026-02-10T09:21:56","modified_gmt":"2026-02-10T08:21:56","slug":"voto-domiciliare-per-elettori-affetti-da-infermita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/","title":{"rendered":"Voto domiciliare per elettori affetti da infermit\u00e0"},"content":{"rendered":"<p><em>Gli elettori affetti da gravissime infermit\u00e0 o che si trovino in condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali, tali da impedirne l&#8217;allontanamento dall&#8217;abitazione, possono richiedere l&#8217;ammissione al voto<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Gli elettori affetti da gravissime infermit\u00e0 o che si trovino in condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali, tali da impedirne l&#8217;allontanamento dall&#8217;abitazione, possono richiedere l&#8217;ammissione al voto domiciliare.<\/p>\n<p>L&#8217;elettore interessato deve far pervenire al Sindaco del proprio Comune di iscrizione elettorale un&#8217;espressa dichiarazione attestante la propria volont\u00e0 di esprimere il voto presso l&#8217;abitazione in cui dimora<b>\u00a0fra marted\u00ec 10 febbraio 2026 e luned\u00ec 2 marzo 2026<\/b>. Tale ultimo termine, in un&#8217;ottica di garanzia del diritto di voto costituzionalmente tutelato, deve considerarsi di carattere\u00a0<b>ordinatorio<\/b>.<br \/>\nLa domanda di ammissione al voto domiciliare deve indicare l&#8217;indirizzo dell&#8217;abitazione in cui l&#8217;elettore dimora e, possibilmente, un recapito telefonico e deve essere corredata di:<br \/>\n&#8211; copia fotostatica di un documento d&#8217;identit\u00e0 in corso di validit\u00e0;<br \/>\n&#8211; copia fotostatica della tessera elettorale;<br \/>\n&#8211; certificato medico della competente Autorit\u00e0 Sanitaria Locale attestante l&#8217;esistenza delle condizioni di gravissima infermit\u00e0, di cui al comma 1, dell&#8217;art. 1 della Legge n. 46\/2009, con prognosi di 60 giorni decorrenti dalla data di rilascio, oppure un certificato medico della competente Autorit\u00e0 Sanitaria Locale attestante la condizione di dipendenza continuativa e vitale da apparecchiature elettromedicali.<\/p>\n<p>Il voto sar\u00e0 raccolto dai componenti del seggio, nei giorni e durante l&#8217;orario di votazione, presso l&#8217;abitazione dichiarata dall&#8217;elettore.<\/p>\n<p>Si ricorda che per poter esercitare il diritto di voto \u00e8 necessario esibire la propria tessera elettorale e un documento di riconoscimento valido.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17188\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2026\/02\/Manifesto-voto-a-domicilio.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2026\/02\/Manifesto-voto-a-domicilio.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Manifesto voto a domicilio<\/a><\/li>\n<li><a id=\"wpba_attachment_list_17189\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2026\/02\/Richiesta-voto-a-domicilio.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2026\/02\/Richiesta-voto-a-domicilio.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Richiesta voto a domicilio<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gli elettori affetti da gravissime infermit\u00e0 o che si trovino in condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali, tali da impedirne l&#8217;allontanamento dall&#8217;abitazione, possono richiedere l&#8217;ammissione al voto&nbsp; [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-17187","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Voto domiciliare per elettori affetti da infermit\u00e0 - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voto domiciliare per elettori affetti da infermit\u00e0 - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Gli elettori affetti da gravissime infermit\u00e0 o che si trovino in condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali, tali da impedirne l&#8217;allontanamento dall&#8217;abitazione, possono richiedere l&#8217;ammissione al voto&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T08:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"Voto domiciliare per elettori affetti da infermit\u00e0\",\"datePublished\":\"2026-02-10T08:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/\"},\"wordCount\":258,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/\",\"name\":\"Voto domiciliare per elettori affetti da infermit\u00e0 - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2026-02-10T08:21:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2026\\\/02\\\/10\\\/voto-domiciliare-per-elettori-affetti-da-infermita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voto domiciliare per elettori affetti da infermit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Voto domiciliare per elettori affetti da infermit\u00e0 - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/","og_locale":"it_IT","og_type":"article","og_title":"Voto domiciliare per elettori affetti da infermit\u00e0 - San Giorgio a Liri","og_description":"Gli elettori affetti da gravissime infermit\u00e0 o che si trovino in condizioni di dipendenza continuativa e vitale da apparecchiature elettromedicali, tali da impedirne l&#8217;allontanamento dall&#8217;abitazione, possono richiedere l&#8217;ammissione al voto&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/","og_site_name":"San Giorgio a Liri","article_published_time":"2026-02-10T08:21:56+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"Voto domiciliare per elettori affetti da infermit\u00e0","datePublished":"2026-02-10T08:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/"},"wordCount":258,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/","name":"Voto domiciliare per elettori affetti da infermit\u00e0 - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2026-02-10T08:21:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2026\/02\/10\/voto-domiciliare-per-elettori-affetti-da-infermita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Voto domiciliare per elettori affetti da infermit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000017327"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=17187"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/17187\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=17187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=17187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=17187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}