{"id":377,"date":"2019-06-05T15:17:43","date_gmt":"2019-06-05T13:17:43","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?p=377"},"modified":"2019-06-05T15:17:43","modified_gmt":"2019-06-05T13:17:43","slug":"elezione-diretta-del-sindaco-e-dei-consiglio-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/","title":{"rendered":"Elezione diretta del Sindaco e dei Consiglio Comunale"},"content":{"rendered":"<p>A seguito dell\u2018elezione diretta del Sindaco e del Consiglio Comunale del 26 maggio 2019 \u00e8 stato proclamato eletto<strong> Sindaco<\/strong> il candidato<\/p>\n<p><strong>Francesco Lavalle<\/strong><\/p>\n<p>e che sono stati proclamati alla carica di Consigliere comunale i seguenti candidati:<\/p>\n<p>per la LISTA N. 3, \u201c<strong>Amo San Giorgio<\/strong>&#8221; collegata con il candidato eletto Sindaco:<\/p>\n<ol>\n<li>Modesto Mario Della Rosa<\/li>\n<li>Rocco Simonelli<\/li>\n<li>Achille Antonio Longo<\/li>\n<li>Antonello D\u2019Abrosca<\/li>\n<li>Gioia Mattei<\/li>\n<li>Luigi Di Cicco<\/li>\n<li>Fabio Lucciola<\/li>\n<li>Francesco Terrezza<\/li>\n<\/ol>\n<p>per la LISTA N. 1 \u201c<strong>Avanti San Giorgio<\/strong>&#8221;<\/p>\n<ol>\n<li>Massimiliano Tenezza, candidate alla carica di Sindaco;<\/li>\n<li>William Alabiso<\/li>\n<li>Enrico De Simone<\/li>\n<\/ol>\n<p>per la LISTA N. 2 &#8220;<strong>Rinascita per San Giorgio<\/strong>&#8221;<\/p>\n<ol>\n<li>Davide Antonio Della Rosa, candidato alla carica di Sindaco;<\/li>\n<\/ol>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_378\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Elezione-diretta-del-Sindaco-e-del-Consiglio-Comunale.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Elezione-diretta-del-Sindaco-e-del-Consiglio-Comunale.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Elezione diretta del Sindaco e del Consiglio Comunale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A seguito dell\u2018elezione diretta del Sindaco e del Consiglio Comunale del 26 maggio 2019 \u00e8 stato proclamato eletto Sindaco il candidato Francesco Lavalle e che sono stati proclamati alla carica [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-377","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezione diretta del Sindaco e dei Consiglio Comunale - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezione diretta del Sindaco e dei Consiglio Comunale - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"A seguito dell\u2018elezione diretta del Sindaco e del Consiglio Comunale del 26 maggio 2019 \u00e8 stato proclamato eletto Sindaco il candidato Francesco Lavalle e che sono stati proclamati alla carica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-05T13:17:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Elezione diretta del Sindaco e dei Consiglio Comunale\",\"datePublished\":\"2019-06-05T13:17:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/\"},\"wordCount\":112,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/\",\"name\":\"Elezione diretta del Sindaco e dei Consiglio Comunale - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"datePublished\":\"2019-06-05T13:17:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/05\\\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezione diretta del Sindaco e dei Consiglio Comunale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezione diretta del Sindaco e dei Consiglio Comunale - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Elezione diretta del Sindaco e dei Consiglio Comunale - San Giorgio a Liri","og_description":"A seguito dell\u2018elezione diretta del Sindaco e del Consiglio Comunale del 26 maggio 2019 \u00e8 stato proclamato eletto Sindaco il candidato Francesco Lavalle e che sono stati proclamati alla carica [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/","og_site_name":"San Giorgio a Liri","article_published_time":"2019-06-05T13:17:43+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"gestoreyic","twitter_misc":{"Scritto da":"gestoreyic","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Elezione diretta del Sindaco e dei Consiglio Comunale","datePublished":"2019-06-05T13:17:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/"},"wordCount":112,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/","name":"Elezione diretta del Sindaco e dei Consiglio Comunale - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"datePublished":"2019-06-05T13:17:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/05\/elezione-diretta-del-sindaco-e-dei-consiglio-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Elezione diretta del Sindaco e dei Consiglio Comunale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=377"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/377\/revisions"}],"predecessor-version":[{"id":379,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/377\/revisions\/379"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}