{"id":418,"date":"2019-06-28T12:38:51","date_gmt":"2019-06-28T10:38:51","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?p=418"},"modified":"2019-07-01T13:12:29","modified_gmt":"2019-07-01T11:12:29","slug":"sperimentazione-dellisola-pedonale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/","title":{"rendered":"Sperimentazione dell&#8217;isola pedonale"},"content":{"rendered":"<p>Vogliamo che il nostro paese diventi sempre pi\u00f9 accogliente e bello da vivere per i sangiorgesi e sempre pi\u00f9 ospitale per le persone che arrivano a farci visita dal territorio circostante.<\/p>\n<p>Per questo abbiamo deciso di dare il via alla sperimentazione dell&#8217;isola pedonale. Si comincia domenica 30 giugno: dalle ore 20 alle ore 24 sar\u00e0 vietato l&#8217;accesso, il transito e la sosta a tutti gli automezzi, autocarri, motocicli e ciclomotori, eccetto quelli di propriet\u00e0 dei residenti nelle seguenti strade e piazze:<\/p>\n<ul>\n<li>Piazza Dante<\/li>\n<li>Corso Achille Spatuzzi, nel tratto compreso tra l&#8217;incrocio di Via Vittorio Emanuele e quello con Via Marconi.<\/li>\n<\/ul>\n<p><em>Ringrazio i miei concittadini per la collaborazione e auguro una buona passeggiata a tutti<\/em><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_420\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Isola pedonale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vogliamo che il nostro paese diventi sempre pi\u00f9 accogliente e bello da vivere per i sangiorgesi e sempre pi\u00f9 ospitale per le persone che arrivano a farci visita dal territorio [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":421,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sperimentazione dell&#039;isola pedonale - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sperimentazione dell&#039;isola pedonale - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Vogliamo che il nostro paese diventi sempre pi\u00f9 accogliente e bello da vivere per i sangiorgesi e sempre pi\u00f9 ospitale per le persone che arrivano a farci visita dal territorio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-28T10:38:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-01T11:12:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2101\" \/>\n\t<meta property=\"og:image:height\" content=\"1400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Sperimentazione dell&#8217;isola pedonale\",\"datePublished\":\"2019-06-28T10:38:51+00:00\",\"dateModified\":\"2019-07-01T11:12:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/\"},\"wordCount\":114,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Isola-pedonale.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/\",\"name\":\"Sperimentazione dell'isola pedonale - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Isola-pedonale.jpg\",\"datePublished\":\"2019-06-28T10:38:51+00:00\",\"dateModified\":\"2019-07-01T11:12:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Isola-pedonale.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/06\\\/Isola-pedonale.jpg\",\"width\":2101,\"height\":1400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2019\\\/06\\\/28\\\/sperimentazione-dellisola-pedonale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sperimentazione dell&#8217;isola pedonale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sperimentazione dell'isola pedonale - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/","og_locale":"it_IT","og_type":"article","og_title":"Sperimentazione dell'isola pedonale - San Giorgio a Liri","og_description":"Vogliamo che il nostro paese diventi sempre pi\u00f9 accogliente e bello da vivere per i sangiorgesi e sempre pi\u00f9 ospitale per le persone che arrivano a farci visita dal territorio [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/","og_site_name":"San Giorgio a Liri","article_published_time":"2019-06-28T10:38:51+00:00","article_modified_time":"2019-07-01T11:12:29+00:00","og_image":[{"width":2101,"height":1400,"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.jpg","type":"image\/jpeg"}],"author":"gestoreyic","twitter_misc":{"Scritto da":"gestoreyic","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Sperimentazione dell&#8217;isola pedonale","datePublished":"2019-06-28T10:38:51+00:00","dateModified":"2019-07-01T11:12:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/"},"wordCount":114,"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/","name":"Sperimentazione dell'isola pedonale - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.jpg","datePublished":"2019-06-28T10:38:51+00:00","dateModified":"2019-07-01T11:12:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#primaryimage","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.jpg","contentUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2019\/06\/Isola-pedonale.jpg","width":2101,"height":1400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2019\/06\/28\/sperimentazione-dellisola-pedonale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"Sperimentazione dell&#8217;isola pedonale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=418"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/418\/revisions"}],"predecessor-version":[{"id":419,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/418\/revisions\/419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media\/421"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}