{"id":744,"date":"2020-03-12T15:23:38","date_gmt":"2020-03-12T14:23:38","guid":{"rendered":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?p=744"},"modified":"2020-03-12T15:23:38","modified_gmt":"2020-03-12T14:23:38","slug":"sangiorgiofalasuaparte-3","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/","title":{"rendered":"#sangiorgiofalasuaparte"},"content":{"rendered":"<p>Insieme agli operatori dei Servizi Sociali del Comune di San Giorgio a Liri abbiamo pensato di contattare direttamente i nostri concittadini pi\u00f9 anziani e quelli che, per diverse ragioni, possono aver bisogno di un aiuto in pi\u00f9 in questi giorni di emergenza Coronavirus.<\/p>\n<p>Continueremo a farlo nei prossimi giorni per accertarci che abbiano tutto ci\u00f2 che occorre per stare bene o anche solo per rivolgere loro un saluto. So che molti di voi stanno facendo lo stesso, per questo vi chiedo di farlo tutti insieme.<\/p>\n<p>In questi giorni difficili, chiamiamo i nostri amici e parenti e accertiamoci che stiano bene. Se hanno necessit\u00e0 di ricevere spesa, farmaci o beni di prima necessit\u00e0, \u00e8 possibile contattare i numeri 0776914813 o 3270165657.<\/p>\n<p>Se, invece, hanno bisogno di assistenza medica non esitiamo a contattare il medico di base. In presenza di febbre, tosse o dolori muscolari, il numero da contattare \u00e8 800118800.<\/p>\n<p>Quando c&#8217;\u00e8 pi\u00f9 bisogno San Giorgio fa la sua parte!<br \/>\n#sangiorgiofalasuaparte<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-745\" src=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515-300x300.jpg 300w, https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515-150x150.jpg 150w, https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515-768x768.jpg 768w, https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515-680x680.jpg 680w, https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Insieme agli operatori dei Servizi Sociali del Comune di San Giorgio a Liri abbiamo pensato di contattare direttamente i nostri concittadini pi\u00f9 anziani e quelli che, per diverse ragioni, possono [&hellip;]<\/p>\n","protected":false},"author":318,"featured_media":745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#sangiorgiofalasuaparte - San Giorgio a Liri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#sangiorgiofalasuaparte - San Giorgio a Liri\" \/>\n<meta property=\"og:description\" content=\"Insieme agli operatori dei Servizi Sociali del Comune di San Giorgio a Liri abbiamo pensato di contattare direttamente i nostri concittadini pi\u00f9 anziani e quelli che, per diverse ragioni, possono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/\" \/>\n<meta property=\"og:site_name\" content=\"San Giorgio a Liri\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-12T14:23:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Lavalle\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Lavalle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/\"},\"author\":{\"name\":\"Francesco Lavalle\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"headline\":\"#sangiorgiofalasuaparte\",\"datePublished\":\"2020-03-12T14:23:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/\"},\"wordCount\":157,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/IMG_20200312_151409_515.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/\",\"name\":\"#sangiorgiofalasuaparte - San Giorgio a Liri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/IMG_20200312_151409_515.jpg\",\"datePublished\":\"2020-03-12T14:23:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/IMG_20200312_151409_515.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/03\\\/IMG_20200312_151409_515.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/2020\\\/03\\\/12\\\/sangiorgiofalasuaparte-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#sangiorgiofalasuaparte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/\",\"name\":\"San Giorgio a Liri\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/#\\\/schema\\\/person\\\/343da3d6b8de21f68606d71ad407b922\",\"name\":\"Francesco Lavalle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g\",\"caption\":\"Francesco Lavalle\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/san-giorgio-a-liri\\\/author\\\/flavalle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#sangiorgiofalasuaparte - San Giorgio a Liri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/","og_locale":"it_IT","og_type":"article","og_title":"#sangiorgiofalasuaparte - San Giorgio a Liri","og_description":"Insieme agli operatori dei Servizi Sociali del Comune di San Giorgio a Liri abbiamo pensato di contattare direttamente i nostri concittadini pi\u00f9 anziani e quelli che, per diverse ragioni, possono [&hellip;]","og_url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/","og_site_name":"San Giorgio a Liri","article_published_time":"2020-03-12T14:23:38+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg","type":"image\/jpeg"}],"author":"Francesco Lavalle","twitter_misc":{"Scritto da":"Francesco Lavalle","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/"},"author":{"name":"Francesco Lavalle","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"headline":"#sangiorgiofalasuaparte","datePublished":"2020-03-12T14:23:38+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/"},"wordCount":157,"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/","name":"#sangiorgiofalasuaparte - San Giorgio a Liri","isPartOf":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg","datePublished":"2020-03-12T14:23:38+00:00","author":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#primaryimage","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg","contentUrl":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-content\/uploads\/sites\/4\/2020\/03\/IMG_20200312_151409_515.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/2020\/03\/12\/sangiorgiofalasuaparte-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/"},{"@type":"ListItem","position":2,"name":"#sangiorgiofalasuaparte"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#website","url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/","name":"San Giorgio a Liri","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/#\/schema\/person\/343da3d6b8de21f68606d71ad407b922","name":"Francesco Lavalle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf2b3e13b8f4008f99095f17fa699aa3be6a47ce27b8562d7f353b29f3722661?s=96&d=mm&r=g","caption":"Francesco Lavalle"},"url":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/author\/flavalle\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/comments?post=744"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/744\/revisions"}],"predecessor-version":[{"id":746,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/posts\/744\/revisions\/746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media\/745"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/media?parent=744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/categories?post=744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/san-giorgio-a-liri\/wp-json\/wp\/v2\/tags?post=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}