{"id":53,"date":"2019-12-10T10:33:29","date_gmt":"2019-12-10T09:33:29","guid":{"rendered":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?post_type=info&#038;p=53"},"modified":"2019-12-10T11:13:35","modified_gmt":"2019-12-10T10:13:35","slug":"luoghi-di-interesse","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/","title":{"rendered":"Luoghi di interesse"},"content":{"rendered":"<hr \/>\n<h3>Mercati<\/h3>\n<p><strong>Mercato agricolo<\/strong>: sabato (Viale Trento e Trieste)<br \/>\n<strong>Mercato settimanale<\/strong>: mercoled\u00ec (Viale Trento e Trieste)<br \/>\n<strong>Mercatino dell\u2019antiquariato<\/strong>: ogni ultima domenica del mese (centro storico)<\/p>\n<p>Eventuali informazioni possono essere acquisite presso:<\/p>\n<p>Ufficio di Polizia Municipale sito in Via C. Battisti \u2013 San Daniele del Friuli<\/p>\n<p><i class=\"fa fa-phone\"><\/i> <a href=\"tel:0432943080\">0432 943080<\/a><br \/>\n<i class=\"fa fa-print\"><\/i> <a href=\"tel:0432954289\">0432 954289<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercati Mercato agricolo: sabato (Viale Trento e Trieste) Mercato settimanale: mercoled\u00ec (Viale Trento e Trieste) Mercatino dell\u2019antiquariato: ogni ultima domenica del mese (centro storico) Eventuali informazioni possono essere acquisite presso: [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":5,"template":"","meta":[],"plugin_info":[],"class_list":["post-53","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luoghi di interesse - San Daniele del Friuli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luoghi di interesse - San Daniele del Friuli\" \/>\n<meta property=\"og:description\" content=\"Mercati Mercato agricolo: sabato (Viale Trento e Trieste) Mercato settimanale: mercoled\u00ec (Viale Trento e Trieste) Mercatino dell\u2019antiquariato: ogni ultima domenica del mese (centro storico) Eventuali informazioni possono essere acquisite presso: [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/\" \/>\n<meta property=\"og:site_name\" content=\"San Daniele del Friuli\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-10T10:13:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/sandanieledelfriuli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/info\\\/luoghi-di-interesse\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/info\\\/luoghi-di-interesse\\\/\",\"name\":\"Luoghi di interesse - San Daniele del Friuli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\"},\"datePublished\":\"2019-12-10T09:33:29+00:00\",\"dateModified\":\"2019-12-10T10:13:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/info\\\/luoghi-di-interesse\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/info\\\/luoghi-di-interesse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/info\\\/luoghi-di-interesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luoghi di interesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"name\":\"San Daniele del Friuli\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/wp-content\\\/uploads\\\/sites\\\/170\\\/2019\\\/12\\\/veduta-aerea.jpg\",\"width\":250,\"height\":249,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sandanieledelfriuli\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luoghi di interesse - San Daniele del Friuli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/","og_locale":"it_IT","og_type":"article","og_title":"Luoghi di interesse - San Daniele del Friuli","og_description":"Mercati Mercato agricolo: sabato (Viale Trento e Trieste) Mercato settimanale: mercoled\u00ec (Viale Trento e Trieste) Mercatino dell\u2019antiquariato: ogni ultima domenica del mese (centro storico) Eventuali informazioni possono essere acquisite presso: [&hellip;]","og_url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/","og_site_name":"San Daniele del Friuli","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2019-12-10T10:13:35+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/sandanieledelfriuli.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/","name":"Luoghi di interesse - San Daniele del Friuli","isPartOf":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website"},"datePublished":"2019-12-10T09:33:29+00:00","dateModified":"2019-12-10T10:13:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/info\/luoghi-di-interesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sandanieledelfriuli\/"},{"@type":"ListItem","position":2,"name":"Luoghi di interesse"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#website","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","name":"San Daniele del Friuli","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sandanieledelfriuli\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","contentUrl":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-content\/uploads\/sites\/170\/2019\/12\/veduta-aerea.jpg","width":250,"height":249,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sandanieledelfriuli\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/info\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/types\/info"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/media?parent=53"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/sandanieledelfriuli\/wp-json\/wp\/v2\/plugin_info?post=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}